{"id":104681,"date":"2023-02-22T11:27:00","date_gmt":"2023-02-22T11:27:00","guid":{"rendered":"https:\/\/fr.cryptonews.com\/?p=105648"},"modified":"2023-06-26T11:06:44","modified_gmt":"2023-06-26T11:06:44","slug":"solana-spaces-fermera-ses-magasins-de-new-york-et-miami-7-mois-apres-leur-ouverture","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/fr\/exclusives\/solana-spaces-fermera-ses-magasins-de-new-york-et-miami-7-mois-apres-leur-ouverture\/","title":{"rendered":"Solana Spaces fermera ses magasins de New York et Miami 7 mois apr\u00e8s leur ouverture"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/105648\/258442\/solana-spaces-twitter-1-media-library-original-679-478.jpeg\" srcset=\"https:\/\/cimg.co\/news\/105648\/258442\/responsive-images\/solana-spaces-twitter-1-media-library-original-679-478___media_library_original_679_478.jpeg 679w, https:\/\/cimg.co\/news\/105648\/258442\/responsive-images\/solana-spaces-twitter-1-media-library-original-679-478___media_library_original_600_422.jpeg 600w, https:\/\/cimg.co\/news\/105648\/258442\/responsive-images\/solana-spaces-twitter-1-media-library-original-679-478___media_library_original_300_211.jpeg 300w\" width=\"679\" class=\"content-img\" alt=\"\"><figcaption>Source : Solana Spaces \/ Twitter<\/figcaption><\/figure><p class=\"wp-block-paragraph\"><a href=\"https:\/\/cryptonews.com\/fr\/news\/solana-team-set-to-open-doors-of-a-physical-store-in-new-york-to-promote-solana-and-web3-fr\/\"><strong>Solana Spaces<\/strong><\/a><strong> <\/strong>fermera ses deux magasins th&eacute;matiques Solana, orient&eacute;s vers la communaut&eacute;, &agrave; New York et Miami &agrave; la fin de ce mois. Ces magasins physiques n&rsquo;ont pas permis d&rsquo;accueillir autant d&rsquo;utilisateurs que pr&eacute;vu initialement.<\/p><p><strong>Solana Spaces a annonc&eacute; la nouvelle sur Twitter<\/strong> le 21 f&eacute;vrier. Le fondateur Vibhu Norby a expliqu&eacute; dans une note les raisons de la fermeture des magasins.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/solanaspaces\/status\/1628100995103494145?s=20\"><\/oembed><\/figure><p>La d&eacute;cision de fermer les magasins, situ&eacute;s dans le quartier d&rsquo;Hudson Yards &agrave; Manhattan et dans la localit&eacute; de Wynwood &agrave; Miami, a &eacute;t&eacute; prise \u00ab\u00a0il y a quelques semaines\u00a0\u00bb. Norbya pr&eacute;cis&eacute; qu&rsquo;<strong>ils fermeront leurs portes &agrave; la fin du mois de f&eacute;vrier<\/strong>.<\/p><p>Cette initiative ambitieuse a &eacute;t&eacute; relativement &eacute;ph&eacute;m&egrave;re, <strong>les deux magasins n&rsquo;ayant ouvert officiellement que fin juillet et ao&ucirc;t 2022<\/strong>, respectivement &agrave; New York et &agrave; Miami.<\/p><p>Norby a soulign&eacute; que cette \u00ab\u00a0exp&eacute;rience\u00a0\u00bb faisait partie d&rsquo;un plan plus large visant &agrave; <strong>int&eacute;grer davantage de personnes dans l&rsquo;&eacute;cosyst&egrave;me <\/strong><a href=\"https:\/\/cryptonews.com\/fr\/news\/prevision-prix-solana-volume-dechange-de-800-millions-dollars-fr\/\"><strong>Solana<\/strong><\/a> et dans le Web3 :<\/p><blockquote><p>\u00ab\u00a0Notre mission depuis le premier jour &eacute;tait d&rsquo;exp&eacute;rimenter de nouveaux mod&egrave;les innovants permettant d&rsquo;attirer le public vers le Web3, et de servir la communaut&eacute; au nom de la Fondation Solana.\u00a0\u00bb<\/p><\/blockquote><p>Il a ensuite ajout&eacute; :&nbsp;<\/p><blockquote><p>\u00ab\u00a0Comme je le disais souvent aux gens, aussi g&eacute;niaux que soient les magasins, si nous trouvions un moyen plus efficace pour attirer les gens &agrave; Solana, nous y consacrerions nos efforts\u00a0\u00bb.<\/p><\/blockquote><p>Mais aujourd&rsquo;hui, il a r&eacute;alis&eacute; depuis que les efforts de l&rsquo;entreprise pourraient donner de meilleurs r&eacute;sultats dans <strong>le domaine num&eacute;rique <\/strong>avec DRiP.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/solanaspaces\/status\/1626346193558319104?s=20\"><\/oembed><\/figure><p>Les magasins sur le th&egrave;me de Solana offraient aux clients la possibilit&eacute; de participer &agrave; toutes sortes d&rsquo;activit&eacute;s, notamment <strong>des tutoriels d&rsquo;initiation au portefeuille<\/strong>, l&rsquo;obtention de r&eacute;compenses, l&rsquo;achat de marchandises et la participation &agrave; des &eacute;v&eacute;nements.<\/p><p>Ces magasins de Solana faisaient ainsi partie d&rsquo;une liste croissante de projets IRL, comme <strong>Bored &amp; Hungry, un restaurant de fast-food sur le th&egrave;me du Yacht Club<\/strong> de Bored Ape, bas&eacute; &agrave; Los Angeles.<\/p><h2>Les raisons qui justifient cette fermeture des magasins de Solana Spaces<\/h2><span class=\"replacer\"><\/span><p>Lorsque Solana Spaces a ouvert <strong>son premier magasin &agrave; New York <\/strong>&agrave; la fin du mois de juillet, Norby esp&eacute;rait que le magasin permettrait &agrave; Solana d&rsquo;attirer plus de 100 000 personnes par mois.<\/p><p>Cependant, Norby a constat&eacute; dans sa lettre qu&rsquo;au cours des sept mois d&rsquo;ouverture, <strong>seules 75 000 personnes se sont rendues dans le magasin<\/strong>.<\/p><p>La fondation Solana, le fournisseur de <a href=\"https:\/\/cryptonews.com\/fr\/news\/solana-based-phantom-wallet-unveils-burn-nfts-to-protect-customers-from-scams-fr\/\"><strong>portefeuille Phantom<\/strong><\/a> et la plateforme de crypto-monnaie Orca ont parrain&eacute; la startup Solana Spaces. M&ecirc;me si elle n&rsquo;a pas fonctionn&eacute;, elle semble n&eacute;anmoins avoir conquis de nombreux fans.<\/p><p>Plusieurs acteurs de l&rsquo;industrie natifs de Solana, comme <strong>les projets de jeux vid&eacute;o Star Atlas et Aurory<\/strong>, ont remerci&eacute; Solana Spaces pour sa contribution &agrave; l&rsquo;&eacute;cosyst&egrave;me.<\/p><p>Cette fermeture de Solana Spaces intervient alors que l&rsquo;hiver prolong&eacute; de la crypto-monnaie a pouss&eacute; de nombreuses entreprises leaders du secteur &agrave; <strong>licencier du personnel et &agrave; fermer des bureaux dans le monde entier<\/strong>.<\/p><h2>La start-up veut d&eacute;sormais se concentrer sur le projet DRiP<\/h2><span class=\"replacer\"><\/span><p>Norby, qui a fond&eacute; Solana Spaces au d&eacute;but de l&rsquo;ann&eacute;e 2022, a expliqu&eacute; que l&rsquo;entreprise avait atteint un \u00ab\u00a0point de rupture\u00a0\u00bb avec les magasins. Ainsi, il a d&eacute;cid&eacute; de <strong>concentrer ses efforts d&rsquo;investissement sur \u00ab\u00a0DRiP\u00a0\u00bb<\/strong>, la nouvelle plateforme de lancement de jetons non fongibles (NFT) de l&rsquo;entreprise.<\/p><p>Pour expliquer la d&eacute;cision de r&eacute;orienter sa strat&eacute;gie d&rsquo;investissement, Norby a d&eacute;clar&eacute; : \u00ab\u00a0Alors que nos magasins accueillent entre 500 et 1 000 personnes par semaine, <strong>DRiP accueille cette m&ecirc;me quantit&eacute; TOUS LES JOURS\u00a0\u00bb<\/strong>.&nbsp;<\/p><p>C&rsquo;est dire du grand int&eacute;r&ecirc;t que cette plateforme suscite pour Solana Spaces. <strong>Drip promet de fournir aux utilisateurs un NFT gratuit One-of-One<\/strong> r&eacute;alis&eacute; par les meilleurs cr&eacute;ateurs. Ce NFT sera envoy&eacute; directement dans leur porte-monnaie chaque semaine.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/solanaspaces\/status\/1595273817093554176?s=20\"><\/oembed><\/figure><p><strong>Drip a d&eacute;but&eacute; sous le nom de NFT List<\/strong>. La plateforme rebaptis&eacute;e a d&eacute;clar&eacute; que les adresses des portefeuilles de tous ceux qui s&rsquo;inscrivaient &agrave; la NFT List seraient automatiquement import&eacute;es dans Drip.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/solanaspaces\/status\/1595284192061014022?s=20\"><\/oembed><\/figure><p>Dans son fil de discussion sur Twitter, Solana Spaces mentionne que<strong> Drip sera une plaque tournante pour les NFT de Solana Spaces<\/strong> et les r&eacute;compenses de fid&eacute;lit&eacute;. Selon le fil de discussion, les utilisateurs qui collectent les NFTs seront &eacute;ligibles pour des r&eacute;compenses futures comme des marchandises, des listes blanches, et m&ecirc;me plus de NFTs.<\/p><p><strong>Pour utiliser Drip, les utilisateurs doivent connecter leur portefeuille Phantom &agrave; la plateforme<\/strong>. Ensuite, ils doivent v&eacute;rifier leur compte Twitter. Depuis lors, de nombreux utilisateurs se ruent sur Twitter pour v&eacute;rifier leur compte afin de recevoir les NFT gratuits.<\/p>","protected":false},"excerpt":{"rendered":"<p>Source : Solana Spaces \/ TwitterSolana Spaces fermera ses deux magasins th&eacute;matiques Solana, orient&eacute;s vers la communaut&eacute;, &agrave; New York et Miami &agrave; la fin de ce mois. Ces magasins physiques n&rsquo;ont pas permis d&rsquo;accueillir autant d&rsquo;utilisateurs que pr&eacute;vu initialement.Solana Spaces a annonc&eacute; la nouvelle sur Twitter le 21 f&eacute;vrier. Le fondateur Vibhu Norby a [&hellip;]<\/p>\n","protected":false},"author":128,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[5,2],"tags":[],"editors":[2034],"sponsored_companies":[],"class_list":["post-104681","post","type-post","status-publish","format-standard","hentry","category-features","category-exclusives","editors-rose-bidzogo"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Solana Spaces fermera ses magasins de New York et Miami 7 mois apr\u00e8s leur ouverture<\/title>\n<meta name=\"description\" content=\"Solana Spaces va fermer les magasins de New York et de Miami, car ils n&#039;ont pas attir\u00e9 autant d&#039;utilisateurs que pr\u00e9vu.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/fr\/exclusives\/solana-spaces-fermera-ses-magasins-de-new-york-et-miami-7-mois-apres-leur-ouverture\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Solana Spaces fermera ses magasins de New York et Miami 7 mois apr\u00e8s leur ouverture\" \/>\n<meta property=\"og:description\" content=\"Solana Spaces va fermer les magasins de New York et de Miami, car ils n&#039;ont pas attir\u00e9 autant d&#039;utilisateurs que pr\u00e9vu.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/fr\/exclusives\/solana-spaces-fermera-ses-magasins-de-new-york-et-miami-7-mois-apres-leur-ouverture\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews France\" \/>\n<meta property=\"article:published_time\" content=\"2023-02-22T11:27:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-06-26T11:06:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/105648\/258442\/solana-spaces-twitter-1-media-library-original-679-478.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Solana Spaces fermera ses magasins de New York et Miami 7 mois apr\u00e8s leur ouverture\" \/>\n<meta name=\"twitter:description\" content=\"Solana Spaces va fermer les magasins de New York et de Miami, car ils n&#039;ont pas attir\u00e9 autant d&#039;utilisateurs que pr\u00e9vu.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/p\/assets\/empty-cryptonews.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Solana Spaces fermera ses magasins de New York et Miami 7 mois apr\u00e8s leur ouverture","description":"Solana Spaces va fermer les magasins de New York et de Miami, car ils n'ont pas attir\u00e9 autant d'utilisateurs que pr\u00e9vu.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/fr\/exclusives\/solana-spaces-fermera-ses-magasins-de-new-york-et-miami-7-mois-apres-leur-ouverture\/","og_locale":"fr_FR","og_type":"article","og_title":"Solana Spaces fermera ses magasins de New York et Miami 7 mois apr\u00e8s leur ouverture","og_description":"Solana Spaces va fermer les magasins de New York et de Miami, car ils n'ont pas attir\u00e9 autant d'utilisateurs que pr\u00e9vu.","og_url":"https:\/\/cryptonews.com\/fr\/exclusives\/solana-spaces-fermera-ses-magasins-de-new-york-et-miami-7-mois-apres-leur-ouverture\/","og_site_name":"Cryptonews France","article_published_time":"2023-02-22T11:27:00+00:00","article_modified_time":"2023-06-26T11:06:44+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/105648\/258442\/solana-spaces-twitter-1-media-library-original-679-478.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Solana Spaces fermera ses magasins de New York et Miami 7 mois apr\u00e8s leur ouverture","twitter_description":"Solana Spaces va fermer les magasins de New York et de Miami, car ils n'ont pas attir\u00e9 autant d'utilisateurs que pr\u00e9vu.","twitter_image":"https:\/\/cimg.co\/p\/assets\/empty-cryptonews.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/solana-spaces-fermera-ses-magasins-de-new-york-et-miami-7-mois-apres-leur-ouverture\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/solana-spaces-fermera-ses-magasins-de-new-york-et-miami-7-mois-apres-leur-ouverture\/"},"author":{"name":"rosebidzogoofr","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/person\/5b04c7d0cabf02282b92b484476a0784"},"headline":"Solana Spaces fermera ses magasins de New York et Miami 7 mois apr\u00e8s leur ouverture","datePublished":"2023-02-22T11:27:00+00:00","dateModified":"2023-06-26T11:06:44+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/solana-spaces-fermera-ses-magasins-de-new-york-et-miami-7-mois-apres-leur-ouverture\/"},"wordCount":914,"publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/solana-spaces-fermera-ses-magasins-de-new-york-et-miami-7-mois-apres-leur-ouverture\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/105648\/258442\/solana-spaces-twitter-1-media-library-original-679-478.jpeg","articleSection":["Articles","Exclusives"],"inLanguage":"fr-FR","copyrightYear":"2023","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/solana-spaces-fermera-ses-magasins-de-new-york-et-miami-7-mois-apres-leur-ouverture\/","url":"https:\/\/cryptonews.com\/fr\/exclusives\/solana-spaces-fermera-ses-magasins-de-new-york-et-miami-7-mois-apres-leur-ouverture\/","name":"Solana Spaces fermera ses magasins de New York et Miami 7 mois apr\u00e8s leur ouverture","isPartOf":{"@id":"https:\/\/cryptonews.com\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/solana-spaces-fermera-ses-magasins-de-new-york-et-miami-7-mois-apres-leur-ouverture\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/solana-spaces-fermera-ses-magasins-de-new-york-et-miami-7-mois-apres-leur-ouverture\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/105648\/258442\/solana-spaces-twitter-1-media-library-original-679-478.jpeg","datePublished":"2023-02-22T11:27:00+00:00","dateModified":"2023-06-26T11:06:44+00:00","description":"Solana Spaces va fermer les magasins de New York et de Miami, car ils n'ont pas attir\u00e9 autant d'utilisateurs que pr\u00e9vu.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/fr\/exclusives\/solana-spaces-fermera-ses-magasins-de-new-york-et-miami-7-mois-apres-leur-ouverture\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/fr\/exclusives\/solana-spaces-fermera-ses-magasins-de-new-york-et-miami-7-mois-apres-leur-ouverture\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/solana-spaces-fermera-ses-magasins-de-new-york-et-miami-7-mois-apres-leur-ouverture\/#primaryimage","url":"https:\/\/cimg.co\/news\/105648\/258442\/solana-spaces-twitter-1-media-library-original-679-478.jpeg","contentUrl":"https:\/\/cimg.co\/news\/105648\/258442\/solana-spaces-twitter-1-media-library-original-679-478.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/fr\/exclusives\/solana-spaces-fermera-ses-magasins-de-new-york-et-miami-7-mois-apres-leur-ouverture\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/fr\/"},{"@type":"ListItem","position":2,"name":"Solana Spaces fermera ses magasins de New York et Miami 7 mois apr\u00e8s leur ouverture"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/fr\/#website","url":"https:\/\/cryptonews.com\/fr\/","name":"Cryptonews","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/fr\/#organization","name":"Cryptonews France","url":"https:\/\/cryptonews.com\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/3\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews France"},"image":{"@id":"https:\/\/cryptonews.com\/fr\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/104681","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/users\/128"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/comments?post=104681"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/posts\/104681\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/media?parent=104681"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/categories?post=104681"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/tags?post=104681"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/editors?post=104681"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/fr\/wp-json\/wp\/v2\/sponsored_companies?post=104681"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}