{"id":170071,"date":"2025-07-25T17:33:56","date_gmt":"2025-07-25T16:33:56","guid":{"rendered":"https:\/\/cryptonews.com\/de\/?p=170071"},"modified":"2025-07-25T17:33:56","modified_gmt":"2025-07-25T16:33:56","slug":"macht-die-stablecoin-regulierung-der-usa-die-reichen-reicher","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/de\/news\/macht-die-stablecoin-regulierung-der-usa-die-reichen-reicher\/","title":{"rendered":"Macht die Stablecoin-Regulierung der USA die Reichen reicher?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Mehr Vorschriften f\u00fcr Stablecoins in den USA und weniger Wettbewerb &#8211; doch am Ende profitieren wom\u00f6glich vor allem Finanzriesen. Wer steht wirklich im Zentrum der Stablecoin-Regulierung der USA?<\/p><h2 class=\"wp-block-heading\">Regulierung: Durchblick oder Konzentration?<\/h2><span class=\"replacer\"><\/span><p class=\"wp-block-paragraph\">Mit der Verabschiedung des GENIUS Act hat der US-Senat klare Regeln f\u00fcr dollargebundene Stablecoins eingef\u00fchrt. Er erlaubt nur zugelassenen Emittenten den Start. Zudem beh\u00e4lt er dem Staat das Recht vor, die sogenannten PPSI (Payment Platform Systemic Importance) von der Stablecoin-Emission auszuschlie\u00dfen. Sollten diese jedoch strenge Regularien erf\u00fcllen und als abgespaltene Entit\u00e4t, die Stablecoins emittieren, beh\u00e4lt sich die US-Regierung immer noch das Recht vor, diese Stablecoin-Unternehmen besonders zu \u00fcberwachen und zu regulieren. <\/p><p class=\"wp-block-paragraph\">Dabei handelt es sich bei den PPSI umgangssprachlich gesprochen um Tech-Riesen wie Facebook, Amazon und Google. Diese k\u00f6nnten mittels ihrer Relevanz und globalen Kundschaft eine monet\u00e4re Macht entwickeln, die selbst Staaten Konkurrenz macht.<\/p><p class=\"wp-block-paragraph\">Gleichzeitig schreibt er eine 1:1-Deckung mit US-Dollar oder Staatsanleihen vor und verlangt regelm\u00e4\u00dfige Berichte \u00fcber Reserven. Dies k\u00f6nnte wiederum Tether regulatorische Schwierigkeiten bereiten, die bis heute der \u00d6ffentlichkeit einen stichfesten Audit schuldig sind.<\/p><h2 class=\"wp-block-heading\">Kritiker sehen Bevorzugung f\u00fcr bestehende Stablecoin-Anbieter<\/h2><span class=\"replacer\"><\/span><p class=\"wp-block-paragraph\">Trotz dieser Bestimmungen, die wichtige Rahmenbedingungen setzen, warnen Kritiker nun, dass der GENIUS Act vor allem bereits etablierte Akteure einen Vorteil verschaffen. Im Zentrum stehen dabei die etablierten Firmen Tether und Circle, die eine Marktkapitalisierung von 160 und 64 Mrd. USD haben. Auch Binance, die als Kryptob\u00f6rse mehrere Mrd. Euro im <a href=\"https:\/\/cryptonews.com\/de\/kryptowaehrungen\/krypto-trading\/\">Krypto-Trading<\/a> pro Tag handeln, mischt im Stablecoin-Markt mit. <\/p><p class=\"wp-block-paragraph\">Grund f\u00fcr die Annahme, dass die Regulation bestehende Unternehmen beg\u00fcnstigt, ist, dass Neu-Einsteiger durch die Regulation nun mit strengen Vorschriften konfrontiert sind, die Tether, Circle und Binance, ein weiterer Player in der Branche, zu ihrer Zeit nicht erf\u00fcllen mussten. Inzwischen haben sie jedoch einen deutlichen Vorsprung vor ihrer Konkurrenz und profitieren zudem von Skalen- und Netzwerk-Effekten, die es Herausforderern mit <a href=\"https:\/\/cryptonews.com\/de\/kryptowaehrungen\/neue-kryptowaehrungen\/\">neuen Kryptow\u00e4hrungen<\/a> zus\u00e4tzlich schwer machen.<\/p><p class=\"wp-block-paragraph\">Experten warnen davor, dass durch die neuen regulatorischen H\u00fcrden kleinere Emittenten gar keine Chance mehr haben k\u00f6nnten. Der Zugang zu teuren Audits, Treasuries und entsprechend regulatorischer Infrastruktur schon vor dem <a href=\"https:\/\/cryptonews.com\/de\/kryptowaehrungen\/coin-launch\/\">Coin Launch<\/a> ist kostspielig. In fr\u00fcheren F\u00e4llen, etwa bei TerraUSD, wurde bereits deutlich, dass ein Zusammenbruch einzelner Stablecoins erhebliche Auswirkungen entwickeln kann. Der GENIUS Act \u00e4ndere am realen Risiko jedoch wenig, warnt ein Experte der SEC, und verweist auf vergangene Instabilit\u00e4ten.<\/p><h2 class=\"wp-block-heading\">Viele Kritiker vermuten Lobbyismus \u2013 doch auch Trump selbst scheint zu profitieren<\/h2><span class=\"replacer\"><\/span><p class=\"wp-block-paragraph\">Dass mehrere hundert Millionen beispielsweise bei den Wahlen 2024 in den USA ins Lobbying flossen, ist \u00f6ffentlicht dokumentiert. Das<a href=\"https:\/\/cepr.net\/publications\/genius-act-provides-profits-for-the-crypto-industry-risk-for-everyone-else\/?utm_source=chatgpt.com\"> Center for Economic and Policy Research<\/a> sieht den GENIUS Act als Legitimierung gro\u00dfer Unternehmen mit gewachsenem Einfluss, allerdings auf Kosten des Wettbewerbs und mit erh\u00f6htem Risiko f\u00fcr die breite \u00d6ffentlichkeit. Auch der New Yorker verweist auf enge Verbindungen zwischen der Trump-Familie und Stablecoin-Emissionen, und fragt sich, wer reguliert hier eigentlich wen?<\/p><p class=\"wp-block-paragraph\">Nach der Verabschiedung stiegen Aktien von Unternehmen wie Coinbase deutlich an. Gleichzeitig sank das Interesse an traditionellen Zahlungsnetzwerken wie Visa und Mastercard. Dieser Umstand kann als Hinweis gedeutet werden, dass sich regulatorische Gewinne m\u00f6glicherweise in Richtung Krypto-Branchengr\u00f6\u00dfen verlagern. Als ein direktes Ergebnis der neuen Auflagen, investieren auch Institutionen wie Tether oder Circle massiv in US-Staatsanleihen. <\/p><p class=\"wp-block-paragraph\">Einerseits k\u00f6nnte dies Sinn ergeben, wenn diese nun ihre Emmission an Stablecoin erh\u00f6hen wollen. Andererseits k\u00f6nnten Skeptiker hier eine Art Bezahlung an die Regierung f\u00fcr erbrachte Leistungen sehen.<\/p>","protected":false},"excerpt":{"rendered":"<p>Mehr Vorschriften f\u00fcr Stablecoins in den USA und weniger Wettbewerb &#8211; doch am Ende profitieren wom\u00f6glich vor allem Finanzriesen. Wer steht wirklich im Zentrum der Stablecoin-Regulierung der USA?Regulierung: Durchblick oder Konzentration?Mit der Verabschiedung des GENIUS Act hat der US-Senat klare Regeln f\u00fcr dollargebundene Stablecoins eingef\u00fchrt. Er erlaubt nur zugelassenen Emittenten den Start. Zudem beh\u00e4lt er [&hellip;]<\/p>\n","protected":false},"author":650,"featured_media":170072,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[8,1],"tags":[324],"editors":[5124],"sponsored_companies":[],"class_list":["post-170071","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-altcoin-news","category-news","tag-stablecoin","editors-michael-sprick"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Macht die Stablecoin-Regulierung der USA die Reichen reicher?<\/title>\n<meta name=\"description\" content=\"Lobbyismus und Bevorzugung bestehender Anbieter - macht die Stablecoin-Regulierung der USA die Reichen reicher?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/de\/news\/macht-die-stablecoin-regulierung-der-usa-die-reichen-reicher\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Macht die Stablecoin-Regulierung der USA die Reichen reicher?\" \/>\n<meta property=\"og:description\" content=\"Lobbyismus und Bevorzugung bestehender Anbieter - macht die Stablecoin-Regulierung der USA die Reichen reicher?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/de\/news\/macht-die-stablecoin-regulierung-der-usa-die-reichen-reicher\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Germany\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-25T16:33:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/07\/25172931\/1753460970-stablecoin-lobbying.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1456\" \/>\n\t<meta property=\"og:image:height\" content=\"816\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:description\" content=\"Lobbyismus und Bevorzugung bestehender Anbieter - macht die Stablecoin-Regulierung der USA die Reichen reicher?\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/07\/25172931\/1753460970-stablecoin-lobbying.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Macht die Stablecoin-Regulierung der USA die Reichen reicher?","description":"Lobbyismus und Bevorzugung bestehender Anbieter - macht die Stablecoin-Regulierung der USA die Reichen reicher?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/de\/news\/macht-die-stablecoin-regulierung-der-usa-die-reichen-reicher\/","og_locale":"de_DE","og_type":"article","og_title":"Macht die Stablecoin-Regulierung der USA die Reichen reicher?","og_description":"Lobbyismus und Bevorzugung bestehender Anbieter - macht die Stablecoin-Regulierung der USA die Reichen reicher?","og_url":"https:\/\/cryptonews.com\/de\/news\/macht-die-stablecoin-regulierung-der-usa-die-reichen-reicher\/","og_site_name":"Cryptonews Germany","article_published_time":"2025-07-25T16:33:56+00:00","og_image":[{"width":1456,"height":816,"url":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/07\/25172931\/1753460970-stablecoin-lobbying.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_description":"Lobbyismus und Bevorzugung bestehender Anbieter - macht die Stablecoin-Regulierung der USA die Reichen reicher?","twitter_image":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/07\/25172931\/1753460970-stablecoin-lobbying.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/de\/news\/macht-die-stablecoin-regulierung-der-usa-die-reichen-reicher\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/de\/news\/macht-die-stablecoin-regulierung-der-usa-die-reichen-reicher\/"},"author":{"name":"michaelsprick","@id":"https:\/\/cryptonews.com\/de\/#\/schema\/person\/1f02092f94b5d7bbf1e366211a4c071e"},"headline":"Macht die Stablecoin-Regulierung der USA die Reichen reicher?","datePublished":"2025-07-25T16:33:56+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/de\/news\/macht-die-stablecoin-regulierung-der-usa-die-reichen-reicher\/"},"wordCount":573,"publisher":{"@id":"https:\/\/cryptonews.com\/de\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/de\/news\/macht-die-stablecoin-regulierung-der-usa-die-reichen-reicher\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/07\/25172931\/1753460970-stablecoin-lobbying.jpg","keywords":["Stablecoin"],"articleSection":["Altcoin News","News"],"inLanguage":"de","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/de\/news\/macht-die-stablecoin-regulierung-der-usa-die-reichen-reicher\/","url":"https:\/\/cryptonews.com\/de\/news\/macht-die-stablecoin-regulierung-der-usa-die-reichen-reicher\/","name":"Macht die Stablecoin-Regulierung der USA die Reichen reicher?","isPartOf":{"@id":"https:\/\/cryptonews.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/de\/news\/macht-die-stablecoin-regulierung-der-usa-die-reichen-reicher\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/de\/news\/macht-die-stablecoin-regulierung-der-usa-die-reichen-reicher\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/07\/25172931\/1753460970-stablecoin-lobbying.jpg","datePublished":"2025-07-25T16:33:56+00:00","description":"Lobbyismus und Bevorzugung bestehender Anbieter - macht die Stablecoin-Regulierung der USA die Reichen reicher?","breadcrumb":{"@id":"https:\/\/cryptonews.com\/de\/news\/macht-die-stablecoin-regulierung-der-usa-die-reichen-reicher\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/de\/news\/macht-die-stablecoin-regulierung-der-usa-die-reichen-reicher\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cryptonews.com\/de\/news\/macht-die-stablecoin-regulierung-der-usa-die-reichen-reicher\/#primaryimage","url":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/07\/25172931\/1753460970-stablecoin-lobbying.jpg","contentUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/07\/25172931\/1753460970-stablecoin-lobbying.jpg","width":1456,"height":816,"caption":"Macht die Stablecoin-Regulierung der USA die Reichen reicher?"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/de\/news\/macht-die-stablecoin-regulierung-der-usa-die-reichen-reicher\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/de\/"},{"@type":"ListItem","position":2,"name":"Macht die Stablecoin-Regulierung der USA die Reichen reicher?"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/de\/#website","url":"https:\/\/cryptonews.com\/de\/","name":"Cryptonews","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/de\/#organization","name":"Cryptonews","url":"https:\/\/cryptonews.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cryptonews.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Cryptonews"},"image":{"@id":"https:\/\/cryptonews.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/posts\/170071","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/users\/650"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/comments?post=170071"}],"version-history":[{"count":1,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/posts\/170071\/revisions"}],"predecessor-version":[{"id":170073,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/posts\/170071\/revisions\/170073"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/media\/170072"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/media?parent=170071"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/categories?post=170071"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/tags?post=170071"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/editors?post=170071"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/sponsored_companies?post=170071"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}