{"id":167906,"date":"2025-06-23T13:47:40","date_gmt":"2025-06-23T12:47:40","guid":{"rendered":"https:\/\/cryptonews.com\/de\/?p=167906"},"modified":"2025-06-23T13:47:40","modified_gmt":"2025-06-23T12:47:40","slug":"israelische-hacker-gruppe-erbeutet-von-iranischer-exchange-kryptowahrungen-im-wert-von-817-mio-usd","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/de\/news\/israelische-hacker-gruppe-erbeutet-von-iranischer-exchange-kryptowahrungen-im-wert-von-817-mio-usd\/","title":{"rendered":"Israelische Hacker Gruppe erbeutet von iranischer Exchange Kryptow\u00e4hrungen im Wert von 81,7 Mio. USD"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Die pro-israelische Hackergruppe Gonjeshke Darande hat am 18. Juni 2025 Kryptow\u00e4hrungen im Wert von 81,7 Mio. USD von der iranischen Kryptob\u00f6rse Nobitex gekapert und vernichtet, um eine politische Botschaft gegen die Sanktionsumgehung und Terrorfinanzierung des iranischen Regimes zu senden.<\/p><h2 class=\"wp-block-heading\">Israelische Hackergruppe Gonjeshke Darande kapert Krypto im Wert vonn 81,7 Mio. USD<\/h2><span class=\"replacer\"><\/span><p class=\"wp-block-paragraph\">Die proisraelische Hacker-Gruppe Gonjeshke Darande hat auf der iranischen Kryptob\u00f6rse Nobitex Kryptow\u00e4hrungen im Wert von 81,7 Mio. USD gekapert und vernichtet. Nobitex best\u00e4tigt den Einbruch einem<a href=\"https:\/\/x.com\/nobitexmarket\/status\/1935222149989519671\"> Post auf X<\/a>. <\/p><p class=\"wp-block-paragraph\">In einem <a href=\"https:\/\/x.com\/gonjeshkedarand\/status\/1935231018937536681\">Bekennerschreiben <\/a>verwiesen die Hacker darauf, dass es ihnen nicht um einen blo\u00dfen Raubzug, sondern um eine politische Botschaft gegangen sei.<\/p><h2 class=\"wp-block-heading\">Mutma\u00dflich persische Hacker<\/h2><span class=\"replacer\"><\/span><p class=\"wp-block-paragraph\">Die Hackergruppe hat m\u00f6glicherweise Verbindungen zu Israel und bekennt sich offen zu den Zielen des j\u00fcdischen Staates, besteht aber mutma\u00dflich aus iranischen und\/oder irakischen Mitgliedern. Darauf verweist ihr Name \u201eGonjeshke Darande\u201c, der sich im Persischen mit \u201eR\u00e4uberischer Sperling\u201c \u00fcbersetzen l\u00e4sst. <\/p><p class=\"wp-block-paragraph\">Es ging den Hackern um einen umfassenden Schaden, denn sie ver\u00f6ffentlichten auch den Quellcode von Nobitex, was die Plattform extrem verwundbar macht. Experten betrachten den Angriff als eine politische Reaktion auf den Krieg zwischen dem Iran und Israel.<\/p><h2 class=\"wp-block-heading\">Welche Rolle spielt die Kryptob\u00f6rses Nobitex?<\/h2><span class=\"replacer\"><\/span><p class=\"wp-block-paragraph\">Laut Gonjeshke Darande ist Nobitex ma\u00dfgeblich daran beteiligt, f\u00fcr die iranische Regierung Sanktionen zu umgehen, die sich auch gegen den Bankensektor des Landes richten. Es handelt sich um eine <a href=\"https:\/\/cryptonews.com\/de\/kryptowaehrungen\/krypto-boersen-ohne-kyc\/\">Krypto B\u00f6rse, die ohne KYC<\/a> operiert. Auch hilft die Kryptob\u00f6rse dem iranischen Geheimdienst bei seiner Finanzierung von illegalen Operationen rund um den Globus. <\/p><p class=\"wp-block-paragraph\">Die Hacker verweisen in ihrem Statement darauf, dass Nobitex das wohl wichtigste Vehikel des iranischen Regimes f\u00fcr die weltweite Terrorfinanzierung ist. Dabei ist das <a href=\"https:\/\/cryptonews.com\/de\/kryptowaehrungen\/krypto-trading\/\">Krypto Trading<\/a> ein Vorwand zu sein. Auch f\u00fcr das Umgehen von Sanktionen scheint die Kryptob\u00f6rse zentral zu sein. Die Hacker warnen sowohl die Betreiber als auch Kunden von Nobitex, dass bei der Beteiligung an Sanktionsverst\u00f6\u00dfen und Terrorfinanzierung ein Verlust des eigenen Verm\u00f6gens droht.<\/p><h2 class=\"wp-block-heading\">Wie ging Gonjeshke Darande vor?<\/h2><span class=\"replacer\"><\/span><p class=\"wp-block-paragraph\">Die offenbar sehr erfahrenen Hacker verschoben am 18. Juni 2025 spezielle <a href=\"https:\/\/cryptonews.com\/de\/kryptowaehrungen\/krypto-wallet-test\/\">Krypto Wallets<\/a> in die B\u00f6rse, kaperten damit Anlagen in Kryptow\u00e4hrungen und vernichteten sie anschlie\u00dfend. Das vermuten jedenfalls Experten des Beratungsunternehmens Elliptic, die sich den Fall genauer angeschaut haben. <\/p><p class=\"wp-block-paragraph\">Die Wallets f\u00fcr die Unterwanderung der Kryptob\u00f6rse trugen provokative Namen wie \u201eF*ckIRGCterrorists\u201c. Scheinbar konnten die Hacker selbst nicht auf das Kryptogeld zugreifen. Es ging ihnen nur um die politische Botschaft, so ein Sprecher von Elliptic.<\/p><h2 class=\"wp-block-heading\">Nicht der erste Angriff von Gonjeshke Darande<\/h2><span class=\"replacer\"><\/span><p class=\"wp-block-paragraph\">Gonjeshke Darande fiel in den letzten Jahren mit mehreren spektakul\u00e4ren Aktionen auf. Die Hacker konnten in die iranische Bank Sepah eindringen, etliche Zahlungssysteme von Tankstellen lahmlegen und sogar Feuer in einem iranischen Stahlwerk entfachen. Ihr Angriff auf das Finanzsystem stellt f\u00fcr das Regime eine sehr ernste Gefahr dar.<\/p>","protected":false},"excerpt":{"rendered":"<p>Die pro-israelische Hackergruppe Gonjeshke Darande hat am 18. Juni 2025 Kryptow\u00e4hrungen im Wert von 81,7 Mio. USD von der iranischen Kryptob\u00f6rse Nobitex gekapert und vernichtet, um eine politische Botschaft gegen die Sanktionsumgehung und Terrorfinanzierung des iranischen Regimes zu senden.Israelische Hackergruppe Gonjeshke Darande kapert Krypto im Wert vonn 81,7 Mio. USDDie proisraelische Hacker-Gruppe Gonjeshke Darande hat [&hellip;]<\/p>\n","protected":false},"author":650,"featured_media":167907,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[71],"editors":[5124],"sponsored_companies":[],"class_list":["post-167906","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-news","tag-altcoins","editors-michael-sprick"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Israelische Hacker Gruppe erbeutet von iranischer Exchange Kryptow\u00e4hrungen im Wert von 81,7 Mio. USD<\/title>\n<meta name=\"description\" content=\"Die pro-israelische Hackergruppe Gonjeshke Darande hat am 18. Juni 2025 Kryptow\u00e4hrungen im Wert von 81,7 Mio. USD von der iranischen Kryptob\u00f6rse Nobitex\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/de\/news\/israelische-hacker-gruppe-erbeutet-von-iranischer-exchange-kryptowahrungen-im-wert-von-817-mio-usd\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Israelische Hacker Gruppe erbeutet von iranischer Exchange Kryptow\u00e4hrungen im Wert von 81,7 Mio. USD\" \/>\n<meta property=\"og:description\" content=\"Die pro-israelische Hackergruppe Gonjeshke Darande hat am 18. Juni 2025 Kryptow\u00e4hrungen im Wert von 81,7 Mio. USD von der iranischen Kryptob\u00f6rse Nobitex\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/de\/news\/israelische-hacker-gruppe-erbeutet-von-iranischer-exchange-kryptowahrungen-im-wert-von-817-mio-usd\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Germany\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-23T12:47:40+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/06\/23134656\/1750682815-nobitex-gojeshke-darande.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1456\" \/>\n\t<meta property=\"og:image:height\" content=\"816\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/06\/23134656\/1750682815-nobitex-gojeshke-darande.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Israelische Hacker Gruppe erbeutet von iranischer Exchange Kryptow\u00e4hrungen im Wert von 81,7 Mio. USD","description":"Die pro-israelische Hackergruppe Gonjeshke Darande hat am 18. Juni 2025 Kryptow\u00e4hrungen im Wert von 81,7 Mio. USD von der iranischen Kryptob\u00f6rse Nobitex","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/de\/news\/israelische-hacker-gruppe-erbeutet-von-iranischer-exchange-kryptowahrungen-im-wert-von-817-mio-usd\/","og_locale":"de_DE","og_type":"article","og_title":"Israelische Hacker Gruppe erbeutet von iranischer Exchange Kryptow\u00e4hrungen im Wert von 81,7 Mio. USD","og_description":"Die pro-israelische Hackergruppe Gonjeshke Darande hat am 18. Juni 2025 Kryptow\u00e4hrungen im Wert von 81,7 Mio. USD von der iranischen Kryptob\u00f6rse Nobitex","og_url":"https:\/\/cryptonews.com\/de\/news\/israelische-hacker-gruppe-erbeutet-von-iranischer-exchange-kryptowahrungen-im-wert-von-817-mio-usd\/","og_site_name":"Cryptonews Germany","article_published_time":"2025-06-23T12:47:40+00:00","og_image":[{"width":1456,"height":816,"url":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/06\/23134656\/1750682815-nobitex-gojeshke-darande.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/06\/23134656\/1750682815-nobitex-gojeshke-darande.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/de\/news\/israelische-hacker-gruppe-erbeutet-von-iranischer-exchange-kryptowahrungen-im-wert-von-817-mio-usd\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/de\/news\/israelische-hacker-gruppe-erbeutet-von-iranischer-exchange-kryptowahrungen-im-wert-von-817-mio-usd\/"},"author":{"name":"michaelsprick","@id":"https:\/\/cryptonews.com\/de\/#\/schema\/person\/1f02092f94b5d7bbf1e366211a4c071e"},"headline":"Israelische Hacker Gruppe erbeutet von iranischer Exchange Kryptow\u00e4hrungen im Wert von 81,7 Mio. USD","datePublished":"2025-06-23T12:47:40+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/de\/news\/israelische-hacker-gruppe-erbeutet-von-iranischer-exchange-kryptowahrungen-im-wert-von-817-mio-usd\/"},"wordCount":481,"publisher":{"@id":"https:\/\/cryptonews.com\/de\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/de\/news\/israelische-hacker-gruppe-erbeutet-von-iranischer-exchange-kryptowahrungen-im-wert-von-817-mio-usd\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/06\/23134656\/1750682815-nobitex-gojeshke-darande.jpg","keywords":["Altcoins"],"articleSection":["News"],"inLanguage":"de","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/de\/news\/israelische-hacker-gruppe-erbeutet-von-iranischer-exchange-kryptowahrungen-im-wert-von-817-mio-usd\/","url":"https:\/\/cryptonews.com\/de\/news\/israelische-hacker-gruppe-erbeutet-von-iranischer-exchange-kryptowahrungen-im-wert-von-817-mio-usd\/","name":"Israelische Hacker Gruppe erbeutet von iranischer Exchange Kryptow\u00e4hrungen im Wert von 81,7 Mio. USD","isPartOf":{"@id":"https:\/\/cryptonews.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/de\/news\/israelische-hacker-gruppe-erbeutet-von-iranischer-exchange-kryptowahrungen-im-wert-von-817-mio-usd\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/de\/news\/israelische-hacker-gruppe-erbeutet-von-iranischer-exchange-kryptowahrungen-im-wert-von-817-mio-usd\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/06\/23134656\/1750682815-nobitex-gojeshke-darande.jpg","datePublished":"2025-06-23T12:47:40+00:00","description":"Die pro-israelische Hackergruppe Gonjeshke Darande hat am 18. Juni 2025 Kryptow\u00e4hrungen im Wert von 81,7 Mio. USD von der iranischen Kryptob\u00f6rse Nobitex","breadcrumb":{"@id":"https:\/\/cryptonews.com\/de\/news\/israelische-hacker-gruppe-erbeutet-von-iranischer-exchange-kryptowahrungen-im-wert-von-817-mio-usd\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/de\/news\/israelische-hacker-gruppe-erbeutet-von-iranischer-exchange-kryptowahrungen-im-wert-von-817-mio-usd\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cryptonews.com\/de\/news\/israelische-hacker-gruppe-erbeutet-von-iranischer-exchange-kryptowahrungen-im-wert-von-817-mio-usd\/#primaryimage","url":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/06\/23134656\/1750682815-nobitex-gojeshke-darande.jpg","contentUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/06\/23134656\/1750682815-nobitex-gojeshke-darande.jpg","width":1456,"height":816,"caption":"Die pro-israelische Hackergruppe Gonjeshke Darande hat am 18. Juni 2025 Kryptow\u00e4hrungen im Wert von 81,7 Mio. USD von der iranischen Kryptob\u00f6rse Nobitex gekapert und vernichtet, um eine politische Botschaft gegen die Sanktionsumgehung und Terrorfinanzierung des iranischen Regimes zu senden."},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/de\/news\/israelische-hacker-gruppe-erbeutet-von-iranischer-exchange-kryptowahrungen-im-wert-von-817-mio-usd\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/de\/"},{"@type":"ListItem","position":2,"name":"Israelische Hacker Gruppe erbeutet von iranischer Exchange Kryptow\u00e4hrungen im Wert von 81,7 Mio. USD"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/de\/#website","url":"https:\/\/cryptonews.com\/de\/","name":"Cryptonews","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/de\/#organization","name":"Cryptonews","url":"https:\/\/cryptonews.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cryptonews.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Cryptonews"},"image":{"@id":"https:\/\/cryptonews.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/posts\/167906","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/users\/650"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/comments?post=167906"}],"version-history":[{"count":1,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/posts\/167906\/revisions"}],"predecessor-version":[{"id":167908,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/posts\/167906\/revisions\/167908"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/media\/167907"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/media?parent=167906"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/categories?post=167906"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/tags?post=167906"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/editors?post=167906"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/sponsored_companies?post=167906"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}