{"id":166756,"date":"2025-06-05T12:39:17","date_gmt":"2025-06-05T11:39:17","guid":{"rendered":"https:\/\/cryptonews.com\/de\/?p=166756"},"modified":"2025-06-05T12:39:17","modified_gmt":"2025-06-05T11:39:17","slug":"spende-an-ross-ulbricht-von-300-btc-an-korruption-beim-ethereum-ico-geknupft","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/de\/news\/spende-an-ross-ulbricht-von-300-btc-an-korruption-beim-ethereum-ico-geknupft\/","title":{"rendered":"Spende an Ross Ulbricht von 300 BTC an Korruption beim Ethereum ICO gekn\u00fcpft?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Eine Spende von 300 BTC an Ross Ulbricht, die \u00fcber Kraken abgewickelt wurde, steht im Verdacht, mit Korruption beim Ethereum ICO 2014 in Verbindung zu stehen, da die Gelder m\u00f6glicherweise aus beschlagnahmten Silk Road-Wallets stammen und \u00fcber den Mixer Jambler liefen.<\/p><h2 class=\"wp-block-heading\">Spenden an Ulbricht \u2013 an sich eine Geste der Solidarit\u00e4t<\/h2><span class=\"replacer\"><\/span><p class=\"wp-block-paragraph\">Im Januar dieses Jahres wurde Ross Ulbricht von Donald Trump begnadigt, nachdem dieser dies zu einem seiner Wahlversprechen gemacht hat. Ulbricht wurde 2013 von einem New Yorker Gericht zu zweifach lebenslanger Haft plus weiterer 40 Jahre Gef\u00e4ngnis verurteilt. <\/p><p class=\"wp-block-paragraph\">Das Gericht warf ihm vor, verantwortlich f\u00fcr die illegalen Aktivit\u00e4ten auf der Darknet-Plattform Silk Road zu sein, weil er sie betrieben hat. Nach seiner Freilassung spendeten viele Menschen Geld an Ulbricht, haupts\u00e4chlich in Form von BTC.<\/p><p class=\"wp-block-paragraph\">Bereits kurz nach seiner Freilassung erhielt der ehemalige Online-Unternehmer gr\u00f6\u00dfere Summen in H\u00f6he von einigen hunderttausend US-Dollar. Au\u00dferdem versteigerte er Kleidung, Gef\u00e4ngnisausweise, ein Notizbuch, eine Trommel, einen Rucksack und Gem\u00e4lde im Wert von fast 800 000 USD. Er will nichts mehr aus seiner Zeit im Gef\u00e4ngnis behalten.<\/p><h2 class=\"wp-block-heading\">Eine einzige Spende sorgt f\u00fcr viel Aufmerksamkeit<\/h2><span class=\"replacer\"><\/span><p class=\"wp-block-paragraph\">Dabei sorgt vor allem eine einzelne Spende f\u00fcr hohe Aufmerksamkeit. Eine Spende f\u00fcr eine Privatperson in H\u00f6he von 300 BTC oder 31,4 Millionen USD d\u00fcrfte weit \u00fcber gew\u00f6hnlichen Altruismus hinausgehen. <\/p><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Ross Ulbricht(<a href=\"https:\/\/twitter.com\/RealRossU?ref_src=twsrc%5Etfw\">@RealRossU<\/a>), the founder of the <a href=\"https:\/\/twitter.com\/hashtag\/SilkRoad?src=hash&amp;ref_src=twsrc%5Etfw\">#SilkRoad<\/a> marketplace, received 300 <a href=\"https:\/\/twitter.com\/search?q=%24BTC&amp;src=ctag&amp;ref_src=twsrc%5Etfw\">$BTC<\/a>($31.4M) to his donation wallet 8 hours ago.<a href=\"https:\/\/t.co\/3DEsM9rpBq\">https:\/\/t.co\/3DEsM9rpBq<\/a> <a href=\"https:\/\/t.co\/JoUMNqM99p\">pic.twitter.com\/JoUMNqM99p<\/a><\/p>&mdash; Lookonchain (@lookonchain) <a href=\"https:\/\/twitter.com\/lookonchain\/status\/1929015485439389888?ref_src=twsrc%5Etfw\">June 1, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><p class=\"wp-block-paragraph\">Die Bitcoin-Transaktion fand \u00fcber Kraken statt und wurde durch Lookonchain aufgedeckt. Das <\/p><p class=\"wp-block-paragraph\">Team hinter Lookonchain machte dabei jedoch auf keine Verdachtsmomente aufmerksam.<\/p><p class=\"wp-block-paragraph\">Einige nahmen dabei zun\u00e4chst an, Ulbricht habe die \u00dcberweisung selbst get\u00e4tigt. Er besitzt n\u00e4mlich einige <a href=\"https:\/\/cryptonews.com\/de\/kryptowaehrungen\/krypto-wallet-test\/\">Krypto Wallets<\/a>, die seit 13 Jahren nicht angetastet wurden und die nun einen Wert von etwa 47 Millionen US-Dollar haben. <\/p><h2 class=\"wp-block-heading\">ZachXBT h\u00e4lt \u201cSpende\u201d durch Ulbricht selbst f\u00fcr unwahrscheinlich<\/h2><span class=\"replacer\"><\/span><p class=\"wp-block-paragraph\">Erst durch ZachXBT, einem bekannten Krypto-Detektiven, fiel auf, dass die Transaktion durchaus verd\u00e4chtige Umst\u00e4nde mit sich zieht. So kamen die BTC offenbar aus Outputs zustande, die zuvor den Mixer Jambler durchlaufen hatten. <\/p><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Update: Few entities regularly use Jambler in size so I found a potential demix for the donation. 1Mp5hH originates from late 2014 exchange activity. 1CNDW has 2019 exchange activity and was previously flagged in compliance tools. <br><br>1Mp5hH &amp; 1CNDW were depositing in size to\u2026<\/p>&mdash; ZachXBT (@zachxbt) <a href=\"https:\/\/twitter.com\/zachxbt\/status\/1929378278214906145?ref_src=twsrc%5Etfw\">June 2, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><p class=\"wp-block-paragraph\">Diesen bezeichnet ZachXBT als \u201cverd\u00e4chtig\u201d und zentralisiert. Normalerweise w\u00fcrden auf Privatsph\u00e4re achtende Nutzer auf <a href=\"https:\/\/cryptonews.com\/de\/kryptowaehrungen\/dezentrale-kryptoboersen\/\">DEX Crypto<\/a> (decentralised Exchange) Services setzen. Da nur wenige Entit\u00e4ten diese h\u00e4ufiger nutzen, w\u00fcrde dies auch den Pool an m\u00f6glichen Transaktionen einschr\u00e4nken. <\/p><p class=\"wp-block-paragraph\">ZachXBT nennt dabei zwei Transaktionen, wobei eine von Ende 2014 stammt und die andere auf 2019 datiert. Er verweist jedoch, dass dies nur m\u00f6gliche Matches und nicht eindeutig nachweisbare Verbindungen bestehen.<\/p><h2 class=\"wp-block-heading\">Was sagt TruthLabs zum Fall?<\/h2><span class=\"replacer\"><\/span><p class=\"wp-block-paragraph\"><a href=\"https:\/\/x.com\/BoringSleuth\">TruthLabs<\/a> ist ein weiterer Krypto-Detektiv. Auch er hat sich zu dem Fall gemeldet und bringt ihn mit dem Ethereum ICO 2014 in Verbindung \u2013 allerdings nur spekulativ. Nach Ulbrichts Verhaftung im Jahr 2013 wurden einige seiner <a href=\"https:\/\/cryptonews.com\/de\/kryptowaehrungen\/bitcoin-wallet\/\">Bitcoin-Wallets<\/a> von der US-Regierung beschlagnahmt. <\/p><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Ethereum\u2019s largest whales who purchased the ETH ICO in 2014,  used Bitcoin sent from Silk Road addresses directly connected to corrupt &amp; convicted FBI Agents, Ross Ulbricht\u2019s own seized Silk Road address\u2019, the Ethereum Foundations Bitcoin address used before their ICO, and the\u2026 <a href=\"https:\/\/t.co\/KqJYzqyVxr\">https:\/\/t.co\/KqJYzqyVxr<\/a> <a href=\"https:\/\/t.co\/7G6y6La4HA\">pic.twitter.com\/7G6y6La4HA<\/a><\/p>&mdash; TruthLabs \ud83e\udee1 (@BoringSleuth) <a href=\"https:\/\/twitter.com\/BoringSleuth\/status\/1929284512749392024?ref_src=twsrc%5Etfw\">June 1, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><p class=\"wp-block-paragraph\">Im Januar 2014 tauchten Gelder aus dieser beschlagnahmten Wallet in Ethereums ICO auf. Die \u201cgr\u00f6\u00dften Wale nutzten Bitcoin, die aus beschlagnahmten Silk Road Adressen stammten\u201d. <\/p><p class=\"wp-block-paragraph\">In Folge dieses Fundings entstand wiederum eine DAO, die Opfer eines offenbar durch Insider inszenierten Hacks wurde. Dabei stahlen die Hacker 3,6 Millionen ETH, damals etwa 50 Millionen US-Dollar \u2013 <a href=\"https:\/\/cryptonews.com\/de\/news\/ethereum-vampirangriff-2016-von-insidern-durchgefuhrt\/\">mehr \u00fcber den Fall hier<\/a>.<\/p><p class=\"wp-block-paragraph\">TruthLabs stellt damit eine Verbindung zwischen den F\u00e4llen her und legt nahe, dass es sich nicht um eine Spende, sondern eine Art \u201cWiedergutmachung\u201d f\u00fcr die Verwendung der Funds von Ross Ulbricht handeln k\u00f6nnte.<\/p><p class=\"wp-block-paragraph\">Es ist nicht das erste Mal, dass TruthLabs Vitalik im Zusammenhang mit Ross Ulbricht an diese Korruption bei Ethereum erinnert.<\/p><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">Vitalik, your ICO, and your Foundations own BTC wallets were funded from Bitcoin that came from <a href=\"https:\/\/twitter.com\/RealRossU?ref_src=twsrc%5Etfw\">@RealRossU<\/a> seized Silk Road wallet address\u2019.<br><br>It was Ross\u2019 demise that funded the Ethereum Foundation, and purchased out the majority of your entire ICO.  His The literal Foundation of\u2026 <a href=\"https:\/\/t.co\/40Eb7Jrlha\">https:\/\/t.co\/40Eb7Jrlha<\/a> <a href=\"https:\/\/t.co\/YKxPmhnWaF\">pic.twitter.com\/YKxPmhnWaF<\/a><\/p>&mdash; TruthLabs \ud83e\udee1 (@BoringSleuth) <a href=\"https:\/\/twitter.com\/BoringSleuth\/status\/1881175747856912653?ref_src=twsrc%5Etfw\">January 20, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><p class=\"wp-block-paragraph\">Wobei er im ersten Post auch darauf hinweist, dass Gelder \u201cweiter in hunderten, wenn nicht sogar tausenden anderen <a href=\"https:\/\/cryptonews.com\/de\/kryptowaehrungen\/krypto-ico-kaufen\/\">ICOs<\/a> gewaschen wurden, die seit 2015 auf Ethereum stattgefunden haben.\u201d<\/p>","protected":false},"excerpt":{"rendered":"<p>Eine Spende von 300 BTC an Ross Ulbricht, die \u00fcber Kraken abgewickelt wurde, steht im Verdacht, mit Korruption beim Ethereum ICO 2014 in Verbindung zu stehen, da die Gelder m\u00f6glicherweise aus beschlagnahmten Silk Road-Wallets stammen und \u00fcber den Mixer Jambler liefen.Spenden an Ulbricht \u2013 an sich eine Geste der Solidarit\u00e4tIm Januar dieses Jahres wurde Ross [&hellip;]<\/p>\n","protected":false},"author":650,"featured_media":166758,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6,1],"tags":[55],"editors":[5124],"sponsored_companies":[],"class_list":["post-166756","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bitcoin-news","category-news","tag-bitcoin","editors-michael-sprick"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Weist 300 BTC Spende an Ross Ulbricht auf korruptes ETH ICO?<\/title>\n<meta name=\"description\" content=\"Ist die Spende an Ross Ulbricht von 300 BTC an korrupte Aktivit\u00e4ten von FBI-Agenten beim Ethereum ICO gekn\u00fcpft?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/de\/news\/spende-an-ross-ulbricht-von-300-btc-an-korruption-beim-ethereum-ico-geknupft\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Weist 300 BTC Spende an Ross Ulbricht auf korruptes ETH ICO?\" \/>\n<meta property=\"og:description\" content=\"Ist die Spende an Ross Ulbricht von 300 BTC an korrupte Aktivit\u00e4ten von FBI-Agenten beim Ethereum ICO gekn\u00fcpft?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/de\/news\/spende-an-ross-ulbricht-von-300-btc-an-korruption-beim-ethereum-ico-geknupft\/\" \/>\n<meta property=\"og:site_name\" content=\"Cryptonews Germany\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-05T11:39:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/06\/05123354\/1749123233-ulbricht-spende.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1456\" \/>\n\t<meta property=\"og:image:height\" content=\"816\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Weist 300 BTC Spende an Ross Ulbricht auf korruptes ETH ICO?\" \/>\n<meta name=\"twitter:description\" content=\"Ist die Spende an Ross Ulbricht von 300 BTC an korrupte Aktivit\u00e4ten von FBI-Agenten beim Ethereum ICO gekn\u00fcpft?\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/06\/05123354\/1749123233-ulbricht-spende.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Weist 300 BTC Spende an Ross Ulbricht auf korruptes ETH ICO?","description":"Ist die Spende an Ross Ulbricht von 300 BTC an korrupte Aktivit\u00e4ten von FBI-Agenten beim Ethereum ICO gekn\u00fcpft?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/de\/news\/spende-an-ross-ulbricht-von-300-btc-an-korruption-beim-ethereum-ico-geknupft\/","og_locale":"de_DE","og_type":"article","og_title":"Weist 300 BTC Spende an Ross Ulbricht auf korruptes ETH ICO?","og_description":"Ist die Spende an Ross Ulbricht von 300 BTC an korrupte Aktivit\u00e4ten von FBI-Agenten beim Ethereum ICO gekn\u00fcpft?","og_url":"https:\/\/cryptonews.com\/de\/news\/spende-an-ross-ulbricht-von-300-btc-an-korruption-beim-ethereum-ico-geknupft\/","og_site_name":"Cryptonews Germany","article_published_time":"2025-06-05T11:39:17+00:00","og_image":[{"width":1456,"height":816,"url":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/06\/05123354\/1749123233-ulbricht-spende.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Weist 300 BTC Spende an Ross Ulbricht auf korruptes ETH ICO?","twitter_description":"Ist die Spende an Ross Ulbricht von 300 BTC an korrupte Aktivit\u00e4ten von FBI-Agenten beim Ethereum ICO gekn\u00fcpft?","twitter_image":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/06\/05123354\/1749123233-ulbricht-spende.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/de\/news\/spende-an-ross-ulbricht-von-300-btc-an-korruption-beim-ethereum-ico-geknupft\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/de\/news\/spende-an-ross-ulbricht-von-300-btc-an-korruption-beim-ethereum-ico-geknupft\/"},"author":{"name":"michaelsprick","@id":"https:\/\/cryptonews.com\/de\/#\/schema\/person\/1f02092f94b5d7bbf1e366211a4c071e"},"headline":"Spende an Ross Ulbricht von 300 BTC an Korruption beim Ethereum ICO gekn\u00fcpft?","datePublished":"2025-06-05T11:39:17+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/de\/news\/spende-an-ross-ulbricht-von-300-btc-an-korruption-beim-ethereum-ico-geknupft\/"},"wordCount":610,"publisher":{"@id":"https:\/\/cryptonews.com\/de\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/de\/news\/spende-an-ross-ulbricht-von-300-btc-an-korruption-beim-ethereum-ico-geknupft\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/06\/05123354\/1749123233-ulbricht-spende.jpg","keywords":["Bitcoin"],"articleSection":["Bitcoin News","News"],"inLanguage":"de","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/de\/news\/spende-an-ross-ulbricht-von-300-btc-an-korruption-beim-ethereum-ico-geknupft\/","url":"https:\/\/cryptonews.com\/de\/news\/spende-an-ross-ulbricht-von-300-btc-an-korruption-beim-ethereum-ico-geknupft\/","name":"Weist 300 BTC Spende an Ross Ulbricht auf korruptes ETH ICO?","isPartOf":{"@id":"https:\/\/cryptonews.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/de\/news\/spende-an-ross-ulbricht-von-300-btc-an-korruption-beim-ethereum-ico-geknupft\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/de\/news\/spende-an-ross-ulbricht-von-300-btc-an-korruption-beim-ethereum-ico-geknupft\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/06\/05123354\/1749123233-ulbricht-spende.jpg","datePublished":"2025-06-05T11:39:17+00:00","description":"Ist die Spende an Ross Ulbricht von 300 BTC an korrupte Aktivit\u00e4ten von FBI-Agenten beim Ethereum ICO gekn\u00fcpft?","breadcrumb":{"@id":"https:\/\/cryptonews.com\/de\/news\/spende-an-ross-ulbricht-von-300-btc-an-korruption-beim-ethereum-ico-geknupft\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/de\/news\/spende-an-ross-ulbricht-von-300-btc-an-korruption-beim-ethereum-ico-geknupft\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cryptonews.com\/de\/news\/spende-an-ross-ulbricht-von-300-btc-an-korruption-beim-ethereum-ico-geknupft\/#primaryimage","url":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/06\/05123354\/1749123233-ulbricht-spende.jpg","contentUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/2\/2025\/06\/05123354\/1749123233-ulbricht-spende.jpg","width":1456,"height":816},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/de\/news\/spende-an-ross-ulbricht-von-300-btc-an-korruption-beim-ethereum-ico-geknupft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/de\/"},{"@type":"ListItem","position":2,"name":"Spende an Ross Ulbricht von 300 BTC an Korruption beim Ethereum ICO gekn\u00fcpft?"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/de\/#website","url":"https:\/\/cryptonews.com\/de\/","name":"Cryptonews","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/de\/#organization","name":"Cryptonews","url":"https:\/\/cryptonews.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/cryptonews.com\/de\/#\/schema\/logo\/image\/","url":"","contentUrl":"","caption":"Cryptonews"},"image":{"@id":"https:\/\/cryptonews.com\/de\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/posts\/166756","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/users\/650"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/comments?post=166756"}],"version-history":[{"count":1,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/posts\/166756\/revisions"}],"predecessor-version":[{"id":166759,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/posts\/166756\/revisions\/166759"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/media\/166758"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/media?parent=166756"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/categories?post=166756"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/tags?post=166756"},{"taxonomy":"editors","embeddable":true,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/editors?post=166756"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/de\/wp-json\/wp\/v2\/sponsored_companies?post=166756"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}