{"id":96300,"date":"2022-11-29T08:42:00","date_gmt":"2022-11-29T08:42:00","guid":{"rendered":"https:\/\/pt.cryptonews.com\/?p=96300"},"modified":"2025-06-18T11:21:46","modified_gmt":"2025-06-18T11:21:46","slug":"previsao-de-preco-dogecoin-pode-chegar-a-1-ussd-em-2023","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/br\/noticias\/previsao-de-preco-dogecoin-pode-chegar-a-1-ussd-em-2023\/","title":{"rendered":"Previs\u00e3o de pre\u00e7o do Dogecoin &#8211; DOGE sobe 13%, pode chegar a US$ 1 em 2023?"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" class=\"content-img\" src=\"https:\/\/cimg.co\/news\/96117\/239455\/dogecoin.jpg\" alt=\"\" width=\"1026\"><\/figure><p>A <a href=\"https:\/\/cryptonews.com\/br\/noticias\/previsao-de-preco-de-dogecoin-enquanto-o-doge-ve-um-volume-de-negociacao-de-usdollar-900-milhoes-chegando\/\" target=\"_blank\" rel=\"noopener noreferrer\">previs\u00e3o de pre\u00e7o do Dogecoin<\/a> \u00e9 positiva, tendo em vista que a cripto subiu mais de US$ 0,0870 e agora est\u00e1 sendo negociado a US$ 0,0910. Por outro lado, o Dogecoin est\u00e1 lutando abaixo do n\u00edvel de resist\u00eancia de US$ 0,0965, que \u00e9 estendido por um n\u00edvel de retra\u00e7\u00e3o de Fibonacci de 38,2% e um n\u00edvel de resist\u00eancia superior duplo.<\/p><p>Vamos dar uma olhada nos fundamentos e previs\u00f5es t\u00e9cnicas do mercado para o Dogecoin.<\/p><h2><strong>Elon Musk pode lan\u00e7ar um smartphone<\/strong><\/h2><p><span class=\"replacer\"><\/span><br>\nEm 26 de novembro, Elon Musk respondeu a um tweet da podcaster Liz Wheeler, que estava preocupada com o fato de o Twitter ser barrado nas lojas onde os dois fabricantes de sistemas operacionais para smartphones vendem aplicativos usando software iOS e Android sob a nova pol\u00edtica de Elon.<\/p><figure class=\"media\"><\/figure><p>Em um tweet, Musk expressou sua preocupa\u00e7\u00e3o de que isso n\u00e3o aconte\u00e7a. Se ele estiver errado, ele prometeu construir seu pr\u00f3prio telefone.<\/p><figure class=\"media\"><\/figure><p>Um novo sistema operacional e uma loja de aplicativos online tamb\u00e9m podem ser inclu\u00eddos<\/p><figure class=\"media\"><\/figure><p>DOGE\/USD subiu dramaticamente desde que Elon Musk, o rec\u00e9m-nomeado CEO do Twitter, anunciou que, se a empresa encontrar dificuldades nas principais lojas de aplicativos m\u00f3veis, ele lan\u00e7ar\u00e1 seu smartphone.<\/p><h2><strong>Especula\u00e7\u00f5es da integra\u00e7\u00e3o do Dogecoin com o Twitter<\/strong><\/h2><p><span class=\"replacer\"><\/span><br>\nO Dogecoin (DOGE) continua a ocupar o centro do palco enquanto Elon Musk, tamb\u00e9m conhecido como &#8220;The Dogefather&#8221;, transforma o Twitter. Desde que Musk adquiriu o Twitter, em 27 de outubro de 2022, o valor de mercado da principal meme coin mais do que dobrou, passando de US$ 10,6 bilh\u00f5es para incr\u00edveis US$ 21,77 bilh\u00f5es em 1\u00ba de novembro de 2022.<\/p><p>Al\u00e9m disso, com 396 milh\u00f5es de usu\u00e1rios em todo o mundo, o DOGE \u00e9 a segunda maior criptomoeda Proof-of-Work (PoW), depois do Bitcoin. Musk elogiou o Dogecoin como a &#8220;criptomoeda do povo&#8221; e at\u00e9 brincou que o Dogecoin poderia ser usado para pagar suas pesquisas online. Nesse cen\u00e1rio, os usu\u00e1rios do Twitter poder\u00e3o recompensar os criadores com criptomoedas populares, como Dogecoin (DOGE).<\/p><figure class=\"media\"><\/figure><p>Musk confirmou no Twitter Spaces, acrescentando &#8220;Dogecoin para a lua!&#8221; antes de confirmar seu apoio a cripto com seus movimentos de dan\u00e7a, sua marca registrada.<\/p><p>Al\u00e9m disso, a ado\u00e7\u00e3o do Dogecoin como m\u00e9todo de pagamento padr\u00e3o no Twitter pode quebrar o gelo para a ado\u00e7\u00e3o de criptomoedas. A not\u00edcia de que o Twitter pode, em breve, integrar o Dogecoin impulsionou o pre\u00e7o DOGE\/USD.<\/p><h2><strong>Mudan\u00e7a para Proof of Stake<\/strong><\/h2><p><span class=\"replacer\"><\/span><br>\nDavid Gokhshtein, fundador da Gokhshtein Media e podcaster de criptomoedas, acredita que o cofundador da Ethereum e CEO do Twitter, Elon Musk, vai colaborar para atualizar o Dogecoin.<\/p><figure class=\"media\"><\/figure><p>Gokhshtein twittou, em 25 de novembro, que esperava que Musk e Buterin trabalhassem juntos no Dogecoin. Ele assumiu isso porque o cofundador do Ethereum havia sugerido anteriormente em seus coment\u00e1rios que a meme coin original deveria usar o mecanismo de consenso proof-of-stake.<\/p><p>Musk j\u00e1 trabalhou duro para tornar o DOGE mais poderoso.<br>\nVitalik tem autoridade legal para aprovar tais solicita\u00e7\u00f5es. \u00c9 membro da Funda\u00e7\u00e3o Dogecoin, bem como observador e cocriador do Ethereum.<\/p><figure class=\"media\"><\/figure><p>Al\u00e9m disso, a mudan\u00e7a para PoS \u00e9 mencionada no roadmap do Dogecoin.<br>\nTal mudan\u00e7a pode aumentar o apelo do Dogecoin, especialmente entre os usu\u00e1rios de criptomoedas preocupados com o meio ambiente. Isso pode ter um impacto positivo no pre\u00e7o DOGE\/USD.<\/p><h2><strong>Pre\u00e7o do Dogecoin e Tokenomics<\/strong><\/h2><p><span class=\"replacer\"><\/span><br>\nO pre\u00e7o atual do Dogecoin \u00e9 de US$ 0,0919, com um volume de negocia\u00e7\u00e3o de 24 horas de US$ 971 milh\u00f5es. O Dogecoin aumentou mais de 4% nas \u00faltimas 24 horas e, atualmente, ocupa a 8\u00aa posi\u00e7\u00e3o no CoinMarketCap, com um valor de mercado ao vivo de US$ 12 bilh\u00f5es. A oferta circulante \u00e9 de 132.670.764.300 tokens DOGE.<\/p><p>No s\u00e1bado, o DOGE\/USD abriu o dia em US$ 0,0894 e subiu para uma alta de US$ 0,09539 e uma baixa de US$ 0,0890.<\/p><figure class=\"image\"><img decoding=\"async\" class=\"content-img lazyload\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" width=\"846\" data-src=\"https:\/\/cimg.co\/news\/96117\/239453\/dogecoin-cmc.jpg\" data-srcset=\"\"><figcaption><strong>Pree\u00e7os e tokenomics do Dogecoin &#8211; Fonte: Coinmarketcap<\/strong><\/figcaption><\/figure><p>O DOGE\/USD completou uma retra\u00e7\u00e3o de Fibonacci de 38,2% em US$ 0,096 no gr\u00e1fico de 4 horas. Ao mesmo tempo, o padr\u00e3o de topo duplo est\u00e1 estendendo a resist\u00eancia ao Dogecoin, e as velas fechando abaixo desse n\u00edvel provavelmente causar\u00e3o uma corre\u00e7\u00e3o de baixa.<\/p><p>No lado negativo, o suporte imediato para DOGE \u00e9 de US$ 0,087, e uma quebra abaixo disso pode expor o pre\u00e7o a US$ 0,0800 ou US$ 0,0717.<\/p><figure class=\"image\"><img decoding=\"async\" class=\"content-img lazyload\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" width=\"1511\" data-src=\"https:\/\/cimg.co\/news\/96117\/239454\/dogecoin.jpg\" data-srcset=\"\"><figcaption><strong>Gr\u00e1fico de pre\u00e7os do Dogecoin  &#8211; Fonte: Tradingview<\/strong><\/figcaption><\/figure><p>Desde ent\u00e3o, os principais indicadores t\u00e9cnicos, como o \u00edndice de for\u00e7a relativa (RSI) e a diverg\u00eancia de converg\u00eancia da m\u00e9dia m\u00f3vel (MACD), permaneceram em uma zona de compra, indicando a possibilidade de continua\u00e7\u00e3o da tend\u00eancia de alta.<\/p><p>Al\u00e9m disso, a m\u00e9dia m\u00f3vel de 50 dias mant\u00e9m o DOGE em alta acima de US$ 0,0800. Portanto, o aumento da demanda por DOGE poderia cortar o n\u00edvel de resist\u00eancia de US$ 0,0965, expondo o DOGE aos n\u00edveis de US$ 0,1040 ou 0,1115 que foram estendidos em 50% e 61,8% de retra\u00e7\u00e3o de Fibonacci, respectivamente.<\/p><p>Fique de olho no n\u00edvel de US$ 0,0965, pois ele determinar\u00e1 o movimento futuro dos pre\u00e7os do Dogecoin.<\/p><h2><strong>Alternativas ao Dogecoin<\/strong><\/h2><p><span class=\"replacer\"><\/span><\/p><h3><strong>Dash 2 Trade <\/strong><\/h3><p>Dash 2 Trade, uma plataforma para intelig\u00eancia e sinais de negocia\u00e7\u00e3o cripto, despertou o interesse dos investidores depois de levantar US$ 7 milh\u00f5es em pouco mais de um m\u00eas. Como resultado, a equipe D2T decidiu desistir no est\u00e1gio 4 e reduzir a meta de hard cap para US$ 13,4 milh\u00f5es. A equipe decidiu reduzir o hard cap por dois motivos.<\/p><p>Para come\u00e7ar, o principal painel de an\u00e1lise de pr\u00e9-venda foi conclu\u00eddo antes do previsto, permitindo uma implanta\u00e7\u00e3o antecipada e a aloca\u00e7\u00e3o imediata de fundos de investimento de pr\u00e9-venda para esfor\u00e7os de marketing.<\/p><p>Em segundo lugar, e vinculado ao primeiro ponto, o mercado evoluiu, tornando os servi\u00e7os do Dash 2 Trade apropriados para investidores de varejo que procuram realizar extensa dilig\u00eancia ap\u00f3s o incidente da FTX.<\/p><p>O Dash 2 Trade tamb\u00e9m foi um sucesso, com duas exchanges (LBank e BitMart) prometendo listar o token D2T ap\u00f3s o fechamento da pr\u00e9-venda.<\/p><p><a href=\"https:\/\/cryptonews.com\/br\/ext\/dash-2-trade\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored nofollow\"><strong>Visite o Dash 2 Trade agora<\/strong><\/a><\/p><h3><strong>Calvaria (RIA)<\/strong><\/h3><p>O <a href=\"https:\/\/cryptonews.com\/br\/ext\/calvaria\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored nofollow\">Calvaria <\/a>\u00e9 um novo projeto de jogos de Bitcoin com potencial para dominar o mercado de jogos para ganhar (P2E). A demanda por criptomoedas para jogar provou ser um obst\u00e1culo substancial para a aceita\u00e7\u00e3o generalizada de jogos Web3, de acordo com os desenvolvedores do Calvaria (RIA). Como resultado, o jogo oferecer\u00e1 op\u00e7\u00f5es free-to-play e pay-to-win, com a variante free-to-play dispon\u00edvel para jogadores sem Bitcoin.<\/p><p>Desde a sua cria\u00e7\u00e3o, a pr\u00e9-venda arrecadou, aproximadamente, US$ 2 milh\u00f5es e agora est\u00e1 em suas fases finais, depois que os desenvolvedores decidiram termin\u00e1-la mais cedo. A pr\u00e9-venda deveria ter dez fases e oferecer 300 milh\u00f5es de tokens RIA.<\/p><p>No entanto, os criadores decidiram revisar a oferta de pr\u00e9-venda, o que implica que o est\u00e1gio 5 ser\u00e1 a \u00faltima oportunidade para os investidores comprarem RIA antes de serem lan\u00e7ados no mercado p\u00fablico, momento em que os pre\u00e7os devem aumentar.<\/p><p><a href=\"https:\/\/cryptonews.com\/br\/ext\/calvaria\/\" target=\"_blank\" rel=\"noopener noreferrer sponsored nofollow\"><strong>Visite a pr\u00e9-venda do Calvaria agora<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>A previs\u00e3o de pre\u00e7o do Dogecoin \u00e9 positiva, tendo em vista que a cripto subiu mais de US$ 0,0870 e agora est\u00e1 sendo negociado a US$ 0,0910. Por outro lado, o Dogecoin est\u00e1 lutando abaixo do n\u00edvel de resist\u00eancia de US$ 0,0965, que \u00e9 estendido por um n\u00edvel de retra\u00e7\u00e3o de Fibonacci de 38,2% e [&hellip;]<\/p>\n","protected":false},"author":109,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,8],"tags":[911,930],"editores":[51],"sponsored_companies":[],"class_list":["post-96300","post","type-post","status-publish","format-standard","hentry","category-noticias","category-altcoin-news","tag-d2t","tag-ria","editores-killian-a"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Previs\u00e3o de pre\u00e7o do Dogecoin: DOGE sobe 13%; chega a US$ 1 em 2023?<\/title>\n<meta name=\"description\" content=\"Veja como est\u00e1 a previs\u00e3o de pre\u00e7o do Dogecoin e moedas alternativas que apostamos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/br\/noticias\/previsao-de-preco-dogecoin-pode-chegar-a-1-ussd-em-2023\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Previs\u00e3o de pre\u00e7o do Dogecoin: DOGE sobe 13%; chega a US$ 1 em 2023?\" \/>\n<meta property=\"og:description\" content=\"Veja como est\u00e1 a previs\u00e3o de pre\u00e7o do Dogecoin e moedas alternativas que apostamos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/br\/noticias\/previsao-de-preco-dogecoin-pode-chegar-a-1-ussd-em-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"CryptoNews Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2022-11-29T08:42:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-06-18T11:21:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/96117\/239455\/dogecoin.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Previs\u00e3o de pre\u00e7o do Dogecoin: DOGE sobe 13%; chega a US$ 1 em 2023?\" \/>\n<meta name=\"twitter:description\" content=\"Veja como est\u00e1 a previs\u00e3o de pre\u00e7o do Dogecoin e moedas alternativas que apostamos.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/96117\/239453\/dogecoin-cmc.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Previs\u00e3o de pre\u00e7o do Dogecoin: DOGE sobe 13%; chega a US$ 1 em 2023?","description":"Veja como est\u00e1 a previs\u00e3o de pre\u00e7o do Dogecoin e moedas alternativas que apostamos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/br\/noticias\/previsao-de-preco-dogecoin-pode-chegar-a-1-ussd-em-2023\/","og_locale":"pt_BR","og_type":"article","og_title":"Previs\u00e3o de pre\u00e7o do Dogecoin: DOGE sobe 13%; chega a US$ 1 em 2023?","og_description":"Veja como est\u00e1 a previs\u00e3o de pre\u00e7o do Dogecoin e moedas alternativas que apostamos.","og_url":"https:\/\/cryptonews.com\/br\/noticias\/previsao-de-preco-dogecoin-pode-chegar-a-1-ussd-em-2023\/","og_site_name":"CryptoNews Brasil","article_published_time":"2022-11-29T08:42:00+00:00","article_modified_time":"2025-06-18T11:21:46+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/96117\/239455\/dogecoin.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Previs\u00e3o de pre\u00e7o do Dogecoin: DOGE sobe 13%; chega a US$ 1 em 2023?","twitter_description":"Veja como est\u00e1 a previs\u00e3o de pre\u00e7o do Dogecoin e moedas alternativas que apostamos.","twitter_image":"https:\/\/cimg.co\/news\/96117\/239453\/dogecoin-cmc.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/br\/noticias\/previsao-de-preco-dogecoin-pode-chegar-a-1-ussd-em-2023\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/previsao-de-preco-dogecoin-pode-chegar-a-1-ussd-em-2023\/"},"author":{"name":"killianbrcvmr","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/person\/89b6c7535aa9d37c1a32aff060ae6bcf"},"headline":"Previs\u00e3o de pre\u00e7o do Dogecoin &#8211; DOGE sobe 13%, pode chegar a US$ 1 em 2023?","datePublished":"2022-11-29T08:42:00+00:00","dateModified":"2025-06-18T11:21:46+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/previsao-de-preco-dogecoin-pode-chegar-a-1-ussd-em-2023\/"},"wordCount":1219,"publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/previsao-de-preco-dogecoin-pode-chegar-a-1-ussd-em-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/96117\/239455\/dogecoin.jpg","keywords":["D2T","RIA"],"articleSection":["Noticias","Not\u00edcias de Altcoin"],"inLanguage":"pt-BR","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/br\/noticias\/previsao-de-preco-dogecoin-pode-chegar-a-1-ussd-em-2023\/","url":"https:\/\/cryptonews.com\/br\/noticias\/previsao-de-preco-dogecoin-pode-chegar-a-1-ussd-em-2023\/","name":"Previs\u00e3o de pre\u00e7o do Dogecoin: DOGE sobe 13%; chega a US$ 1 em 2023?","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/previsao-de-preco-dogecoin-pode-chegar-a-1-ussd-em-2023\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/previsao-de-preco-dogecoin-pode-chegar-a-1-ussd-em-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/96117\/239455\/dogecoin.jpg","datePublished":"2022-11-29T08:42:00+00:00","dateModified":"2025-06-18T11:21:46+00:00","description":"Veja como est\u00e1 a previs\u00e3o de pre\u00e7o do Dogecoin e moedas alternativas que apostamos.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/previsao-de-preco-dogecoin-pode-chegar-a-1-ussd-em-2023\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/br\/noticias\/previsao-de-preco-dogecoin-pode-chegar-a-1-ussd-em-2023\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/noticias\/previsao-de-preco-dogecoin-pode-chegar-a-1-ussd-em-2023\/#primaryimage","url":"https:\/\/cimg.co\/news\/96117\/239455\/dogecoin.jpg","contentUrl":"https:\/\/cimg.co\/news\/96117\/239455\/dogecoin.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/br\/noticias\/previsao-de-preco-dogecoin-pode-chegar-a-1-ussd-em-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/br\/"},{"@type":"ListItem","position":2,"name":"Previs\u00e3o de pre\u00e7o do Dogecoin &#8211; DOGE sobe 13%, pode chegar a US$ 1 em 2023?"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/br\/#website","url":"https:\/\/cryptonews.com\/br\/","name":"Cryptonews Portugal","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/br\/#organization","name":"Cryptonews Portugal","url":"https:\/\/cryptonews.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews Portugal"},"image":{"@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/96300","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/users\/109"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/comments?post=96300"}],"version-history":[{"count":3,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/96300\/revisions"}],"predecessor-version":[{"id":149078,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/96300\/revisions\/149078"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/media?parent=96300"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/categories?post=96300"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/tags?post=96300"},{"taxonomy":"editores","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/editores?post=96300"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/sponsored_companies?post=96300"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}