{"id":92351,"date":"2022-10-27T12:53:00","date_gmt":"2022-10-27T12:53:00","guid":{"rendered":"https:\/\/pt.cryptonews.com\/?p=92351"},"modified":"2022-11-07T11:06:47","modified_gmt":"2022-11-07T11:06:47","slug":"3-razoes-pelas-quais-o-preco-do-axie-infinity-esta-condenado-e-o-calvaria-segue-bombando-durante-a-pre-venda","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/br\/noticias\/3-razoes-pelas-quais-o-preco-do-axie-infinity-esta-condenado-e-o-calvaria-segue-bombando-durante-a-pre-venda\/","title":{"rendered":"3 raz\u00f5es pelas quais o pre\u00e7o do Axie Infinity est\u00e1 condenado e o Calvaria segue bombando durante a pr\u00e9-venda"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/92126\/230737\/3-reasons-axie-infinity-price-is-doomed-and-calvaria-is-pumping-during-presale.jpeg\" alt=\"\" srcset=\"https:\/\/cimg.co\/news\/92126\/230737\/responsive-images\/3-reasons-axie-infinity-price-is-doomed-and-calvaria-is-pumping-during-presale___media_library_original_3256_1800.jpeg 3256w, https:\/\/cimg.co\/news\/92126\/230737\/responsive-images\/3-reasons-axie-infinity-price-is-doomed-and-calvaria-is-pumping-during-presale___media_library_original_1200_663.jpeg 1200w, https:\/\/cimg.co\/news\/92126\/230737\/responsive-images\/3-reasons-axie-infinity-price-is-doomed-and-calvaria-is-pumping-during-presale___media_library_original_900_497.jpeg 900w, https:\/\/cimg.co\/news\/92126\/230737\/responsive-images\/3-reasons-axie-infinity-price-is-doomed-and-calvaria-is-pumping-during-presale___media_library_original_720_398.jpeg 720w, https:\/\/cimg.co\/news\/92126\/230737\/responsive-images\/3-reasons-axie-infinity-price-is-doomed-and-calvaria-is-pumping-during-presale___media_library_original_600_331.jpeg 600w, https:\/\/cimg.co\/news\/92126\/230737\/responsive-images\/3-reasons-axie-infinity-price-is-doomed-and-calvaria-is-pumping-during-presale___media_library_original_300_165.jpeg 300w\" sizes=\"100vw\" width=\"3256\" class=\"content-img\"><\/figure><p class=\"wp-block-paragraph\"><i>Aviso: A se&ccedil;&atilde;o Conversa de Mercado apresenta insights de analistas e traders da ind&uacute;stria cripto e n&atilde;o faz parte do conte&uacute;do editorial do Cryptonews.com.<\/i><\/p><p>O pre&ccedil;o do Axie Infinity aumentou cerca de 4% nas &uacute;ltimas 24 horas, subindo para US$ 8,99. No entanto, com os seus usu&aacute;rios ativos permanecendo comparativamente baixos e o mercado de criptomoedas ainda estagnado, seu pre&ccedil;o tamb&eacute;m caiu 20% em uma semana e 30% em um m&ecirc;s.<\/p><p>No ano passado, o token AXS estava em alta, com a altcoin atingindo um recorde hist&oacute;rico de US$ 164,90, em 6 de novembro. Desde ent&atilde;o, <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/docs.google.com\/spreadsheets\/d\/1g4d2lzBytC-Wo4_rKGHjR3vGeJHb8hd1jb55qRf_S2g\/edit#gid=0\">sofreu um decl&iacute;nio constante a longo prazo, com seus usu&aacute;rios ativos di&aacute;rios caindo de 2,7 milh&otilde;es<\/a>, em meados de novembro, para 250.000 no in&iacute;cio de agosto deste ano.<\/p><p>Felizmente, os comerciantes que procuram por novas plataformas de jogos para investir n&atilde;o precisam ir muito longe. O <a target=\"_blank\" rel=\"noopener noreferrer sponsored nofollow\" href=\"https:\/\/cryptonews.com\/br\/ext\/calvaria\/\">Calvaria: Duels of Eternity<\/a>, lan&ccedil;ou recentemente a sua pr&eacute;-venda. Este projeto visa ter sucesso onde o Axie Infinity falhou, al&eacute;m disso, o jogo tamb&eacute;m suporta uma vers&atilde;o free-to-play que n&atilde;o exige que os usu&aacute;rios tenham cripto para participar.<\/p><h2>3 raz&otilde;es pelas quais o pre&ccedil;o do Axie Infinity est&aacute; condenado<\/h2><span class=\"replacer\"><\/span><p>O gr&aacute;fico do AXS n&atilde;o mostra um quadro bonito. O seu &iacute;ndice de for&ccedil;a relativa est&aacute; abaixo de 50, desde meados de agosto, e acima de 50 h&aacute; apenas algumas semanas (entre meados de julho e meados de agosto) desde o in&iacute;cio de abril.<\/p><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" sizes=\"100vw\" width=\"3772\" class=\"content-img lazyload\" data-src=\"https:\/\/cimg.co\/news\/92126\/230722\/axie-infinity-axs-price-chart-3-reasons-axie-infinity-price-is-doomed.jpg\" data-srcset=\"https:\/\/cimg.co\/news\/92126\/230722\/responsive-images\/axie-infinity-axs-price-chart-3-reasons-axie-infinity-price-is-doomed___media_library_original_3772_2236.jpg 3772w, https:\/\/cimg.co\/news\/92126\/230722\/responsive-images\/axie-infinity-axs-price-chart-3-reasons-axie-infinity-price-is-doomed___media_library_original_1200_711.jpg 1200w, https:\/\/cimg.co\/news\/92126\/230722\/responsive-images\/axie-infinity-axs-price-chart-3-reasons-axie-infinity-price-is-doomed___media_library_original_900_533.jpg 900w, https:\/\/cimg.co\/news\/92126\/230722\/responsive-images\/axie-infinity-axs-price-chart-3-reasons-axie-infinity-price-is-doomed___media_library_original_720_426.jpg 720w, https:\/\/cimg.co\/news\/92126\/230722\/responsive-images\/axie-infinity-axs-price-chart-3-reasons-axie-infinity-price-is-doomed___media_library_original_600_355.jpg 600w, https:\/\/cimg.co\/news\/92126\/230722\/responsive-images\/axie-infinity-axs-price-chart-3-reasons-axie-infinity-price-is-doomed___media_library_original_300_177.jpg 300w\"><\/figure><p>Isso sugere uma s&eacute;ria desacelera&ccedil;&atilde;o, assim como a m&eacute;dia m&oacute;vel de 30 dias da moeda. Este &uacute;ltimo ficou abaixo da m&eacute;dia de 200 dias do AXS, desde o m&ecirc;s de janeiro, desafiando as expectativas puramente gr&aacute;ficas de que deve haver uma recupera&ccedil;&atilde;o em breve.<\/p><p>N&atilde;o s&atilde;o apenas os indicadores do AXS que parecem sombrios. Como mencionado acima, o Axie Infinity tem lutado para recuperar os usu&aacute;rios ativos di&aacute;rios que perdeu desde novembro passado.<\/p><p>Ao longo do ano passado, seu desenvolvedor Sky Mavis lan&ccedil;ou v&aacute;rias atualiza&ccedil;&otilde;es na esperan&ccedil;a de ressuscitar a sua base de usu&aacute;rios. No entanto, desde as principais<a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/axie.substack.com\/p\/axieorigin\"> atualiza&ccedil;&otilde;es do sistema<\/a> at&eacute; os <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/venturebeat.com\/games\/sky-mavis-launches-new-features-and-products-for-axie-infinity-fans\/\">novos recursos<\/a>, eles n&atilde;o foram atendidos com um aumento no n&uacute;mero de usu&aacute;rios do jogo ou no pre&ccedil;o do AXS.<br><br>Como tal, &eacute; dif&iacute;cil ver o que mais Sky Mavis pode fazer para restaurar o Axie Infinity &agrave;s suas alturas anteriores. Parece que os jogadores perderam o interesse no jogo, algo que foi exacerbado pelo mercado em baixa, reduzindo o valor das recompensas que recebem por jog&aacute;-lo.<br>&nbsp;<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/MessariCrypto\/status\/1564583742110216192\"><\/oembed><\/figure><p>Em terceiro lugar, vale ressaltar que o Axie Infinity tamb&eacute;m n&atilde;o se recuperou do grande hack sofrido por sua ponte Ronin em mar&ccedil;o. Essa explora&ccedil;&atilde;o resultou no roubo de Ethereum e USDC, no valor de cerca de US$ 540 milh&otilde;es na &eacute;poca, e seu principal efeito foi minar a confian&ccedil;a no Axie Infinity.<\/p><p>Embora a equipe do <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/cryptonews.com\/br\/noticias\/ronin-bridge-da-axie-infinity-sera-reaberta-apos-hack-fundos-bloqueados-serao-devolvidos\/\">Axie Infinity tenha atualizado o Ronin ap&oacute;s o hac<\/a>k, &eacute; prov&aacute;vel que a viola&ccedil;&atilde;o tenha prejudicado a confian&ccedil;a no Axie a longo prazo, algo que tamb&eacute;m ajudaria a explicar seu decl&iacute;nio cont&iacute;nuo no n&uacute;mero de usu&aacute;rios.<\/p><h2>Por que o Calvaria est&aacute; bombando durante a pr&eacute;-venda?<\/h2><span class=\"replacer\"><\/span><p>Voltando ao Calvaria, &eacute; poss&iacute;vel que o decl&iacute;nio do Axie Infinity tamb&eacute;m explique o aumento do interesse em t&iacute;tulos mais novos, com os investidores buscando crescimento em outros lugares do subsetor.<\/p><p>O Calvaria <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/twitter.com\/CalvariaP2E\/status\/1579382244711534592\">lan&ccedil;ou a sua pr&eacute;-venda no dia 10 de outubro<\/a>, disponibilizando seu token nativo RIA ao pre&ccedil;o de 0,01 USDT. At&eacute; agora, vendeu cerca de 7.558.482 RIA de um total de 30 milh&otilde;es, embora esse total se aplique apenas &agrave; atual primeira etapa da venda, com etapas subsequentes, durante as quais o pre&ccedil;o do token RIA vai aumentar.<\/p><p><br>Dispon&iacute;vel em lojas de aplicativos para PC e dispositivos m&oacute;veis, o Calvaria difere um pouco de outros jogos play-to-ganhar baseados em blockchain, pois os jogadores n&atilde;o precisam de criptomoedas para jog&aacute;-lo. Isso o torna um ponto de entrada ideal para iniciantes em criptografia e P2E, especialmente para aqueles que de outra forma seriam desligados pela necessidade de ter uma carteira e conect&aacute;-la &agrave; plataforma do jogo.<\/p><p>O Calvaria possui as vers&otilde;es Free-to-Play e Play-to-Earn. De qualquer forma, &eacute; ambientado na vida ap&oacute;s a morte, onde os jogadores podem ganhar e atualizar cartas colecion&aacute;veis &#8203;&#8203;usadas para lutar com diferentes fac&ccedil;&otilde;es no universo do jogo.<br>&nbsp;<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/CalvariaP2E\/status\/1573462221799161861\"><\/oembed><\/figure><p>Esses cart&otilde;es s&atilde;o representados como NFTs, assim como outros itens e ativos do jogo, enquanto os jogadores tamb&eacute;m podem apostar o token RIA nativo para ganhar recompensas. Outras caracter&iacute;sticas incluem os mini-jogos e um sistema de bolsas de estudo.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/CalvariaP2E\/status\/1572360203697197056\"><\/oembed><\/figure><p>De acordo com o roteiro do Calvaria, a vers&atilde;o alfa do jogo est&aacute; programada para ser lan&ccedil;ada no primeiro trimestre do pr&oacute;ximo ano, com lan&ccedil;amento completo no trimestre seguinte. Seu token RIA tem uma oferta m&aacute;xima total de um bilh&atilde;o, com 38% disso dedicado &agrave; pr&eacute;-venda em andamento (essa &eacute; a maior participa&ccedil;&atilde;o).<\/p><p>Portanto, o Calvaria parece que est&aacute; se tornando uma adi&ccedil;&atilde;o emocionante ao ecossistema de jogos blockchain, que provavelmente precisa de um novo campe&atilde;o agora que o Axie Infinity continua diminuindo.<br><br><a target=\"_blank\" rel=\"noopener noreferrer sponsored nofollow\" href=\"https:\/\/cryptonews.com\/br\/ext\/calvaria\/\"><strong>Visite o Calvaria agora<\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Aviso: A se&ccedil;&atilde;o Conversa de Mercado apresenta insights de analistas e traders da ind&uacute;stria cripto e n&atilde;o faz parte do conte&uacute;do editorial do Cryptonews.com.O pre&ccedil;o do Axie Infinity aumentou cerca de 4% nas &uacute;ltimas 24 horas, subindo para US$ 8,99. No entanto, com os seus usu&aacute;rios ativos permanecendo comparativamente baixos e o mercado de criptomoedas [&hellip;]<\/p>\n","protected":false},"author":109,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[14,1],"tags":[930],"editores":[51],"sponsored_companies":[],"class_list":["post-92351","post","type-post","status-publish","format-standard","hentry","category-industry-talk","category-noticias","tag-ria","editores-killian-a"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>3 raz\u00f5es pelas quais o pre\u00e7o do Axie Infinity est\u00e1 condenado e o Calvaria segue bombando durante a pr\u00e9-venda<\/title>\n<meta name=\"description\" content=\"O pre\u00e7o do Axie Infinity aumentou 4% nas \u00faltimas 24 horas, apesar de ter diminu\u00eddo 30% no \u00faltimo m\u00eas. No entanto, enquanto continua estagnado, um novo jogo de play-to-earn surgiu para tomar seu lugar.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/br\/noticias\/3-razoes-pelas-quais-o-preco-do-axie-infinity-esta-condenado-e-o-calvaria-segue-bombando-durante-a-pre-venda\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"3 raz\u00f5es pelas quais o pre\u00e7o do Axie Infinity est\u00e1 condenado e o Calvaria segue bombando durante a pr\u00e9-venda\" \/>\n<meta property=\"og:description\" content=\"O pre\u00e7o do Axie Infinity aumentou 4% nas \u00faltimas 24 horas, apesar de ter diminu\u00eddo 30% no \u00faltimo m\u00eas. No entanto, enquanto continua estagnado, um novo jogo de play-to-earn surgiu para tomar seu lugar.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/br\/noticias\/3-razoes-pelas-quais-o-preco-do-axie-infinity-esta-condenado-e-o-calvaria-segue-bombando-durante-a-pre-venda\/\" \/>\n<meta property=\"og:site_name\" content=\"CryptoNews Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-27T12:53:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-07T11:06:47+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/92126\/230737\/3-reasons-axie-infinity-price-is-doomed-and-calvaria-is-pumping-during-presale.jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"3 raz\u00f5es pelas quais o pre\u00e7o do Axie Infinity est\u00e1 condenado e o Calvaria segue bombando durante a pr\u00e9-venda\" \/>\n<meta name=\"twitter:description\" content=\"O pre\u00e7o do Axie Infinity aumentou 4% nas \u00faltimas 24 horas, apesar de ter diminu\u00eddo 30% no \u00faltimo m\u00eas. No entanto, enquanto continua estagnado, um novo jogo de play-to-earn surgiu para tomar seu lugar.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/92126\/230722\/axie-infinity-axs-price-chart-3-reasons-axie-infinity-price-is-doomed.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"3 raz\u00f5es pelas quais o pre\u00e7o do Axie Infinity est\u00e1 condenado e o Calvaria segue bombando durante a pr\u00e9-venda","description":"O pre\u00e7o do Axie Infinity aumentou 4% nas \u00faltimas 24 horas, apesar de ter diminu\u00eddo 30% no \u00faltimo m\u00eas. No entanto, enquanto continua estagnado, um novo jogo de play-to-earn surgiu para tomar seu lugar.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/br\/noticias\/3-razoes-pelas-quais-o-preco-do-axie-infinity-esta-condenado-e-o-calvaria-segue-bombando-durante-a-pre-venda\/","og_locale":"pt_BR","og_type":"article","og_title":"3 raz\u00f5es pelas quais o pre\u00e7o do Axie Infinity est\u00e1 condenado e o Calvaria segue bombando durante a pr\u00e9-venda","og_description":"O pre\u00e7o do Axie Infinity aumentou 4% nas \u00faltimas 24 horas, apesar de ter diminu\u00eddo 30% no \u00faltimo m\u00eas. No entanto, enquanto continua estagnado, um novo jogo de play-to-earn surgiu para tomar seu lugar.","og_url":"https:\/\/cryptonews.com\/br\/noticias\/3-razoes-pelas-quais-o-preco-do-axie-infinity-esta-condenado-e-o-calvaria-segue-bombando-durante-a-pre-venda\/","og_site_name":"CryptoNews Brasil","article_published_time":"2022-10-27T12:53:00+00:00","article_modified_time":"2022-11-07T11:06:47+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/92126\/230737\/3-reasons-axie-infinity-price-is-doomed-and-calvaria-is-pumping-during-presale.jpeg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"3 raz\u00f5es pelas quais o pre\u00e7o do Axie Infinity est\u00e1 condenado e o Calvaria segue bombando durante a pr\u00e9-venda","twitter_description":"O pre\u00e7o do Axie Infinity aumentou 4% nas \u00faltimas 24 horas, apesar de ter diminu\u00eddo 30% no \u00faltimo m\u00eas. No entanto, enquanto continua estagnado, um novo jogo de play-to-earn surgiu para tomar seu lugar.","twitter_image":"https:\/\/cimg.co\/news\/92126\/230722\/axie-infinity-axs-price-chart-3-reasons-axie-infinity-price-is-doomed.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/br\/noticias\/3-razoes-pelas-quais-o-preco-do-axie-infinity-esta-condenado-e-o-calvaria-segue-bombando-durante-a-pre-venda\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/3-razoes-pelas-quais-o-preco-do-axie-infinity-esta-condenado-e-o-calvaria-segue-bombando-durante-a-pre-venda\/"},"author":{"name":"killianbrcvmr","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/person\/89b6c7535aa9d37c1a32aff060ae6bcf"},"headline":"3 raz\u00f5es pelas quais o pre\u00e7o do Axie Infinity est\u00e1 condenado e o Calvaria segue bombando durante a pr\u00e9-venda","datePublished":"2022-10-27T12:53:00+00:00","dateModified":"2022-11-07T11:06:47+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/3-razoes-pelas-quais-o-preco-do-axie-infinity-esta-condenado-e-o-calvaria-segue-bombando-durante-a-pre-venda\/"},"wordCount":1059,"publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/3-razoes-pelas-quais-o-preco-do-axie-infinity-esta-condenado-e-o-calvaria-segue-bombando-durante-a-pre-venda\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/92126\/230737\/3-reasons-axie-infinity-price-is-doomed-and-calvaria-is-pumping-during-presale.jpeg","keywords":["RIA"],"articleSection":["Conversas do Mercado","Noticias"],"inLanguage":"pt-BR","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/br\/noticias\/3-razoes-pelas-quais-o-preco-do-axie-infinity-esta-condenado-e-o-calvaria-segue-bombando-durante-a-pre-venda\/","url":"https:\/\/cryptonews.com\/br\/noticias\/3-razoes-pelas-quais-o-preco-do-axie-infinity-esta-condenado-e-o-calvaria-segue-bombando-durante-a-pre-venda\/","name":"3 raz\u00f5es pelas quais o pre\u00e7o do Axie Infinity est\u00e1 condenado e o Calvaria segue bombando durante a pr\u00e9-venda","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/3-razoes-pelas-quais-o-preco-do-axie-infinity-esta-condenado-e-o-calvaria-segue-bombando-durante-a-pre-venda\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/3-razoes-pelas-quais-o-preco-do-axie-infinity-esta-condenado-e-o-calvaria-segue-bombando-durante-a-pre-venda\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/92126\/230737\/3-reasons-axie-infinity-price-is-doomed-and-calvaria-is-pumping-during-presale.jpeg","datePublished":"2022-10-27T12:53:00+00:00","dateModified":"2022-11-07T11:06:47+00:00","description":"O pre\u00e7o do Axie Infinity aumentou 4% nas \u00faltimas 24 horas, apesar de ter diminu\u00eddo 30% no \u00faltimo m\u00eas. No entanto, enquanto continua estagnado, um novo jogo de play-to-earn surgiu para tomar seu lugar.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/3-razoes-pelas-quais-o-preco-do-axie-infinity-esta-condenado-e-o-calvaria-segue-bombando-durante-a-pre-venda\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/br\/noticias\/3-razoes-pelas-quais-o-preco-do-axie-infinity-esta-condenado-e-o-calvaria-segue-bombando-durante-a-pre-venda\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/noticias\/3-razoes-pelas-quais-o-preco-do-axie-infinity-esta-condenado-e-o-calvaria-segue-bombando-durante-a-pre-venda\/#primaryimage","url":"https:\/\/cimg.co\/news\/92126\/230737\/3-reasons-axie-infinity-price-is-doomed-and-calvaria-is-pumping-during-presale.jpeg","contentUrl":"https:\/\/cimg.co\/news\/92126\/230737\/3-reasons-axie-infinity-price-is-doomed-and-calvaria-is-pumping-during-presale.jpeg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/br\/noticias\/3-razoes-pelas-quais-o-preco-do-axie-infinity-esta-condenado-e-o-calvaria-segue-bombando-durante-a-pre-venda\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/br\/"},{"@type":"ListItem","position":2,"name":"3 raz\u00f5es pelas quais o pre\u00e7o do Axie Infinity est\u00e1 condenado e o Calvaria segue bombando durante a pr\u00e9-venda"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/br\/#website","url":"https:\/\/cryptonews.com\/br\/","name":"Cryptonews Portugal","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/br\/#organization","name":"Cryptonews Portugal","url":"https:\/\/cryptonews.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews Portugal"},"image":{"@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/92351","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/users\/109"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/comments?post=92351"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/92351\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/media?parent=92351"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/categories?post=92351"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/tags?post=92351"},{"taxonomy":"editores","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/editores?post=92351"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/sponsored_companies?post=92351"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}