{"id":92109,"date":"2022-10-25T08:08:00","date_gmt":"2022-10-25T08:08:00","guid":{"rendered":"https:\/\/pt.cryptonews.com\/?p=92109"},"modified":"2022-10-29T20:56:29","modified_gmt":"2022-10-29T20:56:29","slug":"voce-deve-investir-em-move-to-earn-m2e-ou-play-to-earn-p2e-calvaria-esta-tornando-a-escolha-muito-mais-facil","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/br\/noticias\/voce-deve-investir-em-move-to-earn-m2e-ou-play-to-earn-p2e-calvaria-esta-tornando-a-escolha-muito-mais-facil\/","title":{"rendered":"Voc\u00ea deve investir em move-to-earn (M2E) ou play-to-earn (P2E)? Calvaria est\u00e1 tornando a escolha muito mais f\u00e1cil"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/91563\/229100\/calvaria-hero-banner.jpg\" alt=\"\" srcset=\"https:\/\/cimg.co\/news\/91563\/229100\/responsive-images\/calvaria-hero-banner___media_library_original_1600_748.jpg 1600w, https:\/\/cimg.co\/news\/91563\/229100\/responsive-images\/calvaria-hero-banner___media_library_original_1200_561.jpg 1200w, https:\/\/cimg.co\/news\/91563\/229100\/responsive-images\/calvaria-hero-banner___media_library_original_900_420.jpg 900w, https:\/\/cimg.co\/news\/91563\/229100\/responsive-images\/calvaria-hero-banner___media_library_original_720_336.jpg 720w, https:\/\/cimg.co\/news\/91563\/229100\/responsive-images\/calvaria-hero-banner___media_library_original_600_280.jpg 600w, https:\/\/cimg.co\/news\/91563\/229100\/responsive-images\/calvaria-hero-banner___media_library_original_300_140.jpg 300w\" sizes=\"100vw\" width=\"1600\" class=\"content-img\"><\/p><p><i>Aviso: O texto abaixo &eacute; um artigo publicit&aacute;rio que n&atilde;o foi escrito por redatores do Cryptonews.com.<\/i><\/p><p>Os NFTs revolucionaram o mercado de criptomoedas, principalmente porque criaram novas maneiras de gera&ccedil;&atilde;o de receitas para os seus detentores. &Eacute; uma ideia nova que, compreensivelmente, conquistou o mundo inteiro, e cada vez mais marcas e empresas est&atilde;o entrando no espa&ccedil;o NFT.<\/p><p>Dois principais m&eacute;todos de obten&ccedil;&atilde;o de receita est&atilde;o nas manchetes deste ano: Play-to-Earn (P2E) e Move-to-Earn (M2E). Enquanto o &uacute;ltimo causou muita discuss&atilde;o, o P2E &eacute; o que mudou a maneira como todos n&oacute;s vemos os NFTs, especialmente com nomes como Calvaria.<\/p><h2>O P2E oferece enorme potencial enquanto o M2E trope&ccedil;a<\/h2><span class=\"replacer\"><\/span><p>O movimento M2E foi o assunto do mercado por um bom tempo, tudo gra&ccedil;as ao STEPN e ao seu modelo. No entanto, isso mudou muito, pois o projeto redefiniu as suas prioridades. Apesar de parecer que mudaria a maneira como os usu&aacute;rios de criptomoedas ganham dinheiro, o STEPN j&aacute; n&atilde;o &eacute; mais t&atilde;o popular quanto antes.<\/p><p>Em vez disso, o que se provou muito interessante &eacute; o modelo Play-to-earn (P2E). Um grande n&uacute;mero de projetos est&aacute; implementado ou j&aacute; lan&ccedil;ou recursos relacionados, recompensando os jogadores por algo que eles adoram fazer.<\/p><p>Ainda assim, h&aacute; uma pausa no espa&ccedil;o P2E, com a maioria dos projetos trabalhando com as mesmas ideias &#8211; exceto por um projeto not&aacute;vel, o <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/calvaria.io\/\"><u>Calvaria<\/u><\/a>. O jogo oferece muitos recursos que n&atilde;o existem em outros t&iacute;tulos P2E e essas caracter&iacute;sticas o tornam &uacute;nico no mercado.<\/p><h2>Calvaria &eacute; um jogo P2E especial<\/h2><span class=\"replacer\"><\/span><figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" sizes=\"100vw\" width=\"1234\" class=\"content-img lazyload\" data-src=\"https:\/\/cimg.co\/news\/91563\/229101\/calvaria-vs-other-p2e-games.jpg\" data-srcset=\"https:\/\/cimg.co\/news\/91563\/229101\/responsive-images\/calvaria-vs-other-p2e-games___media_library_original_1234_707.jpg 1234w, https:\/\/cimg.co\/news\/91563\/229101\/responsive-images\/calvaria-vs-other-p2e-games___media_library_original_1200_687.jpg 1200w, https:\/\/cimg.co\/news\/91563\/229101\/responsive-images\/calvaria-vs-other-p2e-games___media_library_original_900_515.jpg 900w, https:\/\/cimg.co\/news\/91563\/229101\/responsive-images\/calvaria-vs-other-p2e-games___media_library_original_720_412.jpg 720w, https:\/\/cimg.co\/news\/91563\/229101\/responsive-images\/calvaria-vs-other-p2e-games___media_library_original_600_343.jpg 600w, https:\/\/cimg.co\/news\/91563\/229101\/responsive-images\/calvaria-vs-other-p2e-games___media_library_original_300_171.jpg 300w\"><figcaption><i>O Calvaria oferece muitas op&ccedil;&otilde;es que outros jogos P2E n&atilde;o oferecem.<\/i><\/figcaption><\/figure><p>O Calvaria foi lan&ccedil;ado muito recentemente e &eacute; parecido com os outros jogos P2E, pois oferece cartas colecion&aacute;veis &#8203;&#8203;e a capacidade de batalhar com outros jogadores. Mas as semelhan&ccedil;as param por a&iacute;, pois o Calvaria possui in&uacute;meras outras caracter&iacute;sticas que s&atilde;o &uacute;nicas.<\/p><p>A acessibilidade &eacute; um grande diferencial do jogo e, para isso, est&aacute; dispon&iacute;vel nas lojas de aplicativos para PC e dispositivos m&oacute;veis. Os jogadores tamb&eacute;m n&atilde;o precisam de criptomoedas, de outros ativos digitais ou mesmo de uma carteira para come&ccedil;ar a jogar. Isso significa que quem tem pouca experi&ecirc;ncia com criptomoedas pode entrar facilmente no jogo.<\/p><p>Mas o aspecto chave do jogo que o torna acess&iacute;vel &eacute; o fato de que existem vers&otilde;es Free-to-Play e Play-to-Earn. Isso reduz a barreira de entrada e incentiva usu&aacute;rios n&atilde;o habituados a entrar no universo cripto. O que &eacute; ainda mais interessante &eacute; o fato de que a equipe tamb&eacute;m est&aacute; trabalhando em um jogo para o mercado de jogos que n&atilde;o s&atilde;o criptos. Isso deve ajudar a integrar alguns desses aprendizados e insights no jogo de cripto P2E Calvaria.<\/p><p>O jogo se passa na vida ap&oacute;s a morte e os jogadores ganham e atualizam suas cartas para ter sucesso no combate em um campo de batalha. Os personagens do universo pertencem a diferentes fac&ccedil;&otilde;es, todas com o seu pr&oacute;prio design visual &uacute;nico.<\/p><p>Os recursos mencionados acima incluem a capacidade de apostar o token RIA, um DAO para governan&ccedil;a orientada pela comunidade, uma loja no jogo para NFTs e outros ativos, minijogos e um sistema de bolsas de estudo.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/CalvariaP2E\/status\/1579382244711534592\"><\/oembed><\/figure><p>A <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/calvaria.io\/presale\/\">pr&eacute;-venda do Calvaria<\/a> est&aacute; em andamento, com os tokens RIA sendo oferecidos a um pre&ccedil;o de US$ 0,01 cada. Ou seja, 1 USDT resulta em investidores recebendo 100 tokens RIA. A primeira pr&eacute;-venda disponibiliza 30 milh&otilde;es de tokens RIA, com um total de 300 milh&otilde;es de tokens RIA dispon&iacute;veis em todas as pr&eacute;-vendas. A faixa de pre&ccedil;o do token RIA nas pr&eacute;-vendas varia de US$ 0,01 a US$ 0,325.<\/p><h2>O Calvaria est&aacute; removendo barreiras em jogos P2E<\/h2><span class=\"replacer\"><\/span><p>O espa&ccedil;o P2E est&aacute; provando que tem muito potencial, mas definitivamente h&aacute; uma necessidade de exclusividade quando se trata de ofertas. O Calvaria faz exatamente isso, fornecendo aos usu&aacute;rios muitos recursos ausentes em outros jogos P2E e tamb&eacute;m sendo acess&iacute;vel a usu&aacute;rios n&atilde;o habituados ao universo cripto. Saiba mais visitando o site do <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/calvaria.io\/\"><u>Calvaria<\/u><\/a> e lendo o <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/whitepaper.calvaria.io\/basic-provisions\/about-calvaria-duels-of-eternity\"><u>whitepaper<\/u><\/a> do projeto.<\/p><p><a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/calvaria.io\/presale\/\"><strong><u>Confira a pr&eacute;-venda do Calvaria<\/u><\/strong><\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Aviso: O texto abaixo &eacute; um artigo publicit&aacute;rio que n&atilde;o foi escrito por redatores do Cryptonews.com.Os NFTs revolucionaram o mercado de criptomoedas, principalmente porque criaram novas maneiras de gera&ccedil;&atilde;o de receitas para os seus detentores. &Eacute; uma ideia nova que, compreensivelmente, conquistou o mundo inteiro, e cada vez mais marcas e empresas est&atilde;o entrando no [&hellip;]<\/p>\n","protected":false},"author":109,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[11,1],"tags":[92,809],"editores":[],"sponsored_companies":[],"class_list":["post-92109","post","type-post","status-publish","format-standard","hentry","category-press-releases","category-noticias","tag-altcoins","tag-pre-venda"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Investir em M2E ou P2E? Calvaria est\u00e1 tornando a escolha mais f\u00e1cil<\/title>\n<meta name=\"description\" content=\"Saiba como jogos P2E como Calvaria est\u00e3o dominando o espa\u00e7o de jogos com NFT colecion\u00e1veis.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/br\/noticias\/voce-deve-investir-em-move-to-earn-m2e-ou-play-to-earn-p2e-calvaria-esta-tornando-a-escolha-muito-mais-facil\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Investir em M2E ou P2E? Calvaria est\u00e1 tornando a escolha mais f\u00e1cil\" \/>\n<meta property=\"og:description\" content=\"Saiba como jogos P2E como Calvaria est\u00e3o dominando o espa\u00e7o de jogos com NFT colecion\u00e1veis.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/br\/noticias\/voce-deve-investir-em-move-to-earn-m2e-ou-play-to-earn-p2e-calvaria-esta-tornando-a-escolha-muito-mais-facil\/\" \/>\n<meta property=\"og:site_name\" content=\"CryptoNews Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-25T08:08:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-29T20:56:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/91563\/229100\/calvaria-hero-banner.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Investir em M2E ou P2E? Calvaria est\u00e1 tornando a escolha mais f\u00e1cil\" \/>\n<meta name=\"twitter:description\" content=\"Saiba como jogos P2E como Calvaria est\u00e3o dominando o espa\u00e7o de jogos com NFT colecion\u00e1veis.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/91563\/229100\/calvaria-hero-banner.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Investir em M2E ou P2E? Calvaria est\u00e1 tornando a escolha mais f\u00e1cil","description":"Saiba como jogos P2E como Calvaria est\u00e3o dominando o espa\u00e7o de jogos com NFT colecion\u00e1veis.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/br\/noticias\/voce-deve-investir-em-move-to-earn-m2e-ou-play-to-earn-p2e-calvaria-esta-tornando-a-escolha-muito-mais-facil\/","og_locale":"pt_BR","og_type":"article","og_title":"Investir em M2E ou P2E? Calvaria est\u00e1 tornando a escolha mais f\u00e1cil","og_description":"Saiba como jogos P2E como Calvaria est\u00e3o dominando o espa\u00e7o de jogos com NFT colecion\u00e1veis.","og_url":"https:\/\/cryptonews.com\/br\/noticias\/voce-deve-investir-em-move-to-earn-m2e-ou-play-to-earn-p2e-calvaria-esta-tornando-a-escolha-muito-mais-facil\/","og_site_name":"CryptoNews Brasil","article_published_time":"2022-10-25T08:08:00+00:00","article_modified_time":"2022-10-29T20:56:29+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/91563\/229100\/calvaria-hero-banner.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Investir em M2E ou P2E? Calvaria est\u00e1 tornando a escolha mais f\u00e1cil","twitter_description":"Saiba como jogos P2E como Calvaria est\u00e3o dominando o espa\u00e7o de jogos com NFT colecion\u00e1veis.","twitter_image":"https:\/\/cimg.co\/news\/91563\/229100\/calvaria-hero-banner.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/br\/noticias\/voce-deve-investir-em-move-to-earn-m2e-ou-play-to-earn-p2e-calvaria-esta-tornando-a-escolha-muito-mais-facil\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/voce-deve-investir-em-move-to-earn-m2e-ou-play-to-earn-p2e-calvaria-esta-tornando-a-escolha-muito-mais-facil\/"},"author":{"name":"killianbrcvmr","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/person\/89b6c7535aa9d37c1a32aff060ae6bcf"},"headline":"Voc\u00ea deve investir em move-to-earn (M2E) ou play-to-earn (P2E)? Calvaria est\u00e1 tornando a escolha muito mais f\u00e1cil","datePublished":"2022-10-25T08:08:00+00:00","dateModified":"2022-10-29T20:56:29+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/voce-deve-investir-em-move-to-earn-m2e-ou-play-to-earn-p2e-calvaria-esta-tornando-a-escolha-muito-mais-facil\/"},"wordCount":838,"publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/voce-deve-investir-em-move-to-earn-m2e-ou-play-to-earn-p2e-calvaria-esta-tornando-a-escolha-muito-mais-facil\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/91563\/229100\/calvaria-hero-banner.jpg","keywords":["Altcoins","Pr\u00e9-Venda"],"articleSection":["Comunicados de Imprensa","Noticias"],"inLanguage":"pt-BR","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/br\/noticias\/voce-deve-investir-em-move-to-earn-m2e-ou-play-to-earn-p2e-calvaria-esta-tornando-a-escolha-muito-mais-facil\/","url":"https:\/\/cryptonews.com\/br\/noticias\/voce-deve-investir-em-move-to-earn-m2e-ou-play-to-earn-p2e-calvaria-esta-tornando-a-escolha-muito-mais-facil\/","name":"Investir em M2E ou P2E? Calvaria est\u00e1 tornando a escolha mais f\u00e1cil","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/voce-deve-investir-em-move-to-earn-m2e-ou-play-to-earn-p2e-calvaria-esta-tornando-a-escolha-muito-mais-facil\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/voce-deve-investir-em-move-to-earn-m2e-ou-play-to-earn-p2e-calvaria-esta-tornando-a-escolha-muito-mais-facil\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/91563\/229100\/calvaria-hero-banner.jpg","datePublished":"2022-10-25T08:08:00+00:00","dateModified":"2022-10-29T20:56:29+00:00","description":"Saiba como jogos P2E como Calvaria est\u00e3o dominando o espa\u00e7o de jogos com NFT colecion\u00e1veis.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/voce-deve-investir-em-move-to-earn-m2e-ou-play-to-earn-p2e-calvaria-esta-tornando-a-escolha-muito-mais-facil\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/br\/noticias\/voce-deve-investir-em-move-to-earn-m2e-ou-play-to-earn-p2e-calvaria-esta-tornando-a-escolha-muito-mais-facil\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/noticias\/voce-deve-investir-em-move-to-earn-m2e-ou-play-to-earn-p2e-calvaria-esta-tornando-a-escolha-muito-mais-facil\/#primaryimage","url":"https:\/\/cimg.co\/news\/91563\/229100\/calvaria-hero-banner.jpg","contentUrl":"https:\/\/cimg.co\/news\/91563\/229100\/calvaria-hero-banner.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/br\/noticias\/voce-deve-investir-em-move-to-earn-m2e-ou-play-to-earn-p2e-calvaria-esta-tornando-a-escolha-muito-mais-facil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/br\/"},{"@type":"ListItem","position":2,"name":"Voc\u00ea deve investir em move-to-earn (M2E) ou play-to-earn (P2E)? Calvaria est\u00e1 tornando a escolha muito mais f\u00e1cil"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/br\/#website","url":"https:\/\/cryptonews.com\/br\/","name":"Cryptonews Portugal","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/br\/#organization","name":"Cryptonews Portugal","url":"https:\/\/cryptonews.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews Portugal"},"image":{"@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/92109","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/users\/109"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/comments?post=92109"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/92109\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/media?parent=92109"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/categories?post=92109"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/tags?post=92109"},{"taxonomy":"editores","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/editores?post=92109"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/sponsored_companies?post=92109"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}