{"id":90018,"date":"2022-10-07T08:48:00","date_gmt":"2022-10-07T08:48:00","guid":{"rendered":"https:\/\/pt.cryptonews.com\/?p=90018"},"modified":"2022-10-12T22:48:21","modified_gmt":"2022-10-12T22:48:21","slug":"preco-bitcoin-em-alta-apos-previsao-queda-bitboy-crypto","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/br\/noticias\/preco-bitcoin-em-alta-apos-previsao-queda-bitboy-crypto\/","title":{"rendered":"Pre\u00e7o do Bitcoin em alta ap\u00f3s a previs\u00e3o de queda do Bitboy Crypto"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/89916\/225450\/bitcoin-price-prediction-october.jpg\" alt=\"\" srcset=\"https:\/\/cimg.co\/news\/89916\/225450\/responsive-images\/bitcoin-price-prediction-october___media_library_original_818_397.jpg 818w, https:\/\/cimg.co\/news\/89916\/225450\/responsive-images\/bitcoin-price-prediction-october___media_library_original_720_349.jpg 720w, https:\/\/cimg.co\/news\/89916\/225450\/responsive-images\/bitcoin-price-prediction-october___media_library_original_600_291.jpg 600w, https:\/\/cimg.co\/news\/89916\/225450\/responsive-images\/bitcoin-price-prediction-october___media_library_original_300_145.jpg 300w\" sizes=\"100vw\" width=\"818\" class=\"content-img\"><\/figure><p class=\"wp-block-paragraph\">Bitboy Crypto tem compartilhado v&aacute;rias previs&otilde;es de baixa a curto prazo &#8211; mas alta a longo prazo &#8211; do pre&ccedil;o do Bitcoin. Desde ent&atilde;o, o mercado se recuperou.<\/p><p>Uma figura de amor\/&oacute;dio no mundo de criptomoedas, Ben Armstrong (<i>@Bitboy_Crypto<\/i>) tem agora 892.000 seguidores no Twitter e mais de 1,4 milh&otilde;es em seu canal no <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/cryptonews.com\/news\/best-crypto-youtube-channels\/\">YouTube<\/a> &#8211; o influenciador de cripto mais seguido na plataforma.<\/p><p>O pre&ccedil;o Bitcoin agora fechou duas velas di&aacute;rias acima da zona de suporte psicol&oacute;gico de US$ 20.000 &#8211; no verde hoje, apesar de Bitboy Crypto ter postado que o piso de pre&ccedil;os ainda n&atilde;o chegou.<\/p><h2>Previs&atilde;o do pre&ccedil;o do Bitcoin do Bitboy Crypto&nbsp;<\/h2><span class=\"replacer\"><\/span><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/Bitboy_Crypto\/status\/1571973440755699713\"><\/oembed><\/figure><p>O Bitboy Crypto apresentou uma previs&atilde;o detalhada do Bitcoin no m&ecirc;s passado &#8211; que o BTC chegaria ao fundo do po&ccedil;o em novembro ou dezembro. Na &eacute;poca, o pre&ccedil;o do Bitcoin estava em torno de US$ 19.000.<\/p><p>Na mesma semana, com o Bitcoin a US$ 18.000, Bitboy tweeted:<\/p><blockquote><p><i>#O Bitcoin est&aacute; se movimentando para chegar ao seu limite mais baixo. N&atilde;o se enganem, ele vai eventualmente cair. Come&ccedil;o a me perguntar se valores perto dos US$15.000 podem ser o fundo do po&ccedil;o. N&atilde;o faz sentido, neste momento, acreditar que o piso #Bitcoin j&aacute; chegou. As pessoas que est&atilde;o dizendo isto est&atilde;o vivendo em outro mundo. Estamos batendo na porta de uma querda acentuada e ela vai chegar antes do final de 2022.<\/i><\/p><\/blockquote><p>A partir da&iacute;, o pre&ccedil;o do Bitcoin quebrou a resist&ecirc;ncia e subiu mais de 10%.<\/p><p>Alguns dos melhores traders de cripto no Twitter usam o Bitboy Crypto como um contra-indicador, negociando contra suas previs&otilde;es de pre&ccedil;o &#8211; e o mercado parece ter se movido contra seu sentimento mais uma vez.<\/p><p>Na &eacute;poca da reuni&atilde;o do FOMC, a an&aacute;lise do Bitboy n&atilde;o era muito diferente de v&aacute;rias <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/cryptonews.com\/br\/noticias\/bitcoin-previsao-preco-pt\/\">previs&otilde;es de pre&ccedil;os do Bitcoin<\/a> compartilhadas por traders profissionais, entretanto.<\/p><p>Bitboy Crypto pode se mostrar correto na Reserva Federal, que pausou os aumentos de impostos &#8211; not&iacute;cias desta semana indicaram que uma ag&ecirc;ncia da ONU recomendou ao Fed que fizesse isso.<\/p><p>Tamb&eacute;m tem havido sinais de uma base de volta &agrave; flexibiliza&ccedil;&atilde;o quantitativa.<\/p><h2>Corrida de pre&ccedil;os das criptomoedas<\/h2><span class=\"replacer\"><\/span><p>A capitaliza&ccedil;&atilde;o total do mercado cripto est&aacute; agora quase de volta a US$ 1 trilh&atilde;o, com o pre&ccedil;o do Ethereum aumentando mais que o Bitcoin hoje, com um aumento de 2% nas &uacute;ltimas 24 horas e perto de atingir n&iacute;veis superiores aos US$ 1.400.<\/p><p><a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/cryptonews.com\/br\/noticias\/dogecoin-em-alta-apos-retomada-das-negociacoes-entre-elon-musk-e-twitter\/\">Dogecoin<\/a> tamb&eacute;m subiu esta semana com a not&iacute;cia de que Elon Musk est&aacute; agora confirmado para comprar o Twitter, bem como o pre&ccedil;o de outras meme coins.<\/p><p>&nbsp;<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/Tamadogecoin\/status\/1577308059994652672\"><\/oembed><\/figure><p><a target=\"_blank\" rel=\"noopener noreferrer sponsored nofollow\" href=\"https:\/\/cryptonews.com\/ext\/tamadoge\/\">Tamadoge<\/a> (TAMA) teve uma semana vol&aacute;til, atualmente 300% acima de seu pre&ccedil;o de listagem inicial no final de setembro na OKX, mesmo depois de uma corre&ccedil;&atilde;o de 50% hoje cedo.<\/p><p>O novo token de pr&eacute;-venda <a target=\"_blank\" rel=\"noopener noreferrer\" href=\"https:\/\/cryptonews.com\/br\/noticias\/plataforma-de-compensacao-de-carbono-cripto-imptio-consegue-us-500000-nos-2-primeiros-dias-de-arrecadacao\/\">IMPT tamb&eacute;m levantou mais de US$ 500.000<\/a>, atingindo US$ 820.000 de investimento em sua rodada inicial.<\/p>","protected":false},"excerpt":{"rendered":"<p>Bitboy Crypto tem compartilhado v&aacute;rias previs&otilde;es de baixa a curto prazo &#8211; mas alta a longo prazo &#8211; do pre&ccedil;o do Bitcoin. Desde ent&atilde;o, o mercado se recuperou.Uma figura de amor\/&oacute;dio no mundo de criptomoedas, Ben Armstrong (@Bitboy_Crypto) tem agora 892.000 seguidores no Twitter e mais de 1,4 milh&otilde;es em seu canal no YouTube &#8211; [&hellip;]<\/p>\n","protected":false},"author":109,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,6],"tags":[103],"editores":[51],"sponsored_companies":[],"class_list":["post-90018","post","type-post","status-publish","format-standard","hentry","category-noticias","category-bitcoin-news","tag-bitcoin","editores-killian-a"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pre\u00e7o do Bitcoin em alta ap\u00f3s a previs\u00e3o de queda do Bitboy Crypto<\/title>\n<meta name=\"description\" content=\"Amado por alguns e detestado por outros, Bitboy Crypto erra nas previs\u00f5es de pre\u00e7o do Bitcoin, que segue em movimento de alta.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/br\/noticias\/preco-bitcoin-em-alta-apos-previsao-queda-bitboy-crypto\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pre\u00e7o do Bitcoin em alta ap\u00f3s a previs\u00e3o de queda do Bitboy Crypto\" \/>\n<meta property=\"og:description\" content=\"Amado por alguns e detestado por outros, Bitboy Crypto erra nas previs\u00f5es de pre\u00e7o do Bitcoin, que segue em movimento de alta.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/br\/noticias\/preco-bitcoin-em-alta-apos-previsao-queda-bitboy-crypto\/\" \/>\n<meta property=\"og:site_name\" content=\"CryptoNews Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2022-10-07T08:48:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-12T22:48:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/89916\/225450\/bitcoin-price-prediction-october.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Pre\u00e7o do Bitcoin em alta ap\u00f3s a previs\u00e3o de queda do Bitboy Crypto\" \/>\n<meta name=\"twitter:description\" content=\"Amado por alguns e detestado por outros, Bitboy Crypto erra nas previs\u00f5es de pre\u00e7o do Bitcoin, que segue em movimento de alta.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/89916\/225450\/bitcoin-price-prediction-october.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pre\u00e7o do Bitcoin em alta ap\u00f3s a previs\u00e3o de queda do Bitboy Crypto","description":"Amado por alguns e detestado por outros, Bitboy Crypto erra nas previs\u00f5es de pre\u00e7o do Bitcoin, que segue em movimento de alta.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/br\/noticias\/preco-bitcoin-em-alta-apos-previsao-queda-bitboy-crypto\/","og_locale":"pt_BR","og_type":"article","og_title":"Pre\u00e7o do Bitcoin em alta ap\u00f3s a previs\u00e3o de queda do Bitboy Crypto","og_description":"Amado por alguns e detestado por outros, Bitboy Crypto erra nas previs\u00f5es de pre\u00e7o do Bitcoin, que segue em movimento de alta.","og_url":"https:\/\/cryptonews.com\/br\/noticias\/preco-bitcoin-em-alta-apos-previsao-queda-bitboy-crypto\/","og_site_name":"CryptoNews Brasil","article_published_time":"2022-10-07T08:48:00+00:00","article_modified_time":"2022-10-12T22:48:21+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/89916\/225450\/bitcoin-price-prediction-october.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Pre\u00e7o do Bitcoin em alta ap\u00f3s a previs\u00e3o de queda do Bitboy Crypto","twitter_description":"Amado por alguns e detestado por outros, Bitboy Crypto erra nas previs\u00f5es de pre\u00e7o do Bitcoin, que segue em movimento de alta.","twitter_image":"https:\/\/cimg.co\/news\/89916\/225450\/bitcoin-price-prediction-october.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/br\/noticias\/preco-bitcoin-em-alta-apos-previsao-queda-bitboy-crypto\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/preco-bitcoin-em-alta-apos-previsao-queda-bitboy-crypto\/"},"author":{"name":"killianbrcvmr","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/person\/89b6c7535aa9d37c1a32aff060ae6bcf"},"headline":"Pre\u00e7o do Bitcoin em alta ap\u00f3s a previs\u00e3o de queda do Bitboy Crypto","datePublished":"2022-10-07T08:48:00+00:00","dateModified":"2022-10-12T22:48:21+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/preco-bitcoin-em-alta-apos-previsao-queda-bitboy-crypto\/"},"wordCount":590,"publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/preco-bitcoin-em-alta-apos-previsao-queda-bitboy-crypto\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/89916\/225450\/bitcoin-price-prediction-october.jpg","keywords":["Bitcoin"],"articleSection":["Noticias","Not\u00edcias de Bitcoin"],"inLanguage":"pt-BR","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/br\/noticias\/preco-bitcoin-em-alta-apos-previsao-queda-bitboy-crypto\/","url":"https:\/\/cryptonews.com\/br\/noticias\/preco-bitcoin-em-alta-apos-previsao-queda-bitboy-crypto\/","name":"Pre\u00e7o do Bitcoin em alta ap\u00f3s a previs\u00e3o de queda do Bitboy Crypto","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/preco-bitcoin-em-alta-apos-previsao-queda-bitboy-crypto\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/preco-bitcoin-em-alta-apos-previsao-queda-bitboy-crypto\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/89916\/225450\/bitcoin-price-prediction-october.jpg","datePublished":"2022-10-07T08:48:00+00:00","dateModified":"2022-10-12T22:48:21+00:00","description":"Amado por alguns e detestado por outros, Bitboy Crypto erra nas previs\u00f5es de pre\u00e7o do Bitcoin, que segue em movimento de alta.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/preco-bitcoin-em-alta-apos-previsao-queda-bitboy-crypto\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/br\/noticias\/preco-bitcoin-em-alta-apos-previsao-queda-bitboy-crypto\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/noticias\/preco-bitcoin-em-alta-apos-previsao-queda-bitboy-crypto\/#primaryimage","url":"https:\/\/cimg.co\/news\/89916\/225450\/bitcoin-price-prediction-october.jpg","contentUrl":"https:\/\/cimg.co\/news\/89916\/225450\/bitcoin-price-prediction-october.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/br\/noticias\/preco-bitcoin-em-alta-apos-previsao-queda-bitboy-crypto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/br\/"},{"@type":"ListItem","position":2,"name":"Pre\u00e7o do Bitcoin em alta ap\u00f3s a previs\u00e3o de queda do Bitboy Crypto"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/br\/#website","url":"https:\/\/cryptonews.com\/br\/","name":"Cryptonews Portugal","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/br\/#organization","name":"Cryptonews Portugal","url":"https:\/\/cryptonews.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews Portugal"},"image":{"@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/90018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/users\/109"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/comments?post=90018"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/90018\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/media?parent=90018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/categories?post=90018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/tags?post=90018"},{"taxonomy":"editores","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/editores?post=90018"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/sponsored_companies?post=90018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}