{"id":78436,"date":"2022-05-11T12:33:00","date_gmt":"2022-05-11T12:33:00","guid":{"rendered":"https:\/\/pt.cryptonews.com\/?p=78436"},"modified":"2022-07-04T07:57:09","modified_gmt":"2022-07-04T07:57:09","slug":"presidente-da-sec-dos-eua-se-preocupa-que-mistura-de-exchanges-de-criptomoedas-pode-colocar-em-risco-os-ativos-dos-clientes","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/br\/noticias\/presidente-da-sec-dos-eua-se-preocupa-que-mistura-de-exchanges-de-criptomoedas-pode-colocar-em-risco-os-ativos-dos-clientes\/","title":{"rendered":"Presidente da SEC dos EUA se preocupa que &#8216;mistura&#8217; de exchanges de criptomoedas pode colocar em risco os ativos dos clientes"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/78411\/191997\/gg.jpg\" alt=\"\" srcset=\"https:\/\/cimg.co\/news\/78411\/191997\/responsive-images\/gg___media_library_original_1378_919.jpg 1378w, https:\/\/cimg.co\/news\/78411\/191997\/responsive-images\/gg___media_library_original_1200_800.jpg 1200w, https:\/\/cimg.co\/news\/78411\/191997\/responsive-images\/gg___media_library_original_900_600.jpg 900w, https:\/\/cimg.co\/news\/78411\/191997\/responsive-images\/gg___media_library_original_720_480.jpg 720w, https:\/\/cimg.co\/news\/78411\/191997\/responsive-images\/gg___media_library_original_600_400.jpg 600w, https:\/\/cimg.co\/news\/78411\/191997\/responsive-images\/gg___media_library_original_300_200.jpg 300w\" sizes=\"100vw\" width=\"1378\" class=\"content-img\"><\/figure><p class=\"wp-block-paragraph\">As exchanges de criptoativos n&atilde;o est&atilde;o colocando barreiras entre as respectivas partes de suas atividades, como servi&ccedil;os de negocia&ccedil;&atilde;o, cust&oacute;dia e marketing, o que poderia levar &agrave; &ldquo;mistura&rdquo; de suas atividades e colocar em risco os interesses de seus clientes, de acordo com <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/br\/noticias\/gensler-da-sec-quer-que-exchanges-e-plataformas-de-criptomoedas-ajudem-reguladores\/\">Garry Gensler<\/a>, presidente da <strong>Comiss&atilde;o de Valores Mobili&aacute;rios dos Estados Unidos <\/strong>(SEC). Ele tamb&eacute;m indicou que sua ag&ecirc;ncia est&aacute; analisando os la&ccedil;os entre as principais stablecoins e as principais exchanges.<\/p><p>&ldquo;As criptomoedas tem muitos desses desafios &ndash; de plataformas negociando &agrave; frente de seus clientes&rdquo;, disse o chefe do regulador &agrave; Bloomberg, alegando que,<\/p><blockquote><p><i>&ldquo;na verdade, eles est&atilde;o negociando contra seus clientes muitas vezes porque est&atilde;o marcando mercado contra seus clientes&rdquo;.&nbsp;<\/i><\/p><\/blockquote><p>A declara&ccedil;&atilde;o mais recente vem logo ap&oacute;s a SEC anunciar que criou cerca de 20 posi&ccedil;&otilde;es adicionais, para um total de 50, dentro da unidade respons&aacute;vel por proteger os investidores nos mercados de criptomoedas e de amea&ccedil;as cibern&eacute;ticas. Chamada de <strong>Crypto Assets and Cyber &#8203;&#8203;Unit<\/strong>, a entidade era anteriormente conhecida como Cyber &#8203;&#8203;Unit. Gensler disse que a expans&atilde;o permitiria que a ag&ecirc;ncia &ldquo;estivesse mais bem equipada para policiar irregularidades nos mercados de criptomoedas, continuando a identificar quest&otilde;es de divulga&ccedil;&atilde;o e controle em rela&ccedil;&atilde;o &agrave; seguran&ccedil;a cibern&eacute;tica&rdquo;.<\/p><p>O funcion&aacute;rio se estabeleceu como um cr&iacute;tico vocal de muitos segmentos da ind&uacute;stria de criptomoedas. Ele argumenta que a maioria dos ativos digitais est&aacute; sob a al&ccedil;ada regulat&oacute;ria da SEC e que as plataformas de negocia&ccedil;&atilde;o de criptomoedas devem se registrar na ag&ecirc;ncia. Com isso em mente, o regulador est&aacute; determinado a refor&ccedil;ar seus esfor&ccedil;os de fiscaliza&ccedil;&atilde;o, de acordo com o funcion&aacute;rio.<\/p><p>Ao mesmo tempo, a SEC est&aacute; observando de perto o mercado de stablecoins, pois a Gensler descobre que n&atilde;o &eacute; por acaso que as tr&ecirc;s stablecoins l&iacute;deres, Tether, USD Coin (USDC) e Binance USD, tenham v&iacute;nculos com as principais exchanges.<\/p><blockquote><p><i>&ldquo;N&atilde;o acho que seja coincid&ecirc;ncia&rdquo;, disse o chefe da ag&ecirc;ncia.<\/i><\/p><\/blockquote><p>Fazendo refer&ecirc;ncia &agrave;s medidas de combate &agrave; lavagem de dinheiro (AML) e conhe&ccedil;a seu cliente (KYC), Gensler tamb&eacute;m disse que cada &ldquo;uma das tr&ecirc;s grandes foi fundada pelas plataformas de negocia&ccedil;&atilde;o para facilitar a negocia&ccedil;&atilde;o nessas plataformas e potencialmente evitar AML e KYC&rdquo;.<\/p><p>A abordagem de Gensler &agrave;s stablecoins parece ser compartilhada pela secret&aacute;ria do Tesouro dos EUA, Janet Yellen. Falando em uma audi&ecirc;ncia do Comit&ecirc; Banc&aacute;rio do Senado na ter&ccedil;a-feira, ela disse que as stablecoins representam &ldquo;riscos para a estabilidade financeira&rdquo; e, como tal, devem estar sujeitas a novos regulamentos.<\/p><blockquote><p><i>&ldquo;N&oacute;s realmente precisamos de uma estrutura federal consistente&rdquo;, disse Yellen aos senadores, conforme citado pelo The Wall Street Journal.<\/i><\/p><\/blockquote><p>No m&ecirc;s passado, Gensler participou de uma confer&ecirc;ncia organizada pela <strong>Carey Law School da Universidade da Pensilv&acirc;nia<\/strong>, onde falou sobre o futuro dos ativos digitais em uma apresenta&ccedil;&atilde;o principal. Para alguns observadores da ind&uacute;stria de criptomoedas, o foco crescente do regulador em tais ativos foi em si uma m&aacute; not&iacute;cia.<\/p><p>&ldquo;Algo me diz que assim que a SEC se envolver, podemos dar adeus ao futuro dos ativos digitais&rdquo;, twittou um usu&aacute;rio.<\/p><p>____<\/p><p><strong>Leia Mais:<\/strong><\/p><p><a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/br\/noticias\/nova-geracao-de-investidores-de-criptomoedas-assume-a-responsabilidade-diz-investidor-de-tecnologia\/\">Nova gera&ccedil;&atilde;o de investidores de criptomoedas assume a responsabilidade, diz investidor de tecnologia<\/a><\/p><p><a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/br\/noticias\/2-em-cada-10-pessoas-em-el-salvador-ainda-usam-a-aplicacao-chivo-bitcoin-do-governo-pesquisa\/\">2 em cada 10 pessoas em El Salvador ainda usam a aplica&ccedil;&atilde;o Chivo Bitcoin do governo &#8211; Pesquisa<\/a><\/p><figure class=\"image\"><a href=\"https:\/\/cryptonews.com\/br\/noticias\/\" target=\"_blank\" rel=\"noopener \"><img decoding=\"async\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" class=\" lazyload\" data-src=\"https:\/\/lh3.googleusercontent.com\/NBBc0g861gRTrcCJrj4cygJLL3NmnpM5MPbXmVNWNXI1My0bq_DWgU65pE-ZeI3swzrrKDjU4fOEBUmqsGDfhWWDVDBrNayMs8xIGBKFT-DNt5pDKt0GllVDAYWFwq-g2GuVLhE4HB4WJR1ByA\" data-srcset=\"\"><\/a><\/figure>","protected":false},"excerpt":{"rendered":"<p>As exchanges de criptoativos n&atilde;o est&atilde;o colocando barreiras entre as respectivas partes de suas atividades, como servi&ccedil;os de negocia&ccedil;&atilde;o, cust&oacute;dia e marketing, o que poderia levar &agrave; &ldquo;mistura&rdquo; de suas atividades e colocar em risco os interesses de seus clientes, de acordo com Garry Gensler, presidente da Comiss&atilde;o de Valores Mobili&aacute;rios dos Estados Unidos (SEC). [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,6],"tags":[98,141,94,108],"editores":[49],"sponsored_companies":[],"class_list":["post-78436","post","type-post","status-publish","format-standard","hentry","category-noticias","category-bitcoin-news","tag-eua","tag-exchange","tag-regulamentacao","tag-stablecoin","editores-jaroslaw-adamowski"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Presidente da SEC dos EUA se preocupa que &#039;mistura&#039; de exchanges de criptomoedas pode colocar em risco os ativos dos clientes<\/title>\n<meta name=\"description\" content=\"As exchanges de criptoativos n&atilde;o est&atilde;o colocando barreiras entre as respectivas partes de suas atividades, como servi&ccedil;os de\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/br\/noticias\/presidente-da-sec-dos-eua-se-preocupa-que-mistura-de-exchanges-de-criptomoedas-pode-colocar-em-risco-os-ativos-dos-clientes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Presidente da SEC dos EUA se preocupa que &#039;mistura&#039; de exchanges de criptomoedas pode colocar em risco os ativos dos clientes\" \/>\n<meta property=\"og:description\" content=\"As exchanges de criptoativos n&atilde;o est&atilde;o colocando barreiras entre as respectivas partes de suas atividades, como servi&ccedil;os de\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/br\/noticias\/presidente-da-sec-dos-eua-se-preocupa-que-mistura-de-exchanges-de-criptomoedas-pode-colocar-em-risco-os-ativos-dos-clientes\/\" \/>\n<meta property=\"og:site_name\" content=\"CryptoNews Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-11T12:33:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-04T07:57:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/78411\/191997\/gg.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/78411\/191997\/gg.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Presidente da SEC dos EUA se preocupa que 'mistura' de exchanges de criptomoedas pode colocar em risco os ativos dos clientes","description":"As exchanges de criptoativos n&atilde;o est&atilde;o colocando barreiras entre as respectivas partes de suas atividades, como servi&ccedil;os de","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/br\/noticias\/presidente-da-sec-dos-eua-se-preocupa-que-mistura-de-exchanges-de-criptomoedas-pode-colocar-em-risco-os-ativos-dos-clientes\/","og_locale":"pt_BR","og_type":"article","og_title":"Presidente da SEC dos EUA se preocupa que 'mistura' de exchanges de criptomoedas pode colocar em risco os ativos dos clientes","og_description":"As exchanges de criptoativos n&atilde;o est&atilde;o colocando barreiras entre as respectivas partes de suas atividades, como servi&ccedil;os de","og_url":"https:\/\/cryptonews.com\/br\/noticias\/presidente-da-sec-dos-eua-se-preocupa-que-mistura-de-exchanges-de-criptomoedas-pode-colocar-em-risco-os-ativos-dos-clientes\/","og_site_name":"CryptoNews Brasil","article_published_time":"2022-05-11T12:33:00+00:00","article_modified_time":"2022-07-04T07:57:09+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/78411\/191997\/gg.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/cimg.co\/news\/78411\/191997\/gg.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/br\/noticias\/presidente-da-sec-dos-eua-se-preocupa-que-mistura-de-exchanges-de-criptomoedas-pode-colocar-em-risco-os-ativos-dos-clientes\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/presidente-da-sec-dos-eua-se-preocupa-que-mistura-de-exchanges-de-criptomoedas-pode-colocar-em-risco-os-ativos-dos-clientes\/"},"author":{"name":"caiomatsuiribeirokyy","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/person\/6586ec84b3e08829c939cecb8a29638e"},"headline":"Presidente da SEC dos EUA se preocupa que &#8216;mistura&#8217; de exchanges de criptomoedas pode colocar em risco os ativos dos clientes","datePublished":"2022-05-11T12:33:00+00:00","dateModified":"2022-07-04T07:57:09+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/presidente-da-sec-dos-eua-se-preocupa-que-mistura-de-exchanges-de-criptomoedas-pode-colocar-em-risco-os-ativos-dos-clientes\/"},"wordCount":708,"publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/presidente-da-sec-dos-eua-se-preocupa-que-mistura-de-exchanges-de-criptomoedas-pode-colocar-em-risco-os-ativos-dos-clientes\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/78411\/191997\/gg.jpg","keywords":["EUA","Exchange","Regulamenta\u00e7\u00e3o","Stablecoin"],"articleSection":["Noticias","Not\u00edcias de Bitcoin"],"inLanguage":"pt-BR","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/br\/noticias\/presidente-da-sec-dos-eua-se-preocupa-que-mistura-de-exchanges-de-criptomoedas-pode-colocar-em-risco-os-ativos-dos-clientes\/","url":"https:\/\/cryptonews.com\/br\/noticias\/presidente-da-sec-dos-eua-se-preocupa-que-mistura-de-exchanges-de-criptomoedas-pode-colocar-em-risco-os-ativos-dos-clientes\/","name":"Presidente da SEC dos EUA se preocupa que 'mistura' de exchanges de criptomoedas pode colocar em risco os ativos dos clientes","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/presidente-da-sec-dos-eua-se-preocupa-que-mistura-de-exchanges-de-criptomoedas-pode-colocar-em-risco-os-ativos-dos-clientes\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/presidente-da-sec-dos-eua-se-preocupa-que-mistura-de-exchanges-de-criptomoedas-pode-colocar-em-risco-os-ativos-dos-clientes\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/78411\/191997\/gg.jpg","datePublished":"2022-05-11T12:33:00+00:00","dateModified":"2022-07-04T07:57:09+00:00","description":"As exchanges de criptoativos n&atilde;o est&atilde;o colocando barreiras entre as respectivas partes de suas atividades, como servi&ccedil;os de","breadcrumb":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/presidente-da-sec-dos-eua-se-preocupa-que-mistura-de-exchanges-de-criptomoedas-pode-colocar-em-risco-os-ativos-dos-clientes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/br\/noticias\/presidente-da-sec-dos-eua-se-preocupa-que-mistura-de-exchanges-de-criptomoedas-pode-colocar-em-risco-os-ativos-dos-clientes\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/noticias\/presidente-da-sec-dos-eua-se-preocupa-que-mistura-de-exchanges-de-criptomoedas-pode-colocar-em-risco-os-ativos-dos-clientes\/#primaryimage","url":"https:\/\/cimg.co\/news\/78411\/191997\/gg.jpg","contentUrl":"https:\/\/cimg.co\/news\/78411\/191997\/gg.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/br\/noticias\/presidente-da-sec-dos-eua-se-preocupa-que-mistura-de-exchanges-de-criptomoedas-pode-colocar-em-risco-os-ativos-dos-clientes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/br\/"},{"@type":"ListItem","position":2,"name":"Presidente da SEC dos EUA se preocupa que &#8216;mistura&#8217; de exchanges de criptomoedas pode colocar em risco os ativos dos clientes"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/br\/#website","url":"https:\/\/cryptonews.com\/br\/","name":"Cryptonews Portugal","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/br\/#organization","name":"Cryptonews Portugal","url":"https:\/\/cryptonews.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews Portugal"},"image":{"@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/78436","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/comments?post=78436"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/78436\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/media?parent=78436"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/categories?post=78436"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/tags?post=78436"},{"taxonomy":"editores","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/editores?post=78436"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/sponsored_companies?post=78436"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}