{"id":70329,"date":"2022-02-02T11:37:00","date_gmt":"2022-02-02T11:37:00","guid":{"rendered":"https:\/\/pt.cryptonews.com\/?p=70329"},"modified":"2022-07-04T07:57:13","modified_gmt":"2022-07-04T07:57:13","slug":"outro-caso-para-bitcoin-conforme-o-libano-ameaca-dinheiro-de-seus-cidadaos","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/br\/noticias\/outro-caso-para-bitcoin-conforme-o-libano-ameaca-dinheiro-de-seus-cidadaos\/","title":{"rendered":"Outro caso para Bitcoin conforme o L\u00edbano amea\u00e7a dinheiro de seus cidad\u00e3os"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/70305\/62127\/adobestock-60195266.jpg\" alt=\"\" srcset=\"https:\/\/cimg.co\/news\/70305\/62127\/responsive-images\/adobestock-60195266___media_library_original_1200_797.jpg 1200w, https:\/\/cimg.co\/news\/70305\/62127\/responsive-images\/adobestock-60195266___media_library_original_900_597.jpg 900w, https:\/\/cimg.co\/news\/70305\/62127\/responsive-images\/adobestock-60195266___media_library_original_720_478.jpg 720w, https:\/\/cimg.co\/news\/70305\/62127\/responsive-images\/adobestock-60195266___media_library_original_600_398.jpg 600w, https:\/\/cimg.co\/news\/70305\/62127\/responsive-images\/adobestock-60195266___media_library_original_300_199.jpg 300w\" sizes=\"100vw\" width=\"1200\" class=\"content-img\"><\/figure><p class=\"wp-block-paragraph\">O L&iacute;bano supostamente planeja converter &agrave; for&ccedil;a as participa&ccedil;&otilde;es em moeda estrangeira de seus cidad&atilde;os em sua libra esterlina (LBP), mais uma vez construindo um caso para o <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/br\/noticias\/bitcoin-atingira-us-93-mil-neste-ano-de-acordo-com-pesquisa-menos-otimista\/\">Bitcoin (BTC)<\/a>.&nbsp;<\/p><p>No in&iacute;cio desta semana, a Reuters informou que viu um &ldquo;plano&rdquo; do governo projetado para combater a crise financeira em andamento. O plano, escreveu a ag&ecirc;ncia de not&iacute;cias, &ldquo;projeta uma desvaloriza&ccedil;&atilde;o de 93% da libra libanesa e converte a maior parte dos dep&oacute;sitos em moeda forte no sistema banc&aacute;rio em moeda local&rdquo;.<\/p><p>Os investidores potencialmente enfrentariam enormes perdas se o plano fosse colocado em a&ccedil;&atilde;o. A Reuters continuou afirmando que &ldquo;dos US$ 104 bilh&otilde;es de dep&oacute;sitos em moeda forte&rdquo;, os autores do plano &ldquo;prev&ecirc;em o retorno de apenas US$ 25 bilh&otilde;es aos poupadores em d&oacute;lares, com a maior parte do que resta convertido em LBP em v&aacute;rias taxas de c&acirc;mbio, incluindo uma que eliminaria em 75% alguns dep&oacute;sitos&rdquo;.<\/p><p>E enquanto o governo supostamente planeja reembolsar &ldquo;todos os depositantes&rdquo;, ele o far&aacute; em &ldquo;um prazo de 15 anos&rdquo;.<\/p><p>Alex Gladstein, diretor de estrat&eacute;gia da <strong>Human Rights Foundation<\/strong>, lamentou o fato de o mundo estar &ldquo;observando&rdquo; como &ldquo;burocratas ladr&otilde;es saqueiam a moeda de uma na&ccedil;&atilde;o outrora orgulhosa&rdquo;.<\/p><p>Da comunidade Bitcoin, a mensagem foi clara e foi mais ou menos assim: &ldquo;Bitcoin corrige isso&rdquo;.<\/p><p>O s&oacute;cio da <strong>Castle Island Ventures<\/strong>, Nic Carter, opinou que o relat&oacute;rio do L&iacute;bano era &ldquo;um conto t&atilde;o antigo quanto o tempo&rdquo; e podia ver os depositantes &ldquo;dando um corte de cabelo enorme&rdquo;. No entanto, ele afirmou que era &ldquo;apenas uma quest&atilde;o de tempo at&eacute; que a dolariza&ccedil;&atilde;o de criptomoedas se tornasse o padr&atilde;o e roubasse desses bancos centrais sua principal arma&rdquo;.<\/p><p>O podcaster Neil Jacobs compartilhou um v&iacute;deo com coment&aacute;rios do bilion&aacute;rio mexicano e entusiasta do bitcoin Ricardo Salinas Pliego. Este &uacute;ltimo afirmou:<\/p><blockquote><p><i>&ldquo;Tudo o que temos em fiat &eacute; 100% apreendido pelo governo. As pessoas n&atilde;o percebem isso [&#8230;]. Mas isso &eacute; um fato.&rdquo;<\/i><\/p><\/blockquote><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/NeilJacobs\/status\/1488731357199142914\"><\/oembed><\/figure><p>Em outros lugares, alguns comentaristas acrescentaram que a melhor maneira de evitar que os estados acessassem suas contas banc&aacute;rias era converter seus fundos para criptomoedas e armazen&aacute;-los em uma carteira de hardware.<\/p><p>No entanto, n&atilde;o s&atilde;o apenas os depositantes libaneses que agora vivem com medo do que o governo far&aacute; com seus fundos.&nbsp;<\/p><p>Nic Carter apontou a relev&acirc;ncia de um relat&oacute;rio de 12 de janeiro do Wall Street Journal (WSJ), que explicava que os cidad&atilde;os turcos estavam &ldquo;acumulando&rdquo; investimentos em bitcoin (BTC) e tether (USDT) para escapar da lira &ldquo;despencando&rdquo;.<\/p><p>O relat&oacute;rio do WSJ explicou que, como &ldquo;alguns&rdquo; turcos sentiram que o governo poderia &ldquo;for&ccedil;ar os bancos&rdquo; a converter dep&oacute;sitos em d&oacute;lares em liras, isso estava &ldquo;pressionando alguns a trocar d&oacute;lares em bancos e d&oacute;lares em dinheiro&rdquo; por stablecoins &ldquo;de acordo com v&aacute;rios poupadores turcos&rdquo;. O WSJ acrescentou que, de acordo com a <strong>Chainalysis<\/strong>, &ldquo;mais da metade das negocia&ccedil;&otilde;es contra a lira em dezembro envolveram o tether&rdquo;.<\/p><p>A atividade de criptomoedas e stablecoins tamb&eacute;m disparou na Argentina, que vem lutando contra a hiperinfla&ccedil;&atilde;o h&aacute; v&aacute;rios meses &ndash; levando o governo a conter a compra de d&oacute;lares.<\/p><p>Outros alegaram que a ado&ccedil;&atilde;o em larga escala do USDT poderia levar ao desenvolvimento de economias &ldquo;hiperdolarizadas&rdquo;.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/Stealthcrypted\/status\/1470694303739834368\"><\/oembed><\/figure><p>_____<br><strong>Leia Mais:<\/strong><\/p><p>&#8211;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/br\/exclusivas\/20-principais-mercados-onde-voce-pode-comprar-e-vender-nfts\/\"> 20 Principais Mercados onde voc&ecirc; pode comprar e vender NFTs<\/a><\/p><p>&#8211;<a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/br\/noticias\/governos-locais-chineses-e-empresas-de-tecnologia-tentam-se-envolver-com-metaverso\/\"> Governos Locais Chineses e Empresas de Tecnologia tentam se envolver com Metaverso<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>O L&iacute;bano supostamente planeja converter &agrave; for&ccedil;a as participa&ccedil;&otilde;es em moeda estrangeira de seus cidad&atilde;os em sua libra esterlina (LBP), mais uma vez construindo um caso para o Bitcoin (BTC).&nbsp;No in&iacute;cio desta semana, a Reuters informou que viu um &ldquo;plano&rdquo; do governo projetado para combater a crise financeira em andamento. O plano, escreveu a ag&ecirc;ncia [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,6],"tags":[104,101,103,95],"editores":[884],"sponsored_companies":[],"class_list":["post-70329","post","type-post","status-publish","format-standard","hentry","category-noticias","category-bitcoin-news","tag-adocao","tag-banco-central","tag-bitcoin","tag-criptomoedas","editores-cryptonewscom"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Outro caso para Bitcoin conforme o L\u00edbano amea\u00e7a dinheiro de seus cidad\u00e3os<\/title>\n<meta name=\"description\" content=\"O L&iacute;bano supostamente planeja converter &agrave; for&ccedil;a as participa&ccedil;&otilde;es em moeda estrangeira de seus cidad&atilde;os em sua\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/br\/noticias\/outro-caso-para-bitcoin-conforme-o-libano-ameaca-dinheiro-de-seus-cidadaos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Outro caso para Bitcoin conforme o L\u00edbano amea\u00e7a dinheiro de seus cidad\u00e3os\" \/>\n<meta property=\"og:description\" content=\"O L&iacute;bano supostamente planeja converter &agrave; for&ccedil;a as participa&ccedil;&otilde;es em moeda estrangeira de seus cidad&atilde;os em sua\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/br\/noticias\/outro-caso-para-bitcoin-conforme-o-libano-ameaca-dinheiro-de-seus-cidadaos\/\" \/>\n<meta property=\"og:site_name\" content=\"CryptoNews Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-02T11:37:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-04T07:57:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/70305\/62127\/adobestock-60195266.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/70305\/62127\/adobestock-60195266.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Outro caso para Bitcoin conforme o L\u00edbano amea\u00e7a dinheiro de seus cidad\u00e3os","description":"O L&iacute;bano supostamente planeja converter &agrave; for&ccedil;a as participa&ccedil;&otilde;es em moeda estrangeira de seus cidad&atilde;os em sua","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/br\/noticias\/outro-caso-para-bitcoin-conforme-o-libano-ameaca-dinheiro-de-seus-cidadaos\/","og_locale":"pt_BR","og_type":"article","og_title":"Outro caso para Bitcoin conforme o L\u00edbano amea\u00e7a dinheiro de seus cidad\u00e3os","og_description":"O L&iacute;bano supostamente planeja converter &agrave; for&ccedil;a as participa&ccedil;&otilde;es em moeda estrangeira de seus cidad&atilde;os em sua","og_url":"https:\/\/cryptonews.com\/br\/noticias\/outro-caso-para-bitcoin-conforme-o-libano-ameaca-dinheiro-de-seus-cidadaos\/","og_site_name":"CryptoNews Brasil","article_published_time":"2022-02-02T11:37:00+00:00","article_modified_time":"2022-07-04T07:57:13+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/70305\/62127\/adobestock-60195266.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/cimg.co\/news\/70305\/62127\/adobestock-60195266.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/br\/noticias\/outro-caso-para-bitcoin-conforme-o-libano-ameaca-dinheiro-de-seus-cidadaos\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/outro-caso-para-bitcoin-conforme-o-libano-ameaca-dinheiro-de-seus-cidadaos\/"},"author":{"name":"caiomatsuiribeirokyy","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/person\/6586ec84b3e08829c939cecb8a29638e"},"headline":"Outro caso para Bitcoin conforme o L\u00edbano amea\u00e7a dinheiro de seus cidad\u00e3os","datePublished":"2022-02-02T11:37:00+00:00","dateModified":"2022-07-04T07:57:13+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/outro-caso-para-bitcoin-conforme-o-libano-ameaca-dinheiro-de-seus-cidadaos\/"},"wordCount":716,"publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/outro-caso-para-bitcoin-conforme-o-libano-ameaca-dinheiro-de-seus-cidadaos\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/70305\/62127\/adobestock-60195266.jpg","keywords":["Ado\u00e7\u00e3o","Banco Central","Bitcoin","Criptomoedas"],"articleSection":["Noticias","Not\u00edcias de Bitcoin"],"inLanguage":"pt-BR","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/br\/noticias\/outro-caso-para-bitcoin-conforme-o-libano-ameaca-dinheiro-de-seus-cidadaos\/","url":"https:\/\/cryptonews.com\/br\/noticias\/outro-caso-para-bitcoin-conforme-o-libano-ameaca-dinheiro-de-seus-cidadaos\/","name":"Outro caso para Bitcoin conforme o L\u00edbano amea\u00e7a dinheiro de seus cidad\u00e3os","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/outro-caso-para-bitcoin-conforme-o-libano-ameaca-dinheiro-de-seus-cidadaos\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/outro-caso-para-bitcoin-conforme-o-libano-ameaca-dinheiro-de-seus-cidadaos\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/70305\/62127\/adobestock-60195266.jpg","datePublished":"2022-02-02T11:37:00+00:00","dateModified":"2022-07-04T07:57:13+00:00","description":"O L&iacute;bano supostamente planeja converter &agrave; for&ccedil;a as participa&ccedil;&otilde;es em moeda estrangeira de seus cidad&atilde;os em sua","breadcrumb":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/outro-caso-para-bitcoin-conforme-o-libano-ameaca-dinheiro-de-seus-cidadaos\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/br\/noticias\/outro-caso-para-bitcoin-conforme-o-libano-ameaca-dinheiro-de-seus-cidadaos\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/noticias\/outro-caso-para-bitcoin-conforme-o-libano-ameaca-dinheiro-de-seus-cidadaos\/#primaryimage","url":"https:\/\/cimg.co\/news\/70305\/62127\/adobestock-60195266.jpg","contentUrl":"https:\/\/cimg.co\/news\/70305\/62127\/adobestock-60195266.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/br\/noticias\/outro-caso-para-bitcoin-conforme-o-libano-ameaca-dinheiro-de-seus-cidadaos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/br\/"},{"@type":"ListItem","position":2,"name":"Outro caso para Bitcoin conforme o L\u00edbano amea\u00e7a dinheiro de seus cidad\u00e3os"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/br\/#website","url":"https:\/\/cryptonews.com\/br\/","name":"Cryptonews Portugal","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/br\/#organization","name":"Cryptonews Portugal","url":"https:\/\/cryptonews.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews Portugal"},"image":{"@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/70329","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/comments?post=70329"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/70329\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/media?parent=70329"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/categories?post=70329"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/tags?post=70329"},{"taxonomy":"editores","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/editores?post=70329"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/sponsored_companies?post=70329"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}