{"id":70242,"date":"2022-02-01T13:33:00","date_gmt":"2022-02-01T13:33:00","guid":{"rendered":"https:\/\/pt.cryptonews.com\/?p=70242"},"modified":"2022-07-04T07:57:13","modified_gmt":"2022-07-04T07:57:13","slug":"professores-de-ontario-continuam-investindo-na-ftx-mesmo-sem-estar-disponivel-no-canada","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/br\/noticias\/professores-de-ontario-continuam-investindo-na-ftx-mesmo-sem-estar-disponivel-no-canada\/","title":{"rendered":"Professores de Ont\u00e1rio continuam investindo na FTX, mesmo sem estar dispon\u00edvel no Canad\u00e1"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/70161\/61462\/adobestock-309061402.jpg\" alt=\"\" srcset=\"https:\/\/cimg.co\/news\/70161\/61462\/responsive-images\/adobestock-309061402___media_library_original_1178_786.jpg 1178w, https:\/\/cimg.co\/news\/70161\/61462\/responsive-images\/adobestock-309061402___media_library_original_900_600.jpg 900w, https:\/\/cimg.co\/news\/70161\/61462\/responsive-images\/adobestock-309061402___media_library_original_720_480.jpg 720w, https:\/\/cimg.co\/news\/70161\/61462\/responsive-images\/adobestock-309061402___media_library_original_600_400.jpg 600w, https:\/\/cimg.co\/news\/70161\/61462\/responsive-images\/adobestock-309061402___media_library_original_300_200.jpg 300w\" sizes=\"100vw\" width=\"1178\" class=\"content-img\"><\/figure><p class=\"wp-block-paragraph\">Uma organiza&ccedil;&atilde;o sediada em Ont&aacute;rio encarregada de administrar pens&otilde;es para professores mais uma vez investiu durante a &uacute;ltima rodada de investimentos da <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/br\/noticias\/ftx-us-recebe-us-400-milhoes-para-competir-com-exchanges-nos-eua\/\">FTX<\/a>, mas os residentes desta prov&iacute;ncia canadense ainda n&atilde;o podem usar o FTX.com.<\/p><p>A <strong>FTX Trading Ltd.<\/strong>, propriet&aacute;ria e operadora da grande exchange de criptomoedas FTX, disse que fechou uma arrecada&ccedil;&atilde;o de fundos S&eacute;rie C de US$ 400 milh&otilde;es &ndash; aumentando a avalia&ccedil;&atilde;o da empresa para US$ 32 bilh&otilde;es.<\/p><p>Entre os participantes est&aacute; o <strong>Ontario Teachers&#8217; Pension Plan Board<\/strong>, uma organiza&ccedil;&atilde;o independente respons&aacute;vel pela administra&ccedil;&atilde;o de pens&otilde;es de benef&iacute;cio para professores da prov&iacute;ncia canadense de Ont&aacute;rio. O Conselho alega que tinha US$ 227,7 bilh&otilde;es em ativos l&iacute;quidos em 30 de junho de 2021.<\/p><p>Ainda assim, Ont&aacute;rio &eacute; um mercado restrito para a FTX. A exchange afirma que &ldquo;pode haver restri&ccedil;&otilde;es parciais&rdquo; em certas jurisdi&ccedil;&otilde;es, &ldquo;potencialmente incluindo&rdquo; o Canad&aacute;, enquanto a &ldquo;FTX tamb&eacute;m n&atilde;o possui nenhum usu&aacute;rio de Ont&aacute;rio&rdquo;.<\/p><p>E n&atilde;o &eacute; a primeira vez: a organiza&ccedil;&atilde;o anunciou em outubro do ano passado que sua Plataforma de Inova&ccedil;&atilde;o de Professores (TIP) havia participado da rodada de financiamento de US$ 420 milh&otilde;es da FTX. &#8220;O TIP se concentra em investimentos de capital de crescimento e capital de risco em empresas, como a FTX, que est&atilde;o usando a tecnologia para moldar mercados futuros&#8221;, disseram eles na &eacute;poca.<\/p><p>Enquanto isso, de acordo com o CEO da FTX, Sam Bankman-Fried, eles &ldquo;procurar&atilde;o continuar interagindo com os reguladores para facilitar o acesso aos ativos digitais de maneira segura e compat&iacute;vel&rdquo;.<\/p><p>N&atilde;o &eacute; apenas a FTX que pode ter problemas regulat&oacute;rios caso ofere&ccedil;a servi&ccedil;os aos residentes de Ont&aacute;rio. Em dezembro de 2021, a <strong>Comiss&atilde;o de Valores Mobili&aacute;rios de Ont&aacute;rio<\/strong> alertou os investidores que a plataforma de criptoativos <strong>Binance <\/strong>n&atilde;o est&aacute; registrada em Ont&aacute;rio, portanto, n&atilde;o est&aacute; autorizada a vender derivativos ou t&iacute;tulos na prov&iacute;ncia.<\/p><p>Enquanto isso, outros participantes desta &uacute;ltima capta&ccedil;&atilde;o de recursos da FTX incluem <strong>Temasek<\/strong>, <strong>Paradigm<\/strong>, <strong>NEA<\/strong>, <strong>IVP<\/strong>, <strong>SoftBank Vision<\/strong> <strong>Fund 2<\/strong>, <strong>Lightspeed<\/strong> <strong>Venture Partners<\/strong>, <strong>Steadview Capital<\/strong>, <strong>Tiger Global<\/strong> e <strong>Insight Partners<\/strong>, entre outros.<\/p><p>Al&eacute;m disso, esta &eacute; a terceira arrecada&ccedil;&atilde;o de fundos nos &uacute;ltimos seis meses para a FTX.com, elevando o valor total levantado para US$ 1,8 bilh&atilde;o e vendo a avalia&ccedil;&atilde;o da FTX aumentar mais de 75% nesse per&iacute;odo.<\/p><p>O an&uacute;ncio afirmou ainda que a FTX cresceu &ldquo;significativamente&rdquo; desde que a empresa foi avaliada em US$ 25 bilh&otilde;es em outubro de 2021 &ndash; a base de usu&aacute;rios da FTX Trading aumentou 60% e seu volume m&eacute;dio di&aacute;rio de negocia&ccedil;&atilde;o aumentou 40%, atingindo cerca de US$ 14 bilh&otilde;es em volume di&aacute;rio, disseram eles.<\/p><p>De acordo com a empresa, todos os &ldquo;investidores envolvidos na S&eacute;rie C participaram simultaneamente&rdquo;, e avaliaram a <strong>FTX US <\/strong>em US$ 8 bilh&otilde;es.<\/p><p>____<\/p><p><strong>Leia Mais:<\/strong><\/p><p>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/br\/noticias\/silvergate-bank-pretende-comprar-propriedade-intelectual-da-diem-por-us-200-milhoes\/\">Silvergate Bank pretende comprar Propriedade Intelectual da Diem por US$ 200 Milh&otilde;es<\/a><\/p><p>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/br\/exclusivas\/20-principais-mercados-onde-voce-pode-comprar-e-vender-nfts\/\">20 Principais Mercados onde voc&ecirc; pode comprar e vender NFTs<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Uma organiza&ccedil;&atilde;o sediada em Ont&aacute;rio encarregada de administrar pens&otilde;es para professores mais uma vez investiu durante a &uacute;ltima rodada de investimentos da FTX, mas os residentes desta prov&iacute;ncia canadense ainda n&atilde;o podem usar o FTX.com.A FTX Trading Ltd., propriet&aacute;ria e operadora da grande exchange de criptomoedas FTX, disse que fechou uma arrecada&ccedil;&atilde;o de fundos S&eacute;rie [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,6],"tags":[180,85,94],"editores":[884],"sponsored_companies":[],"class_list":["post-70242","post","type-post","status-publish","format-standard","hentry","category-noticias","category-bitcoin-news","tag-ftx","tag-investimentos","tag-regulamentacao","editores-cryptonewscom"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Professores de Ont\u00e1rio continuam investindo na FTX, mesmo sem estar dispon\u00edvel no Canad\u00e1<\/title>\n<meta name=\"description\" content=\"Uma organiza&ccedil;&atilde;o sediada em Ont&aacute;rio encarregada de administrar pens&otilde;es para professores mais uma vez investiu durante a\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/br\/noticias\/professores-de-ontario-continuam-investindo-na-ftx-mesmo-sem-estar-disponivel-no-canada\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Professores de Ont\u00e1rio continuam investindo na FTX, mesmo sem estar dispon\u00edvel no Canad\u00e1\" \/>\n<meta property=\"og:description\" content=\"Uma organiza&ccedil;&atilde;o sediada em Ont&aacute;rio encarregada de administrar pens&otilde;es para professores mais uma vez investiu durante a\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/br\/noticias\/professores-de-ontario-continuam-investindo-na-ftx-mesmo-sem-estar-disponivel-no-canada\/\" \/>\n<meta property=\"og:site_name\" content=\"CryptoNews Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-01T13:33:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-04T07:57:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/70161\/61462\/adobestock-309061402.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/70161\/61462\/adobestock-309061402.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Professores de Ont\u00e1rio continuam investindo na FTX, mesmo sem estar dispon\u00edvel no Canad\u00e1","description":"Uma organiza&ccedil;&atilde;o sediada em Ont&aacute;rio encarregada de administrar pens&otilde;es para professores mais uma vez investiu durante a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/br\/noticias\/professores-de-ontario-continuam-investindo-na-ftx-mesmo-sem-estar-disponivel-no-canada\/","og_locale":"pt_BR","og_type":"article","og_title":"Professores de Ont\u00e1rio continuam investindo na FTX, mesmo sem estar dispon\u00edvel no Canad\u00e1","og_description":"Uma organiza&ccedil;&atilde;o sediada em Ont&aacute;rio encarregada de administrar pens&otilde;es para professores mais uma vez investiu durante a","og_url":"https:\/\/cryptonews.com\/br\/noticias\/professores-de-ontario-continuam-investindo-na-ftx-mesmo-sem-estar-disponivel-no-canada\/","og_site_name":"CryptoNews Brasil","article_published_time":"2022-02-01T13:33:00+00:00","article_modified_time":"2022-07-04T07:57:13+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/70161\/61462\/adobestock-309061402.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/cimg.co\/news\/70161\/61462\/adobestock-309061402.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/br\/noticias\/professores-de-ontario-continuam-investindo-na-ftx-mesmo-sem-estar-disponivel-no-canada\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/professores-de-ontario-continuam-investindo-na-ftx-mesmo-sem-estar-disponivel-no-canada\/"},"author":{"name":"caiomatsuiribeirokyy","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/person\/6586ec84b3e08829c939cecb8a29638e"},"headline":"Professores de Ont\u00e1rio continuam investindo na FTX, mesmo sem estar dispon\u00edvel no Canad\u00e1","datePublished":"2022-02-01T13:33:00+00:00","dateModified":"2022-07-04T07:57:13+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/professores-de-ontario-continuam-investindo-na-ftx-mesmo-sem-estar-disponivel-no-canada\/"},"wordCount":631,"publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/professores-de-ontario-continuam-investindo-na-ftx-mesmo-sem-estar-disponivel-no-canada\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/70161\/61462\/adobestock-309061402.jpg","keywords":["FTX","Investimentos","Regulamenta\u00e7\u00e3o"],"articleSection":["Noticias","Not\u00edcias de Bitcoin"],"inLanguage":"pt-BR","copyrightYear":"2022","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/br\/noticias\/professores-de-ontario-continuam-investindo-na-ftx-mesmo-sem-estar-disponivel-no-canada\/","url":"https:\/\/cryptonews.com\/br\/noticias\/professores-de-ontario-continuam-investindo-na-ftx-mesmo-sem-estar-disponivel-no-canada\/","name":"Professores de Ont\u00e1rio continuam investindo na FTX, mesmo sem estar dispon\u00edvel no Canad\u00e1","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/professores-de-ontario-continuam-investindo-na-ftx-mesmo-sem-estar-disponivel-no-canada\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/professores-de-ontario-continuam-investindo-na-ftx-mesmo-sem-estar-disponivel-no-canada\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/70161\/61462\/adobestock-309061402.jpg","datePublished":"2022-02-01T13:33:00+00:00","dateModified":"2022-07-04T07:57:13+00:00","description":"Uma organiza&ccedil;&atilde;o sediada em Ont&aacute;rio encarregada de administrar pens&otilde;es para professores mais uma vez investiu durante a","breadcrumb":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/professores-de-ontario-continuam-investindo-na-ftx-mesmo-sem-estar-disponivel-no-canada\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/br\/noticias\/professores-de-ontario-continuam-investindo-na-ftx-mesmo-sem-estar-disponivel-no-canada\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/noticias\/professores-de-ontario-continuam-investindo-na-ftx-mesmo-sem-estar-disponivel-no-canada\/#primaryimage","url":"https:\/\/cimg.co\/news\/70161\/61462\/adobestock-309061402.jpg","contentUrl":"https:\/\/cimg.co\/news\/70161\/61462\/adobestock-309061402.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/br\/noticias\/professores-de-ontario-continuam-investindo-na-ftx-mesmo-sem-estar-disponivel-no-canada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/br\/"},{"@type":"ListItem","position":2,"name":"Professores de Ont\u00e1rio continuam investindo na FTX, mesmo sem estar dispon\u00edvel no Canad\u00e1"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/br\/#website","url":"https:\/\/cryptonews.com\/br\/","name":"Cryptonews Portugal","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/br\/#organization","name":"Cryptonews Portugal","url":"https:\/\/cryptonews.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews Portugal"},"image":{"@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/70242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/comments?post=70242"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/70242\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/media?parent=70242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/categories?post=70242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/tags?post=70242"},{"taxonomy":"editores","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/editores?post=70242"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/sponsored_companies?post=70242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}