{"id":67836,"date":"2021-12-31T13:00:00","date_gmt":"2021-12-31T13:00:00","guid":{"rendered":"https:\/\/pt.cryptonews.com\/?p=67836"},"modified":"2022-07-04T07:57:15","modified_gmt":"2022-07-04T07:57:15","slug":"usuarios-chineses-de-criptomoedas-ainda-conseguem-contornar-a-proibicao","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/br\/noticias\/usuarios-chineses-de-criptomoedas-ainda-conseguem-contornar-a-proibicao\/","title":{"rendered":"Usu\u00e1rios Chineses de Criptomoedas ainda Conseguem Contornar a Proibi\u00e7\u00e3o"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/67794\/52341\/adobestock-50026439.jpg\" alt=\"\" srcset=\"https:\/\/cimg.co\/news\/67794\/52341\/responsive-images\/adobestock-50026439___media_library_original_1227_818.jpg 1227w, https:\/\/cimg.co\/news\/67794\/52341\/responsive-images\/adobestock-50026439___media_library_original_1200_800.jpg 1200w, https:\/\/cimg.co\/news\/67794\/52341\/responsive-images\/adobestock-50026439___media_library_original_900_600.jpg 900w, https:\/\/cimg.co\/news\/67794\/52341\/responsive-images\/adobestock-50026439___media_library_original_720_480.jpg 720w, https:\/\/cimg.co\/news\/67794\/52341\/responsive-images\/adobestock-50026439___media_library_original_600_400.jpg 600w, https:\/\/cimg.co\/news\/67794\/52341\/responsive-images\/adobestock-50026439___media_library_original_300_200.jpg 300w\" sizes=\"100vw\" width=\"1227\" class=\"content-img\"><\/figure><p class=\"wp-block-paragraph\">Os usu&aacute;rios de criptografia na China continental ainda est&atilde;o encontrando maneiras de negociar, enquanto as principais exchanges se preparam para desativar o servi&ccedil;o para usu&aacute;rios chineses at&eacute; o final do ano.<\/p><p>Como 2021 est&aacute; chegando ao fim, acredita-se que o tempo est&aacute; se esgotando para usu&aacute;rios de criptografia e investidores baseados na China. Ap&oacute;s uma proibi&ccedil;&atilde;o renovada no in&iacute;cio deste ano de tudo, desde o com&eacute;rcio de criptografia at&eacute; &agrave; minera&ccedil;&atilde;o, exchanges que historicamente tiveram um grande n&uacute;mero de usu&aacute;rios chineses, incluindo <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/criptomestre.com\/exchanges\/como-criar-conta-na-binance\/\"><strong>Binance<\/strong><\/a> e <strong>Huobi<\/strong>, disseram que o servi&ccedil;o para esses usu&aacute;rios ser&aacute; desativado at&eacute; o final de dezembro.<\/p><p>O pr&oacute;ximo prazo foi destacado por alguns como um risco potencial para o mercado, por exemplo, o jornalista chin&ecirc;s Colin Wu, focado em criptografia, escreveu que as pessoas devem &#8220;estar cientes das flutua&ccedil;&otilde;es do mercado&#8221;, j&aacute; que Binance, Huobi e <strong>MEXC <\/strong>suspender&atilde;o o suporte &agrave; usu&aacute;rios chineses.<\/p><p>Apesar do prazo iminente, no entanto, os usu&aacute;rios de criptografia na China continental j&aacute; encontraram maneiras de contornar as restri&ccedil;&otilde;es, de acordo com fontes n&atilde;o identificadas com as quais o South China Morning Post falou.<\/p><p>De acordo com um investidor chin&ecirc;s, usar uma rede privada virtual (VPN) para contornar o &#8216;Grande Firewall&#8217; significa que os usu&aacute;rios na China ainda podem acessar exchanges de criptografia estrangeiras. A partir da&iacute;, a mesma fonte disse que &eacute; poss&iacute;vel se cadastrar por meio de um servi&ccedil;o de e-mail estrangeiro e escolher um pa&iacute;s que n&atilde;o tenha sistema de identidade.<\/p><p>Enquanto isso, de acordo com outro investidor chin&ecirc;s que tamb&eacute;m estava por perto durante a repress&atilde;o anterior &agrave; criptografia na China em 2017, provavelmente surgir&atilde;o novas solu&ccedil;&otilde;es para os comerciantes chineses.<\/p><p>Ap&oacute;s a proibi&ccedil;&atilde;o de 2017, muitas exchanges chinesas suspenderam os dep&oacute;sitos de yuans chineses e permitiram apenas retiradas, disse o investidor, acrescentando que isso levou a um &ldquo;caos tempor&aacute;rio&rdquo; no mercado dom&eacute;stico. No entanto, a situa&ccedil;&atilde;o melhorou quando alguns veteranos do mercado formaram grupos privados de balc&atilde;o (OTC) que poderiam facilitar a negocia&ccedil;&atilde;o entre fiat e cripto, explicou a fonte.<\/p><p>De acordo com uma terceira fonte, no entanto, as op&ccedil;&otilde;es est&atilde;o se tornando muito mais limitadas para aqueles que s&atilde;o novos em criptomoedas.<\/p><p>Os comerciantes podem sempre optar por exchanges descentralizadas (DEXes), que n&atilde;o imp&otilde;em checagem &#8220;conhe&ccedil;a seu cliente&#8221; (KYC) para negociar entre tokens, mas mudar do yuan chin&ecirc;s para a criptografia est&aacute; se tornando mais dif&iacute;cil, disse a fonte.<\/p><p>Ap&oacute;s a proibi&ccedil;&atilde;o anterior de criptomoedas na China em 2017, muitas das maiores exchanges do pa&iacute;s responderam mudando suas sedes para fora do continente chin&ecirc;s e para locais como Hong Kong e Cingapura.<\/p><p>No entanto, os mercados peer-to-peer e OTC ainda estavam geralmente dispon&iacute;veis para usu&aacute;rios na China, tornando relativamente f&aacute;cil para esses usu&aacute;rios continuar a participar da criptoeconomia. Com Pequim, desta vez, aparentemente mais determinada a expulsar atividades relacionadas &agrave; criptografia do pa&iacute;s, no entanto, ainda &eacute; uma quest&atilde;o em aberto quais solu&ccedil;&otilde;es surgir&atilde;o para os usu&aacute;rios de criptografia chineses desta vez.<br>____<br><strong>Leia Mais:<\/strong><\/p><p><strong>&#8211; <\/strong><a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/br\/exclusivas\/crypto-security-em-2022-prepare-se-para-mais-hacks-defi-interrupcoes-de-exchanges-e-erros-noob\/\">Crypto Security em 2022: Prepare-se para Mais Hacks DeFi, Interrup&ccedil;&otilde;es de Exchanges e Erros Noob<\/a><\/p><p>&#8211; <a target=\"_blank\" rel=\"noopener \" href=\"https:\/\/cryptonews.com\/br\/noticias\/metamask-ira-adicionar-suporte-para-nfts\/\">MetaMask ir&aacute; Adicionar Suporte para NFTs<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Os usu&aacute;rios de criptografia na China continental ainda est&atilde;o encontrando maneiras de negociar, enquanto as principais exchanges se preparam para desativar o servi&ccedil;o para usu&aacute;rios chineses at&eacute; o final do ano.Como 2021 est&aacute; chegando ao fim, acredita-se que o tempo est&aacute; se esgotando para usu&aacute;rios de criptografia e investidores baseados na China. Ap&oacute;s uma proibi&ccedil;&atilde;o [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,6],"tags":[103,141,142],"editores":[884],"sponsored_companies":[],"class_list":["post-67836","post","type-post","status-publish","format-standard","hentry","category-noticias","category-bitcoin-news","tag-bitcoin","tag-exchange","tag-trading","editores-cryptonewscom"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Usu\u00e1rios Chineses de Criptomoedas ainda Conseguem Contornar a Proibi\u00e7\u00e3o<\/title>\n<meta name=\"description\" content=\"Os usu&aacute;rios de criptografia na China continental ainda est&atilde;o encontrando maneiras de negociar, enquanto as principais exchanges se preparam\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/br\/noticias\/usuarios-chineses-de-criptomoedas-ainda-conseguem-contornar-a-proibicao\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Usu\u00e1rios Chineses de Criptomoedas ainda Conseguem Contornar a Proibi\u00e7\u00e3o\" \/>\n<meta property=\"og:description\" content=\"Os usu&aacute;rios de criptografia na China continental ainda est&atilde;o encontrando maneiras de negociar, enquanto as principais exchanges se preparam\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/br\/noticias\/usuarios-chineses-de-criptomoedas-ainda-conseguem-contornar-a-proibicao\/\" \/>\n<meta property=\"og:site_name\" content=\"CryptoNews Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-31T13:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-04T07:57:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/67794\/52341\/adobestock-50026439.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/67794\/52341\/adobestock-50026439.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Usu\u00e1rios Chineses de Criptomoedas ainda Conseguem Contornar a Proibi\u00e7\u00e3o","description":"Os usu&aacute;rios de criptografia na China continental ainda est&atilde;o encontrando maneiras de negociar, enquanto as principais exchanges se preparam","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/br\/noticias\/usuarios-chineses-de-criptomoedas-ainda-conseguem-contornar-a-proibicao\/","og_locale":"pt_BR","og_type":"article","og_title":"Usu\u00e1rios Chineses de Criptomoedas ainda Conseguem Contornar a Proibi\u00e7\u00e3o","og_description":"Os usu&aacute;rios de criptografia na China continental ainda est&atilde;o encontrando maneiras de negociar, enquanto as principais exchanges se preparam","og_url":"https:\/\/cryptonews.com\/br\/noticias\/usuarios-chineses-de-criptomoedas-ainda-conseguem-contornar-a-proibicao\/","og_site_name":"CryptoNews Brasil","article_published_time":"2021-12-31T13:00:00+00:00","article_modified_time":"2022-07-04T07:57:15+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/67794\/52341\/adobestock-50026439.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/cimg.co\/news\/67794\/52341\/adobestock-50026439.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/br\/noticias\/usuarios-chineses-de-criptomoedas-ainda-conseguem-contornar-a-proibicao\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/usuarios-chineses-de-criptomoedas-ainda-conseguem-contornar-a-proibicao\/"},"author":{"name":"caiomatsuiribeirokyy","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/person\/6586ec84b3e08829c939cecb8a29638e"},"headline":"Usu\u00e1rios Chineses de Criptomoedas ainda Conseguem Contornar a Proibi\u00e7\u00e3o","datePublished":"2021-12-31T13:00:00+00:00","dateModified":"2022-07-04T07:57:15+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/usuarios-chineses-de-criptomoedas-ainda-conseguem-contornar-a-proibicao\/"},"wordCount":667,"publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/usuarios-chineses-de-criptomoedas-ainda-conseguem-contornar-a-proibicao\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/67794\/52341\/adobestock-50026439.jpg","keywords":["Bitcoin","Exchange","Trading"],"articleSection":["Noticias","Not\u00edcias de Bitcoin"],"inLanguage":"pt-BR","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/br\/noticias\/usuarios-chineses-de-criptomoedas-ainda-conseguem-contornar-a-proibicao\/","url":"https:\/\/cryptonews.com\/br\/noticias\/usuarios-chineses-de-criptomoedas-ainda-conseguem-contornar-a-proibicao\/","name":"Usu\u00e1rios Chineses de Criptomoedas ainda Conseguem Contornar a Proibi\u00e7\u00e3o","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/usuarios-chineses-de-criptomoedas-ainda-conseguem-contornar-a-proibicao\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/usuarios-chineses-de-criptomoedas-ainda-conseguem-contornar-a-proibicao\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/67794\/52341\/adobestock-50026439.jpg","datePublished":"2021-12-31T13:00:00+00:00","dateModified":"2022-07-04T07:57:15+00:00","description":"Os usu&aacute;rios de criptografia na China continental ainda est&atilde;o encontrando maneiras de negociar, enquanto as principais exchanges se preparam","breadcrumb":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/usuarios-chineses-de-criptomoedas-ainda-conseguem-contornar-a-proibicao\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/br\/noticias\/usuarios-chineses-de-criptomoedas-ainda-conseguem-contornar-a-proibicao\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/noticias\/usuarios-chineses-de-criptomoedas-ainda-conseguem-contornar-a-proibicao\/#primaryimage","url":"https:\/\/cimg.co\/news\/67794\/52341\/adobestock-50026439.jpg","contentUrl":"https:\/\/cimg.co\/news\/67794\/52341\/adobestock-50026439.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/br\/noticias\/usuarios-chineses-de-criptomoedas-ainda-conseguem-contornar-a-proibicao\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/br\/"},{"@type":"ListItem","position":2,"name":"Usu\u00e1rios Chineses de Criptomoedas ainda Conseguem Contornar a Proibi\u00e7\u00e3o"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/br\/#website","url":"https:\/\/cryptonews.com\/br\/","name":"Cryptonews Portugal","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/br\/#organization","name":"Cryptonews Portugal","url":"https:\/\/cryptonews.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews Portugal"},"image":{"@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/67836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/comments?post=67836"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/67836\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/media?parent=67836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/categories?post=67836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/tags?post=67836"},{"taxonomy":"editores","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/editores?post=67836"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/sponsored_companies?post=67836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}