{"id":66987,"date":"2021-12-16T12:01:00","date_gmt":"2021-12-16T12:01:00","guid":{"rendered":"https:\/\/pt.cryptonews.com\/?p=66987"},"modified":"2022-07-04T07:57:15","modified_gmt":"2022-07-04T07:57:15","slug":"orgao-regulador-australiano-apoia-governo-a-regulamentar-criptomoedas","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/br\/noticias\/orgao-regulador-australiano-apoia-governo-a-regulamentar-criptomoedas\/","title":{"rendered":"\u00d3rg\u00e3o Regulador Australiano Apoia Governo a Regulamentar Criptomoedas"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/66967\/48723\/adobestock-alexander-1-1.jpg\" alt=\"\"><\/figure><p class=\"wp-block-paragraph\">Em uma tentativa de desenvolver novos regulamentos para criptomoedas e outros ativos digitais, os reguladores da Austr\u00e1lia &#8211; agindo por meio de seu \u00f3rg\u00e3o conjunto, o <strong>Conselho de Reguladores Financeiros<\/strong> (CFR) &#8211; divulgaram uma declara\u00e7\u00e3o na qual apoiam o plano do governo de implementar pagamentos e regulamenta\u00e7\u00e3o de criptoativos.<\/p><p>\u201cO Conselho analisou a evolu\u00e7\u00e3o da tecnologia e regula\u00e7\u00e3o financeira, incluindo os pagamentos e reformas de criptoativos anunciadas pelo Governo em 8 de dezembro\u201d, disse o comunicado.<\/p><p>Os membros do CFR incluem: <\/p><ul><li><strong>Autoridade de Regulamenta\u00e7\u00e3o Prudencial Australiana<\/strong> (APRA), que supervisiona bancos, sociedades de constru\u00e7\u00e3o, cooperativas de cr\u00e9dito, companhias de seguros gerais e de vida, sociedades amig\u00e1veis \u200b\u200be tamb\u00e9m a maior parte da ind\u00fastria de aposentadoria;<\/li><li><strong>Australian Securities and Investments Commission<\/strong> (ASIC), que atua como o regulador corporativo, de mercados e de servi\u00e7os financeiros do pa\u00eds;<\/li><li>O <strong>Banco de Reserva da Austr\u00e1lia<\/strong> (RBA);<\/li><li>E o <strong>Tesouro<\/strong>, uma ag\u00eancia central de pol\u00edtica encarregada de fornecer assessoria pol\u00edtica ao governo australiano.<\/li><\/ul><p>O CFR disse que,<\/p><blockquote><p><i>&#8220;[Ele] endossou os Termos de Refer\u00eancia para o Grupo de Trabalho sobre a Regulamenta\u00e7\u00e3o do Cripto-Ecossistema, que ajudar\u00e1 a progredir algumas das reformas de criptoativos.&#8221;<\/i><\/p><\/blockquote><p>De acordo com a declara\u00e7\u00e3o, um grupo de trabalho separado ir\u00e1 focar na elimina\u00e7\u00e3o de bancos nos setores de fintech, criptoativos e remessas e &#8220;o pedido do governo de aconselhamento sobre as causas subjacentes e respostas pol\u00edticas&#8221;. <\/p><p>O grupo de trabalho compreender\u00e1 as ag\u00eancias que fazem parte do conselho, bem como a <strong>Comiss\u00e3o Australiana de Concorr\u00eancia e Consumidores<\/strong>, o <strong>Centro Australiano de Relat\u00f3rios e An\u00e1lise de Transa\u00e7\u00f5es<\/strong> e o <strong>Departamento de Assuntos Internos<\/strong>, disse o comunicado.<\/p><p>Conforme relatado em 8 de dezembro, o Tesoureiro Federal Josh Frydenberg recentemente revelou planos do gabinete de legislar o que pode se tornar a maior reforma dos sistemas de pagamentos da Austr\u00e1lia em d\u00e9cadas. Ele disse que o objetivo era tirar &#8220;esta \u00e1rea das sombras e traz\u00ea-la [&#8230;] para uma estrutura regulat\u00f3ria&#8221;, j\u00e1 que o governo quer que as empresas que est\u00e3o comprando e vendendo criptomoedas sejam devidamente licenciadas para &#8220;uma maior certeza e seguran\u00e7a para aquelas pessoas que est\u00e3o negociando nessa \u00e1rea.\u201d <\/p><p>O gabinete tamb\u00e9m estava trabalhando com o<strong> Reserve Bank of Australia<\/strong>, o banco central do pa\u00eds, para &#8220;examinar a viabilidade&#8221; da introdu\u00e7\u00e3o de uma moeda digital de banco central (CBDC), disse Frydenberg.<\/p>","protected":false},"excerpt":{"rendered":"<p>Em uma tentativa de desenvolver novos regulamentos para criptomoedas e outros ativos digitais, os reguladores da Austr\u00e1lia &#8211; agindo por meio de seu \u00f3rg\u00e3o conjunto, o Conselho de Reguladores Financeiros (CFR) &#8211; divulgaram uma declara\u00e7\u00e3o na qual apoiam o plano do governo de implementar pagamentos e regulamenta\u00e7\u00e3o de criptoativos.\u201cO Conselho analisou a evolu\u00e7\u00e3o da tecnologia [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,6],"tags":[],"editores":[49],"sponsored_companies":[],"class_list":["post-66987","post","type-post","status-publish","format-standard","hentry","category-noticias","category-bitcoin-news","editores-jaroslaw-adamowski"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00d3rg\u00e3o Regulador Australiano Apoia o Governo na Cria\u00e7\u00e3o de Regulamenta\u00e7\u00f5es<\/title>\n<meta name=\"description\" content=\"O \u00f3rg\u00e3o regulador australiano manifestou seu apoio \u00e0s iniciativas do governo para regulamentar criptomoedas, com o objetivo de proteger consumidores e investidores.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/br\/noticias\/orgao-regulador-australiano-apoia-governo-a-regulamentar-criptomoedas\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00d3rg\u00e3o Regulador Australiano Apoia o Governo na Cria\u00e7\u00e3o de Regulamenta\u00e7\u00f5es\" \/>\n<meta property=\"og:description\" content=\"O \u00f3rg\u00e3o regulador australiano manifestou seu apoio \u00e0s iniciativas do governo para regulamentar criptomoedas, com o objetivo de proteger consumidores e investidores.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/br\/noticias\/orgao-regulador-australiano-apoia-governo-a-regulamentar-criptomoedas\/\" \/>\n<meta property=\"og:site_name\" content=\"CryptoNews Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-16T12:01:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-04T07:57:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/66967\/48723\/adobestock-alexander-1-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"\u00d3rg\u00e3o Regulador Australiano Apoia o Governo na Cria\u00e7\u00e3o de Regulamenta\u00e7\u00f5es\" \/>\n<meta name=\"twitter:description\" content=\"O \u00f3rg\u00e3o regulador australiano manifestou seu apoio \u00e0s iniciativas do governo para regulamentar criptomoedas, com o objetivo de proteger consumidores e investidores.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/66967\/48723\/adobestock-alexander-1-1.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00d3rg\u00e3o Regulador Australiano Apoia o Governo na Cria\u00e7\u00e3o de Regulamenta\u00e7\u00f5es","description":"O \u00f3rg\u00e3o regulador australiano manifestou seu apoio \u00e0s iniciativas do governo para regulamentar criptomoedas, com o objetivo de proteger consumidores e investidores.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/br\/noticias\/orgao-regulador-australiano-apoia-governo-a-regulamentar-criptomoedas\/","og_locale":"pt_BR","og_type":"article","og_title":"\u00d3rg\u00e3o Regulador Australiano Apoia o Governo na Cria\u00e7\u00e3o de Regulamenta\u00e7\u00f5es","og_description":"O \u00f3rg\u00e3o regulador australiano manifestou seu apoio \u00e0s iniciativas do governo para regulamentar criptomoedas, com o objetivo de proteger consumidores e investidores.","og_url":"https:\/\/cryptonews.com\/br\/noticias\/orgao-regulador-australiano-apoia-governo-a-regulamentar-criptomoedas\/","og_site_name":"CryptoNews Brasil","article_published_time":"2021-12-16T12:01:00+00:00","article_modified_time":"2022-07-04T07:57:15+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/66967\/48723\/adobestock-alexander-1-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"\u00d3rg\u00e3o Regulador Australiano Apoia o Governo na Cria\u00e7\u00e3o de Regulamenta\u00e7\u00f5es","twitter_description":"O \u00f3rg\u00e3o regulador australiano manifestou seu apoio \u00e0s iniciativas do governo para regulamentar criptomoedas, com o objetivo de proteger consumidores e investidores.","twitter_image":"https:\/\/cimg.co\/news\/66967\/48723\/adobestock-alexander-1-1.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/br\/noticias\/orgao-regulador-australiano-apoia-governo-a-regulamentar-criptomoedas\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/orgao-regulador-australiano-apoia-governo-a-regulamentar-criptomoedas\/"},"author":{"name":"caiomatsuiribeirokyy","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/person\/6586ec84b3e08829c939cecb8a29638e"},"headline":"\u00d3rg\u00e3o Regulador Australiano Apoia Governo a Regulamentar Criptomoedas","datePublished":"2021-12-16T12:01:00+00:00","dateModified":"2022-07-04T07:57:15+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/orgao-regulador-australiano-apoia-governo-a-regulamentar-criptomoedas\/"},"wordCount":422,"publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/orgao-regulador-australiano-apoia-governo-a-regulamentar-criptomoedas\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/66967\/48723\/adobestock-alexander-1-1.jpg","articleSection":["Noticias","Not\u00edcias de Bitcoin"],"inLanguage":"pt-BR","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/br\/noticias\/orgao-regulador-australiano-apoia-governo-a-regulamentar-criptomoedas\/","url":"https:\/\/cryptonews.com\/br\/noticias\/orgao-regulador-australiano-apoia-governo-a-regulamentar-criptomoedas\/","name":"\u00d3rg\u00e3o Regulador Australiano Apoia o Governo na Cria\u00e7\u00e3o de Regulamenta\u00e7\u00f5es","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/orgao-regulador-australiano-apoia-governo-a-regulamentar-criptomoedas\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/orgao-regulador-australiano-apoia-governo-a-regulamentar-criptomoedas\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/66967\/48723\/adobestock-alexander-1-1.jpg","datePublished":"2021-12-16T12:01:00+00:00","dateModified":"2022-07-04T07:57:15+00:00","description":"O \u00f3rg\u00e3o regulador australiano manifestou seu apoio \u00e0s iniciativas do governo para regulamentar criptomoedas, com o objetivo de proteger consumidores e investidores.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/orgao-regulador-australiano-apoia-governo-a-regulamentar-criptomoedas\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/br\/noticias\/orgao-regulador-australiano-apoia-governo-a-regulamentar-criptomoedas\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/noticias\/orgao-regulador-australiano-apoia-governo-a-regulamentar-criptomoedas\/#primaryimage","url":"https:\/\/cimg.co\/news\/66967\/48723\/adobestock-alexander-1-1.jpg","contentUrl":"https:\/\/cimg.co\/news\/66967\/48723\/adobestock-alexander-1-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/br\/noticias\/orgao-regulador-australiano-apoia-governo-a-regulamentar-criptomoedas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/br\/"},{"@type":"ListItem","position":2,"name":"\u00d3rg\u00e3o Regulador Australiano Apoia Governo a Regulamentar Criptomoedas"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/br\/#website","url":"https:\/\/cryptonews.com\/br\/","name":"Cryptonews Portugal","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/br\/#organization","name":"Cryptonews Portugal","url":"https:\/\/cryptonews.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews Portugal"},"image":{"@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/66987","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/comments?post=66987"}],"version-history":[{"count":1,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/66987\/revisions"}],"predecessor-version":[{"id":128185,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/66987\/revisions\/128185"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/media?parent=66987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/categories?post=66987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/tags?post=66987"},{"taxonomy":"editores","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/editores?post=66987"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/sponsored_companies?post=66987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}