{"id":66103,"date":"2021-12-06T11:30:00","date_gmt":"2021-12-06T11:30:00","guid":{"rendered":"https:\/\/pt.cryptonews.com\/?p=66103"},"modified":"2022-07-04T07:57:16","modified_gmt":"2022-07-04T07:57:16","slug":"bitmart-planeja-compensar-traders-de-criptomoedas-apos-hack-de-us-200-milhoes","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/br\/noticias\/bitmart-planeja-compensar-traders-de-criptomoedas-apos-hack-de-us-200-milhoes\/","title":{"rendered":"Bitmart Planeja Compensar Traders de Criptomoedas ap\u00f3s Hack de US$ 200 milh\u00f5es"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/66084\/45259\/adobestock-piter2121-1-1.jpg\" alt=\"\"><\/figure><p class=\"wp-block-paragraph\">A importante exchange de criptomoedas centralizada <strong>BitMart<\/strong>, que foi v&iacute;tima de um hack no fim de semana e perdeu aproximadamente US$ 200 milh&otilde;es em ativos digitais, pretende compensar os usu&aacute;rios afetados e retomar suas opera&ccedil;&otilde;es.<\/p><p>Sheldon Xia, o CEO da BitMart, revelou a not&iacute;cia por meio de uma s&eacute;rie de mensagens no Twitter, dizendo que a exchange &#8220;concluiu as verifica&ccedil;&otilde;es de seguran&ccedil;a iniciais e identificou os ativos afetados&#8221;. Ele acrescentou que a viola&ccedil;&atilde;o de seguran&ccedil;a foi o resultado de uma chave privada roubada que comprometeu duas das carteiras da bolsa, insistindo que outros ativos est&atilde;o seguros.<\/p><p>Xia tamb&eacute;m revelou que a exchange ir&aacute; compensar os usu&aacute;rios afetados, declarando:<\/p><blockquote><p><i>&#8220;Tamb&eacute;m estamos conversando com v&aacute;rias equipes de projeto para confirmar as solu&ccedil;&otilde;es mais razo&aacute;veis, como troca de tokens. Nenhum ativo dos usu&aacute;rios ser&aacute; prejudicado.&#8221;<\/i><\/p><\/blockquote><p>O CEO disse estar &#8220;confiante de que as fun&ccedil;&otilde;es de dep&oacute;sito e retirada come&ccedil;ar&atilde;o gradualmente em 7 de dezembro de 2021&#8221;. Ele tamb&eacute;m pretende conduzir uma AMA (pergunte-me qualquer coisa) &agrave; 1h UTC do dia 6 de dezembro para compartilhar mais informa&ccedil;&otilde;es sobre o incidente.&nbsp;<\/p><p>&#8220;Agora estamos fazendo o nosso melhor para recuperar as configura&ccedil;&otilde;es de seguran&ccedil;a e nossa opera&ccedil;&atilde;o. Precisamos de tempo para fazer os arranjos adequados e sua gentil compreens&atilde;o durante este per&iacute;odo ser&aacute; muito apreciada&#8221;, tuitou Xia.&nbsp;<\/p><p>A empresa de an&aacute;lise de seguran&ccedil;a <strong>Peckshield <\/strong>chamou a aten&ccedil;&atilde;o para o fluxo incomum de fundos saindo do BitMart, compilando uma lista de &#8220;ativos transferidos e seus valores&#8221;. A empresa observou que cerca de US$ 100 milh&otilde;es de fundos foram transferidos do Ethereum (ETH) blockchain e outros US$ 96 milh&otilde;es da Binance Smart Chain (BSC).<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/peckshield\/status\/1467310381073047552\"><\/oembed><\/figure><p>Seguindo o aviso de Peckshield, a Bitmart reconheceu que identificou &#8220;uma viola&ccedil;&atilde;o de seguran&ccedil;a em grande escala&#8221;, acrescentando que suspendeu temporariamente as retiradas.<\/p><p>O hacker trocou os ativos criptogr&aacute;ficos roubados, que incluem uma quantidade substancial de moedas de meme como dogecoin (DOGE) e shiba inu (SHIB), por ETH usando o agregador de exchanges descentralizadas (DEX) <strong>1inch<\/strong>.<\/p><p>O hacker tamb&eacute;m usou o protocolo de mixer descentralizado <strong>Tornado Cash <\/strong>para melhorar ainda mais a privacidade da transa&ccedil;&atilde;o, tornando ainda mais dif&iacute;cil rastrear os fundos roubados.<\/p><p>De acordo com o PeckShield, o hack foi um &#8220;caso bastante simples de transfer&ecirc;ncia, troca e lavagem&#8221;.<\/p><figure class=\"media\"><oembed url=\"https:\/\/twitter.com\/peckshield\/status\/1467318513971118083\"><\/oembed><\/figure><p>O volume de negocia&ccedil;&atilde;o de 24 horas no BitMart &eacute; atualmente de US$ 1,15 bilh&atilde;o, caindo dos US$ 1,46 bilh&atilde;o vistos ontem, de acordo com os dados da Coingecko. A plataforma encontra-se agora na 27&ordf; posi&ccedil;&atilde;o em volume di&aacute;rio de negocia&ccedil;&atilde;o.<\/p><p>Enquanto isso, na semana passada, a organiza&ccedil;&atilde;o aut&ocirc;noma descentralizada (DAO) <strong>Badger DAO <\/strong>perdeu mais de US$ 120 milh&otilde;es em um suposto ataque de front-end. De acordo com as transa&ccedil;&otilde;es Etherscan, um dos usu&aacute;rios afetados perdeu cerca de 897 WBTC (BTC empacotado) (mais de US$ 50 milh&otilde;es) com o hack. Relat&oacute;rios afirmam que o endere&ccedil;o pertencia &agrave; <strong>Celsius Network <\/strong>(CEL), uma grande empresa de criptomoedas.<\/p>","protected":false},"excerpt":{"rendered":"<p>A importante exchange de criptomoedas centralizada BitMart, que foi v&iacute;tima de um hack no fim de semana e perdeu aproximadamente US$ 200 milh&otilde;es em ativos digitais, pretende compensar os usu&aacute;rios afetados e retomar suas opera&ccedil;&otilde;es.Sheldon Xia, o CEO da BitMart, revelou a not&iacute;cia por meio de uma s&eacute;rie de mensagens no Twitter, dizendo que a [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,6],"tags":[],"editores":[884],"sponsored_companies":[],"class_list":["post-66103","post","type-post","status-publish","format-standard","hentry","category-noticias","category-bitcoin-news","editores-cryptonewscom"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bitmart Planeja Compensar Traders de Criptomoedas ap\u00f3s Hack de US$ 200 milh\u00f5es<\/title>\n<meta name=\"description\" content=\"A importante exchange de criptomoedas centralizada BitMart, que foi v&iacute;tima de um hack no fim de semana e perdeu aproximadamente US$ 200\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/br\/noticias\/bitmart-planeja-compensar-traders-de-criptomoedas-apos-hack-de-us-200-milhoes\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bitmart Planeja Compensar Traders de Criptomoedas ap\u00f3s Hack de US$ 200 milh\u00f5es\" \/>\n<meta property=\"og:description\" content=\"A importante exchange de criptomoedas centralizada BitMart, que foi v&iacute;tima de um hack no fim de semana e perdeu aproximadamente US$ 200\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/br\/noticias\/bitmart-planeja-compensar-traders-de-criptomoedas-apos-hack-de-us-200-milhoes\/\" \/>\n<meta property=\"og:site_name\" content=\"CryptoNews Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2021-12-06T11:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-04T07:57:16+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/66084\/45259\/adobestock-piter2121-1-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/66084\/45259\/adobestock-piter2121-1-1.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bitmart Planeja Compensar Traders de Criptomoedas ap\u00f3s Hack de US$ 200 milh\u00f5es","description":"A importante exchange de criptomoedas centralizada BitMart, que foi v&iacute;tima de um hack no fim de semana e perdeu aproximadamente US$ 200","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/br\/noticias\/bitmart-planeja-compensar-traders-de-criptomoedas-apos-hack-de-us-200-milhoes\/","og_locale":"pt_BR","og_type":"article","og_title":"Bitmart Planeja Compensar Traders de Criptomoedas ap\u00f3s Hack de US$ 200 milh\u00f5es","og_description":"A importante exchange de criptomoedas centralizada BitMart, que foi v&iacute;tima de um hack no fim de semana e perdeu aproximadamente US$ 200","og_url":"https:\/\/cryptonews.com\/br\/noticias\/bitmart-planeja-compensar-traders-de-criptomoedas-apos-hack-de-us-200-milhoes\/","og_site_name":"CryptoNews Brasil","article_published_time":"2021-12-06T11:30:00+00:00","article_modified_time":"2022-07-04T07:57:16+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/66084\/45259\/adobestock-piter2121-1-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_image":"https:\/\/cimg.co\/news\/66084\/45259\/adobestock-piter2121-1-1.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/br\/noticias\/bitmart-planeja-compensar-traders-de-criptomoedas-apos-hack-de-us-200-milhoes\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/bitmart-planeja-compensar-traders-de-criptomoedas-apos-hack-de-us-200-milhoes\/"},"author":{"name":"caiomatsuiribeirokyy","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/person\/6586ec84b3e08829c939cecb8a29638e"},"headline":"Bitmart Planeja Compensar Traders de Criptomoedas ap\u00f3s Hack de US$ 200 milh\u00f5es","datePublished":"2021-12-06T11:30:00+00:00","dateModified":"2022-07-04T07:57:16+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/bitmart-planeja-compensar-traders-de-criptomoedas-apos-hack-de-us-200-milhoes\/"},"wordCount":604,"publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/bitmart-planeja-compensar-traders-de-criptomoedas-apos-hack-de-us-200-milhoes\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/66084\/45259\/adobestock-piter2121-1-1.jpg","articleSection":["Noticias","Not\u00edcias de Bitcoin"],"inLanguage":"pt-BR","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/br\/noticias\/bitmart-planeja-compensar-traders-de-criptomoedas-apos-hack-de-us-200-milhoes\/","url":"https:\/\/cryptonews.com\/br\/noticias\/bitmart-planeja-compensar-traders-de-criptomoedas-apos-hack-de-us-200-milhoes\/","name":"Bitmart Planeja Compensar Traders de Criptomoedas ap\u00f3s Hack de US$ 200 milh\u00f5es","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/bitmart-planeja-compensar-traders-de-criptomoedas-apos-hack-de-us-200-milhoes\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/bitmart-planeja-compensar-traders-de-criptomoedas-apos-hack-de-us-200-milhoes\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/66084\/45259\/adobestock-piter2121-1-1.jpg","datePublished":"2021-12-06T11:30:00+00:00","dateModified":"2022-07-04T07:57:16+00:00","description":"A importante exchange de criptomoedas centralizada BitMart, que foi v&iacute;tima de um hack no fim de semana e perdeu aproximadamente US$ 200","breadcrumb":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/bitmart-planeja-compensar-traders-de-criptomoedas-apos-hack-de-us-200-milhoes\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/br\/noticias\/bitmart-planeja-compensar-traders-de-criptomoedas-apos-hack-de-us-200-milhoes\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/noticias\/bitmart-planeja-compensar-traders-de-criptomoedas-apos-hack-de-us-200-milhoes\/#primaryimage","url":"https:\/\/cimg.co\/news\/66084\/45259\/adobestock-piter2121-1-1.jpg","contentUrl":"https:\/\/cimg.co\/news\/66084\/45259\/adobestock-piter2121-1-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/br\/noticias\/bitmart-planeja-compensar-traders-de-criptomoedas-apos-hack-de-us-200-milhoes\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/br\/"},{"@type":"ListItem","position":2,"name":"Bitmart Planeja Compensar Traders de Criptomoedas ap\u00f3s Hack de US$ 200 milh\u00f5es"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/br\/#website","url":"https:\/\/cryptonews.com\/br\/","name":"Cryptonews Portugal","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/br\/#organization","name":"Cryptonews Portugal","url":"https:\/\/cryptonews.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews Portugal"},"image":{"@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/66103","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/comments?post=66103"}],"version-history":[{"count":0,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/66103\/revisions"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/media?parent=66103"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/categories?post=66103"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/tags?post=66103"},{"taxonomy":"editores","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/editores?post=66103"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/sponsored_companies?post=66103"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}