{"id":64721,"date":"2021-11-20T16:00:00","date_gmt":"2021-11-20T16:00:00","guid":{"rendered":"https:\/\/pt.cryptonews.com\/?p=64721"},"modified":"2022-07-04T07:57:17","modified_gmt":"2022-07-04T07:57:17","slug":"lei-de-infraestrutura-dos-eua-criptoverso-diz-que-ainda-ha-esperancas-mas-pode-ser-complicado","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/br\/noticias\/lei-de-infraestrutura-dos-eua-criptoverso-diz-que-ainda-ha-esperancas-mas-pode-ser-complicado\/","title":{"rendered":"Lei de Infraestrutura dos EUA: Criptoverso diz que Ainda h\u00e1 Esperan\u00e7as, mas pode ser Complicado"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" class=\"content-img\" src=\"https:\/\/cimg.co\/news\/64684\/40114\/source-screenshot-cnbc-television-youtube-media-library-original-718-405.jpg\" alt=\"\" width=\"718\"><\/figure><p class=\"wp-block-paragraph\">Os defensores de criptomoedas prometeram continuar lutando contra a controversa lei de infraestrutura dos EUA apesar do fato de que o presidente norte-americano, Joe Biden, sancionou a lei na segunda-feira, deixando as t\u00e3o criticadas cl\u00e1usulas de status de \u201ccorretor de ativos digitais\u201d intactas.<\/p><p>A comunidade criptogr\u00e1fica americana lutou tanto no Senado quanto no Congresso para alterar a defini\u00e7\u00e3o de &#8220;corretor&#8221; no projeto de lei, mas esses esfor\u00e7os agora parecem ter sido em v\u00e3o &#8211; o que significa que os mineradores e operadores de nodes agora podem ser for\u00e7ados a fazer c\u00e1lculos complicados de taxas. Isso \u00e9, a menos que o Tesouro decida refinar a legisla\u00e7\u00e3o.<\/p><p>No Senado, a bola j\u00e1 est\u00e1 rolando, com os pr\u00f3-cripto senadores Cynthia Lummis e Ron Wyden co-patrocinando um projeto de emenda \u00e0 lei.<\/p><p>Se bem-sucedida, a emenda retiraria algumas das cl\u00e1usulas mais problem\u00e1ticas da lei e excluiria explicitamente criptomoedas, participantes de staking, desenvolvedores de software de blockchain e desenvolvedores de carteira do status de corretor. Isso permitiria que eles evitassem o dep\u00f3sito de dados exaustivos para o<strong> Internal Revenue Service <\/strong>(IRS).<\/p><p>No Twitter, Lummis prometeu que \u201cSe no come\u00e7o voc\u00ea n\u00e3o tiver sucesso\u201d, ela e outros legisladores pr\u00f3-criptografia tentariam, tentariam e tentariam novamente fazer mudan\u00e7as na lei.<\/p><p>Em um comunicado \u00e0 imprensa, Wyden explicou:<\/p><blockquote>\r\n<p><i>\u201c\u00c9 extremamente importante proteger a inova\u00e7\u00e3o no espa\u00e7o de ativos digitais. Nosso projeto de lei deixa claro que os novos requisitos de relat\u00f3rio n\u00e3o se aplicam a indiv\u00edduos que desenvolvem tecnologia e carteiras de blockchain. Isso proteger\u00e1 a inova\u00e7\u00e3o americana e, ao mesmo tempo, garantir\u00e1 que aqueles que compram e vendem criptomoedas paguem os impostos que j\u00e1 devem\u201d.<\/i><\/p>\r\n<\/blockquote><p>Um triunfante Biden havia anteriormente chamado o projeto de &#8220;projeto de colarinho azul para reconstruir a Am\u00e9rica&#8221; \u200b\u200bem uma cerim\u00f4nia de assinatura na Casa Branca em Washington DC, informou a Reuters.<\/p><p>Em coment\u00e1rios compartilhados com o <i>Cryptonews.com<\/i>, Bill Tulloh, economista da <strong>Agoric<\/strong>, uma plataforma de contrato inteligente, chamou o ato de um &#8220;alerta para a criptografia da ind\u00fastria&#8221;, alegando que o setor agora &#8220;precisa se mobilizar para desfazer os danos causados por este projeto de lei e evitar maiores danos no futuro.\u201d<\/p><p>Tulloh chamou a lei de uma legisla\u00e7\u00e3o &#8220;concebida apressadamente e mal considerada&#8221;, acrescentando que &#8220;as receitas fiscais de curto prazo n\u00e3o devem sufocar o ritmo de inova\u00e7\u00e3o e descoberta necess\u00e1rio para o amadurecimento de uma ind\u00fastria jovem&#8221;.<\/p><p>Em uma nota mais otimista, o economista acrescentou que o an\u00fancio de Randall Quarles de que deixar\u00e1 o cargo de Governador do Conselho Federal &#8220;d\u00e1 ao presidente Biden a oportunidade de nomear um candidato que pode ter uma vis\u00e3o mais ampla sobre a promessa do com\u00e9rcio criptogr\u00e1fico&#8221;.<\/p><p>Amber Ghaddar, a cofundadora da <strong>AllianceBlock<\/strong>, uma empresa que visa fechar a lacuna entre as finan\u00e7as descentralizadas (DeFi) e as finan\u00e7as tradicionais, refletiu que as cl\u00e1usulas de corretor do ato eram &#8220;parcialmente&#8221; culpa da comunidade de criptografia &#8220;por n\u00e3o &#8216;centralizar&#8217; os esfor\u00e7os para n\u00e3o apenas fazer lobby, mas tamb\u00e9m explicar aos principais interessados \u200b\u200bcomo os protocolos funcionam\u201d.<\/p><p>Ghaddar aconselhou:<\/p><blockquote>\r\n<p><i>&#8220;Trabalhar de boa f\u00e9 com governos e reguladores em todo o mundo \u00e9 uma necessidade. N\u00e3o estamos aqui para sonegar nossos impostos ou lavar dinheiro como alguns parecem acreditar. Estou confiante de que h\u00e1 uma grande probabilidade de vermos emendas ou at\u00e9 mesmo aceitarmos &#8211; leis isoladas que ser\u00e3o aprovadas antes de 2024 [quando as disposi\u00e7\u00f5es dever\u00e3o entrar em vigor].\u201d<\/i><\/p>\r\n<\/blockquote><p>Mas ela acrescentou que &#8220;a aprova\u00e7\u00e3o&#8221; da nova lei &#8220;pode \u200b\u200bser muito complicada para os pequenos investidores&#8221;, explicando com o seguinte exemplo:<\/p><blockquote>\r\n<p><i>&#8220;Se um usu\u00e1rio de DeFi ou de autocust\u00f3dia transferir uma determinada quantia de sua carteira para a bolsa, a bolsa ir\u00e1 considerar o valor em d\u00f3lares enviado como uma venda. Mas ele n\u00e3o sabe quanto o cliente pagou inicialmente pelos tokens. O usu\u00e1rio pode ent\u00e3o acabar com um 1099-B [formul\u00e1rio fiscal] exagerado, for\u00e7ando-o a realmente contratar um contador ou reconciliar as contas manualmente.\u201d<\/i><\/p>\r\n<\/blockquote><p>A lei foi projetada para criar empregos em todos os EUA, injetando bilh\u00f5es de d\u00f3lares em projetos apoiados pelo governo estadual e local, envolvendo a repara\u00e7\u00e3o de estradas e o alargamento do acesso \u00e0 Internet de banda larga.<\/p>","protected":false},"excerpt":{"rendered":"<p>Os defensores de criptomoedas prometeram continuar lutando contra a controversa lei de infraestrutura dos EUA apesar do fato de que o presidente norte-americano, Joe Biden, sancionou a lei na segunda-feira, deixando as t\u00e3o criticadas cl\u00e1usulas de status de \u201ccorretor de ativos digitais\u201d intactas.A comunidade criptogr\u00e1fica americana lutou tanto no Senado quanto no Congresso para alterar [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,6],"tags":[],"editores":[884],"sponsored_companies":[],"class_list":["post-64721","post","type-post","status-publish","format-standard","hentry","category-noticias","category-bitcoin-news","editores-cryptonewscom"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Lei de Infraestrutura dos EUA: Esperan\u00e7as e Complica\u00e7\u00f5es<\/title>\n<meta name=\"description\" content=\"An\u00e1lise sobre a Lei de Infraestrutura dos EUA e suas implica\u00e7\u00f5es para o criptoverso. H\u00e1 esperan\u00e7as, mas tamb\u00e9m muitas complica\u00e7\u00f5es. Leia mais na Cryptonews.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/br\/noticias\/lei-de-infraestrutura-dos-eua-criptoverso-diz-que-ainda-ha-esperancas-mas-pode-ser-complicado\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Lei de Infraestrutura dos EUA: Esperan\u00e7as e Complica\u00e7\u00f5es\" \/>\n<meta property=\"og:description\" content=\"An\u00e1lise sobre a Lei de Infraestrutura dos EUA e suas implica\u00e7\u00f5es para o criptoverso. H\u00e1 esperan\u00e7as, mas tamb\u00e9m muitas complica\u00e7\u00f5es. Leia mais na Cryptonews.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/br\/noticias\/lei-de-infraestrutura-dos-eua-criptoverso-diz-que-ainda-ha-esperancas-mas-pode-ser-complicado\/\" \/>\n<meta property=\"og:site_name\" content=\"CryptoNews Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-20T16:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-04T07:57:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/64684\/40114\/source-screenshot-cnbc-television-youtube-media-library-original-718-405.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Lei de Infraestrutura dos EUA: Esperan\u00e7as e Complica\u00e7\u00f5es\" \/>\n<meta name=\"twitter:description\" content=\"An\u00e1lise sobre a Lei de Infraestrutura dos EUA e suas implica\u00e7\u00f5es para o criptoverso. H\u00e1 esperan\u00e7as, mas tamb\u00e9m muitas complica\u00e7\u00f5es. Leia mais na Cryptonews.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/64684\/40114\/source-screenshot-cnbc-television-youtube-media-library-original-718-405.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Lei de Infraestrutura dos EUA: Esperan\u00e7as e Complica\u00e7\u00f5es","description":"An\u00e1lise sobre a Lei de Infraestrutura dos EUA e suas implica\u00e7\u00f5es para o criptoverso. H\u00e1 esperan\u00e7as, mas tamb\u00e9m muitas complica\u00e7\u00f5es. Leia mais na Cryptonews.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/br\/noticias\/lei-de-infraestrutura-dos-eua-criptoverso-diz-que-ainda-ha-esperancas-mas-pode-ser-complicado\/","og_locale":"pt_BR","og_type":"article","og_title":"Lei de Infraestrutura dos EUA: Esperan\u00e7as e Complica\u00e7\u00f5es","og_description":"An\u00e1lise sobre a Lei de Infraestrutura dos EUA e suas implica\u00e7\u00f5es para o criptoverso. H\u00e1 esperan\u00e7as, mas tamb\u00e9m muitas complica\u00e7\u00f5es. Leia mais na Cryptonews.","og_url":"https:\/\/cryptonews.com\/br\/noticias\/lei-de-infraestrutura-dos-eua-criptoverso-diz-que-ainda-ha-esperancas-mas-pode-ser-complicado\/","og_site_name":"CryptoNews Brasil","article_published_time":"2021-11-20T16:00:00+00:00","article_modified_time":"2022-07-04T07:57:17+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/64684\/40114\/source-screenshot-cnbc-television-youtube-media-library-original-718-405.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Lei de Infraestrutura dos EUA: Esperan\u00e7as e Complica\u00e7\u00f5es","twitter_description":"An\u00e1lise sobre a Lei de Infraestrutura dos EUA e suas implica\u00e7\u00f5es para o criptoverso. H\u00e1 esperan\u00e7as, mas tamb\u00e9m muitas complica\u00e7\u00f5es. Leia mais na Cryptonews.","twitter_image":"https:\/\/cimg.co\/news\/64684\/40114\/source-screenshot-cnbc-television-youtube-media-library-original-718-405.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/br\/noticias\/lei-de-infraestrutura-dos-eua-criptoverso-diz-que-ainda-ha-esperancas-mas-pode-ser-complicado\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/lei-de-infraestrutura-dos-eua-criptoverso-diz-que-ainda-ha-esperancas-mas-pode-ser-complicado\/"},"author":{"name":"caiomatsuiribeirokyy","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/person\/6586ec84b3e08829c939cecb8a29638e"},"headline":"Lei de Infraestrutura dos EUA: Criptoverso diz que Ainda h\u00e1 Esperan\u00e7as, mas pode ser Complicado","datePublished":"2021-11-20T16:00:00+00:00","dateModified":"2022-07-04T07:57:17+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/lei-de-infraestrutura-dos-eua-criptoverso-diz-que-ainda-ha-esperancas-mas-pode-ser-complicado\/"},"wordCount":744,"publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/lei-de-infraestrutura-dos-eua-criptoverso-diz-que-ainda-ha-esperancas-mas-pode-ser-complicado\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/64684\/40114\/source-screenshot-cnbc-television-youtube-media-library-original-718-405.jpg","articleSection":["Noticias","Not\u00edcias de Bitcoin"],"inLanguage":"pt-BR","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/br\/noticias\/lei-de-infraestrutura-dos-eua-criptoverso-diz-que-ainda-ha-esperancas-mas-pode-ser-complicado\/","url":"https:\/\/cryptonews.com\/br\/noticias\/lei-de-infraestrutura-dos-eua-criptoverso-diz-que-ainda-ha-esperancas-mas-pode-ser-complicado\/","name":"Lei de Infraestrutura dos EUA: Esperan\u00e7as e Complica\u00e7\u00f5es","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/lei-de-infraestrutura-dos-eua-criptoverso-diz-que-ainda-ha-esperancas-mas-pode-ser-complicado\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/lei-de-infraestrutura-dos-eua-criptoverso-diz-que-ainda-ha-esperancas-mas-pode-ser-complicado\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/64684\/40114\/source-screenshot-cnbc-television-youtube-media-library-original-718-405.jpg","datePublished":"2021-11-20T16:00:00+00:00","dateModified":"2022-07-04T07:57:17+00:00","description":"An\u00e1lise sobre a Lei de Infraestrutura dos EUA e suas implica\u00e7\u00f5es para o criptoverso. H\u00e1 esperan\u00e7as, mas tamb\u00e9m muitas complica\u00e7\u00f5es. Leia mais na Cryptonews.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/lei-de-infraestrutura-dos-eua-criptoverso-diz-que-ainda-ha-esperancas-mas-pode-ser-complicado\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/br\/noticias\/lei-de-infraestrutura-dos-eua-criptoverso-diz-que-ainda-ha-esperancas-mas-pode-ser-complicado\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/noticias\/lei-de-infraestrutura-dos-eua-criptoverso-diz-que-ainda-ha-esperancas-mas-pode-ser-complicado\/#primaryimage","url":"https:\/\/cimg.co\/news\/64684\/40114\/source-screenshot-cnbc-television-youtube-media-library-original-718-405.jpg","contentUrl":"https:\/\/cimg.co\/news\/64684\/40114\/source-screenshot-cnbc-television-youtube-media-library-original-718-405.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/br\/noticias\/lei-de-infraestrutura-dos-eua-criptoverso-diz-que-ainda-ha-esperancas-mas-pode-ser-complicado\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/br\/"},{"@type":"ListItem","position":2,"name":"Lei de Infraestrutura dos EUA: Criptoverso diz que Ainda h\u00e1 Esperan\u00e7as, mas pode ser Complicado"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/br\/#website","url":"https:\/\/cryptonews.com\/br\/","name":"Cryptonews Portugal","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/br\/#organization","name":"Cryptonews Portugal","url":"https:\/\/cryptonews.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews Portugal"},"image":{"@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/64721","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/comments?post=64721"}],"version-history":[{"count":1,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/64721\/revisions"}],"predecessor-version":[{"id":124408,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/64721\/revisions\/124408"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/media?parent=64721"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/categories?post=64721"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/tags?post=64721"},{"taxonomy":"editores","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/editores?post=64721"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/sponsored_companies?post=64721"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}