{"id":64696,"date":"2021-11-16T12:35:00","date_gmt":"2021-11-16T12:35:00","guid":{"rendered":"https:\/\/pt.cryptonews.com\/?p=64696"},"modified":"2022-07-04T07:57:17","modified_gmt":"2022-07-04T07:57:17","slug":"apenas-1-dos-sul-coreanos-super-ricos-desejam-investir-em-criptomoedas-pesquisa","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/br\/noticias\/apenas-1-dos-sul-coreanos-super-ricos-desejam-investir-em-criptomoedas-pesquisa\/","title":{"rendered":"&#8216;Apenas 1% dos Sul-Coreanos Super-Ricos&#8217; Desejam Investir em Criptomoedas &#8211; Pesquisa"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/64619\/40005\/adobestock-bankrx-1.jpg\" alt=\"\" width=\"1200\"><\/figure><p class=\"wp-block-paragraph\">O investimento em criptomoedas atingiu n\u00edveis alt\u00edssimos na Coreia do Sul este ano, com os volumes de negocia\u00e7\u00e3o na maioria das exchanges quebrando todos os tipos de recordes, deixando os volumes do mercado de a\u00e7\u00f5es para tr\u00e1s. A quest\u00e3o das criptomoedas se infiltrou at\u00e9 mesmo na pol\u00edtica dominante, onde poderia determinar o resultado das elei\u00e7\u00f5es presidenciais do pr\u00f3ximo ano.<\/p><p>Mas apesar do fato de os candidatos estarem recorrendo a promessas t\u00e3o ambiciosas quanto poss\u00edvel, os super-ricos do pa\u00eds ainda est\u00e3o evitando moedas como o bitcoin (BTC) &#8211; em favor de mercados tradicionais como a bolsa de valores.<\/p><p>De acordo com o Munhwa Ilbo e o EToday, as descobertas foram publicadas em um relat\u00f3rio do <strong>KB Financial Group <\/strong>(o operador do <strong>Kookmin Bank<\/strong>), que questionou 400 sul-coreanos com mais de US$ 850.000 em ativos &#8211; e que, portanto, s\u00e3o classificados como &#8220;ricos&#8221;.<\/p><blockquote>\r\n<p><i>De acordo com o relat\u00f3rio, quando questionados se tinham alguma inten\u00e7\u00e3o de investir em criptoativos, 70% dos entrevistados responderam que \u201cn\u00e3o tinham inten\u00e7\u00e3o\u201d. Outros 26,8% n\u00e3o tinham certeza, com apenas 3,3% declarando que estavam &#8220;dispostos a investir&#8221;.<\/i><\/p>\r\n<\/blockquote><p>E os autores do relat\u00f3rio observaram que, na maioria dos casos, aqueles que responderam &#8220;n\u00e3o&#8221; \u00e0 pergunta se eles estavam dispostos a investir disseram que achavam que os investimentos em criptomoedas eram muito &#8220;arriscados&#8221;.<\/p><p>Os mais ricos pesquisados \u200b\u200b- aqueles com cerca de US$ 2,5 milh\u00f5es ou mais em ativos &#8211; pareciam os mais c\u00e9ticos de todos. Quase metade desse grupo demogr\u00e1fico declarou que \u201cn\u00e3o confia\u201d nas exchanges de criptomoedas. E cerca de um ter\u00e7o do mesmo grupo admitiu que sua pr\u00f3pria falta de conhecimento sobre como funcionam os mercados de criptografia os estava impedindo.<\/p><blockquote>\r\n<p><i>Nesse grupo, um m\u00edsero 1% afirmou ter interesse em fazer investimentos em criptomoedas.<\/i><\/p>\r\n<\/blockquote><p>Para os ricos, de longe a ferramenta de investimento mais popular era o mercado de a\u00e7\u00f5es, com mais de 60% afirmando que possu\u00edam a\u00e7\u00f5es em empresas listadas. Outros 19% afirmaram ter investido em fundos, com outros 15% investindo em \u201couro e joias\u201d.<\/p><p>Aqueles com ativos no valor de mais de US$ 2,5 milh\u00f5es tamb\u00e9m eram mais propensos a investir em empresas estrangeiras, com mais de um ter\u00e7o indicando uma prefer\u00eancia por empresas sediadas fora da Coreia do Sul. Os investidores de fundos optaram esmagadoramente por fundos chineses &#8211; provavelmente atra\u00eddos pelos n\u00fameros das altas taxas de crescimento dos \u00faltimos anos.<\/p>","protected":false},"excerpt":{"rendered":"<p>O investimento em criptomoedas atingiu n\u00edveis alt\u00edssimos na Coreia do Sul este ano, com os volumes de negocia\u00e7\u00e3o na maioria das exchanges quebrando todos os tipos de recordes, deixando os volumes do mercado de a\u00e7\u00f5es para tr\u00e1s. A quest\u00e3o das criptomoedas se infiltrou at\u00e9 mesmo na pol\u00edtica dominante, onde poderia determinar o resultado das elei\u00e7\u00f5es [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,6],"tags":[],"editores":[884],"sponsored_companies":[],"class_list":["post-64696","post","type-post","status-publish","format-standard","hentry","category-noticias","category-bitcoin-news","editores-cryptonewscom"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Apenas 1% dos Super-Ricos Sul-Coreanos Querem Cripto<\/title>\n<meta name=\"description\" content=\"Pesquisa revela que apenas 1% dos sul-coreanos super-ricos est\u00e3o interessados em investir em criptomoedas. Leia os detalhes dessa pesquisa na Cryptonews.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/br\/noticias\/apenas-1-dos-sul-coreanos-super-ricos-desejam-investir-em-criptomoedas-pesquisa\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apenas 1% dos Super-Ricos Sul-Coreanos Querem Cripto\" \/>\n<meta property=\"og:description\" content=\"Pesquisa revela que apenas 1% dos sul-coreanos super-ricos est\u00e3o interessados em investir em criptomoedas. Leia os detalhes dessa pesquisa na Cryptonews.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/br\/noticias\/apenas-1-dos-sul-coreanos-super-ricos-desejam-investir-em-criptomoedas-pesquisa\/\" \/>\n<meta property=\"og:site_name\" content=\"CryptoNews Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-16T12:35:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-04T07:57:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/64619\/40005\/adobestock-bankrx-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Apenas 1% dos Super-Ricos Sul-Coreanos Querem Cripto\" \/>\n<meta name=\"twitter:description\" content=\"Pesquisa revela que apenas 1% dos sul-coreanos super-ricos est\u00e3o interessados em investir em criptomoedas. Leia os detalhes dessa pesquisa na Cryptonews.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/64619\/40005\/adobestock-bankrx-1.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apenas 1% dos Super-Ricos Sul-Coreanos Querem Cripto","description":"Pesquisa revela que apenas 1% dos sul-coreanos super-ricos est\u00e3o interessados em investir em criptomoedas. Leia os detalhes dessa pesquisa na Cryptonews.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/br\/noticias\/apenas-1-dos-sul-coreanos-super-ricos-desejam-investir-em-criptomoedas-pesquisa\/","og_locale":"pt_BR","og_type":"article","og_title":"Apenas 1% dos Super-Ricos Sul-Coreanos Querem Cripto","og_description":"Pesquisa revela que apenas 1% dos sul-coreanos super-ricos est\u00e3o interessados em investir em criptomoedas. Leia os detalhes dessa pesquisa na Cryptonews.","og_url":"https:\/\/cryptonews.com\/br\/noticias\/apenas-1-dos-sul-coreanos-super-ricos-desejam-investir-em-criptomoedas-pesquisa\/","og_site_name":"CryptoNews Brasil","article_published_time":"2021-11-16T12:35:00+00:00","article_modified_time":"2022-07-04T07:57:17+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/64619\/40005\/adobestock-bankrx-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Apenas 1% dos Super-Ricos Sul-Coreanos Querem Cripto","twitter_description":"Pesquisa revela que apenas 1% dos sul-coreanos super-ricos est\u00e3o interessados em investir em criptomoedas. Leia os detalhes dessa pesquisa na Cryptonews.","twitter_image":"https:\/\/cimg.co\/news\/64619\/40005\/adobestock-bankrx-1.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/br\/noticias\/apenas-1-dos-sul-coreanos-super-ricos-desejam-investir-em-criptomoedas-pesquisa\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/apenas-1-dos-sul-coreanos-super-ricos-desejam-investir-em-criptomoedas-pesquisa\/"},"author":{"name":"caiomatsuiribeirokyy","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/person\/6586ec84b3e08829c939cecb8a29638e"},"headline":"&#8216;Apenas 1% dos Sul-Coreanos Super-Ricos&#8217; Desejam Investir em Criptomoedas &#8211; Pesquisa","datePublished":"2021-11-16T12:35:00+00:00","dateModified":"2022-07-04T07:57:17+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/apenas-1-dos-sul-coreanos-super-ricos-desejam-investir-em-criptomoedas-pesquisa\/"},"wordCount":422,"publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/apenas-1-dos-sul-coreanos-super-ricos-desejam-investir-em-criptomoedas-pesquisa\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/64619\/40005\/adobestock-bankrx-1.jpg","articleSection":["Noticias","Not\u00edcias de Bitcoin"],"inLanguage":"pt-BR","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/br\/noticias\/apenas-1-dos-sul-coreanos-super-ricos-desejam-investir-em-criptomoedas-pesquisa\/","url":"https:\/\/cryptonews.com\/br\/noticias\/apenas-1-dos-sul-coreanos-super-ricos-desejam-investir-em-criptomoedas-pesquisa\/","name":"Apenas 1% dos Super-Ricos Sul-Coreanos Querem Cripto","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/apenas-1-dos-sul-coreanos-super-ricos-desejam-investir-em-criptomoedas-pesquisa\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/apenas-1-dos-sul-coreanos-super-ricos-desejam-investir-em-criptomoedas-pesquisa\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/64619\/40005\/adobestock-bankrx-1.jpg","datePublished":"2021-11-16T12:35:00+00:00","dateModified":"2022-07-04T07:57:17+00:00","description":"Pesquisa revela que apenas 1% dos sul-coreanos super-ricos est\u00e3o interessados em investir em criptomoedas. Leia os detalhes dessa pesquisa na Cryptonews.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/apenas-1-dos-sul-coreanos-super-ricos-desejam-investir-em-criptomoedas-pesquisa\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/br\/noticias\/apenas-1-dos-sul-coreanos-super-ricos-desejam-investir-em-criptomoedas-pesquisa\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/noticias\/apenas-1-dos-sul-coreanos-super-ricos-desejam-investir-em-criptomoedas-pesquisa\/#primaryimage","url":"https:\/\/cimg.co\/news\/64619\/40005\/adobestock-bankrx-1.jpg","contentUrl":"https:\/\/cimg.co\/news\/64619\/40005\/adobestock-bankrx-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/br\/noticias\/apenas-1-dos-sul-coreanos-super-ricos-desejam-investir-em-criptomoedas-pesquisa\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/br\/"},{"@type":"ListItem","position":2,"name":"&#8216;Apenas 1% dos Sul-Coreanos Super-Ricos&#8217; Desejam Investir em Criptomoedas &#8211; Pesquisa"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/br\/#website","url":"https:\/\/cryptonews.com\/br\/","name":"Cryptonews Portugal","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/br\/#organization","name":"Cryptonews Portugal","url":"https:\/\/cryptonews.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews Portugal"},"image":{"@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/64696","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/comments?post=64696"}],"version-history":[{"count":1,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/64696\/revisions"}],"predecessor-version":[{"id":124407,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/64696\/revisions\/124407"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/media?parent=64696"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/categories?post=64696"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/tags?post=64696"},{"taxonomy":"editores","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/editores?post=64696"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/sponsored_companies?post=64696"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}