{"id":64647,"date":"2021-11-20T14:30:00","date_gmt":"2021-11-20T14:30:00","guid":{"rendered":"https:\/\/pt.cryptonews.com\/?p=64647"},"modified":"2022-07-04T07:57:17","modified_gmt":"2022-07-04T07:57:17","slug":"16-dos-americanos-pesquisados-utilizam-criptomoedas-sendo-comerciantes-e-usuarios-think-tank","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/br\/noticias\/16-dos-americanos-pesquisados-utilizam-criptomoedas-sendo-comerciantes-e-usuarios-think-tank\/","title":{"rendered":"16% dos Americanos Pesquisados Utilizam Criptomoedas, Sendo Comerciantes e Usu\u00e1rios &#8211; Think Tank"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/64496\/39477\/adobestock-goami-1.jpg\" alt=\"\" width=\"1200\" class=\"content-img\"><\/figure><p class=\"wp-block-paragraph\">As criptomoedas est\u00e3o rapidamente ganhando popularidade entre os adultos dos EUA, com 16% dos entrevistados admitindo que investiram, negociaram ou usaram criptomoedas, de acordo com uma recente pesquisa da think tank apartid\u00e1ria <strong>Pew Research Center<\/strong>. <\/p><p>Em 2015, respondendo a uma pesquisa anterior que era voltada para bitcoin (BTC), apenas 1% dos pesquisados \u200b\u200bdeu a mesma resposta em rela\u00e7\u00e3o \u00e0 criptomoeda.<\/p><p>Esta pesquisa foi realizada entre 10.371 adultos norte-americanos de 13 a 19 de setembro de 2021, afirma o centro.<\/p><p>O think tank diz que sua \u00faltima pesquisa mostra que certos grupos demogr\u00e1ficos s\u00e3o particularmente propensos a declarar que usaram criptomoedas.<\/p><p>Cerca de tr\u00eas em cada dez americanos, ou 31%, com idades entre 18 e 29 anos, dizem que j\u00e1 investiram, negociaram ou usaram uma criptomoeda como BTC ou ethereum (ETH), em compara\u00e7\u00e3o com parcelas menores de adultos em grupos de idade mais avan\u00e7ada, disse o Centro de Pesquisa Pew.<\/p><p>Al\u00e9m disso, eles descobriram que os homens t\u00eam cerca de duas vezes mais probabilidade do que as mulheres de dizer que j\u00e1 usaram uma criptomoeda: 22% vs. 10%.<\/p><p>As diferen\u00e7as identificadas s\u00e3o especialmente pronunciadas quando se considera a combina\u00e7\u00e3o de idade e g\u00eanero, conforme indicado pela pesquisa.<\/p><blockquote><p><i>\u201cCerca de quatro em cada dez homens com idades entre 18 e 29 (43%), por exemplo, dizem que j\u00e1 investiram, trocaram ou usaram uma criptomoeda, em compara\u00e7\u00e3o com 19% das mulheres na mesma faixa et\u00e1ria. Entre homens e mulheres, a probabilidade de terem investido, negociado ou usado criptomoedas diminui com a idade\u201d, disse o centro.<\/i><\/p><\/blockquote><p>A pesquisa mostra que os adultos asi\u00e1ticos, negros e hisp\u00e2nicos representam grupos que t\u00eam mais probabilidade de dizer que j\u00e1 investiram, negociaram ou usaram uma criptomoeda do que os adultos brancos. <\/p><p>Ao mesmo tempo, n\u00e3o h\u00e1 diferen\u00e7as estatisticamente significativas que resultariam dos n\u00edveis de renda familiar. Os investidores, comerciantes e usu\u00e1rios de criptomoedas representam 17% dos entrevistados de alta e m\u00e9dia renda e 15% dos entrevistados de baixa renda.<\/p><p>\u201cEmbora a maioria dos grupos demogr\u00e1ficos diga ter ouvido pelo menos um pouco sobre criptomoeda, a\u00e7\u00f5es menores afirmam ter ouvido muito&#8221;, de acordo com o think tank, acrescentando:<\/p><blockquote><p><i>&#8220;Por exemplo, adultos com menos de 50 anos (31%) e homens (35%) t\u00eam mais probabilidade do que os americanos mais velhos (16%) e as mulheres (15%), respectivamente, de dizer que j\u00e1 ouviram bastante sobre\u201d<\/i><\/p><\/blockquote>","protected":false},"excerpt":{"rendered":"<p>As criptomoedas est\u00e3o rapidamente ganhando popularidade entre os adultos dos EUA, com 16% dos entrevistados admitindo que investiram, negociaram ou usaram criptomoedas, de acordo com uma recente pesquisa da think tank apartid\u00e1ria Pew Research Center. Em 2015, respondendo a uma pesquisa anterior que era voltada para bitcoin (BTC), apenas 1% dos pesquisados \u200b\u200bdeu a mesma [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,6],"tags":[],"editores":[49],"sponsored_companies":[],"class_list":["post-64647","post","type-post","status-publish","format-standard","hentry","category-noticias","category-bitcoin-news","editores-jaroslaw-adamowski"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Americanos Usam Criptomoedas: Pesquisa Revela Tend\u00eancias e Uso<\/title>\n<meta name=\"description\" content=\"Uma pesquisa revela que 16% dos americanos utilizam criptomoedas, tanto como comerciantes quanto usu\u00e1rios. Entenda as tend\u00eancias e o impacto dessa ado\u00e7\u00e3o crescente.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/br\/noticias\/16-dos-americanos-pesquisados-utilizam-criptomoedas-sendo-comerciantes-e-usuarios-think-tank\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Americanos Usam Criptomoedas: Pesquisa Revela Tend\u00eancias e Uso\" \/>\n<meta property=\"og:description\" content=\"Uma pesquisa revela que 16% dos americanos utilizam criptomoedas, tanto como comerciantes quanto usu\u00e1rios. Entenda as tend\u00eancias e o impacto dessa ado\u00e7\u00e3o crescente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/br\/noticias\/16-dos-americanos-pesquisados-utilizam-criptomoedas-sendo-comerciantes-e-usuarios-think-tank\/\" \/>\n<meta property=\"og:site_name\" content=\"CryptoNews Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2021-11-20T14:30:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-04T07:57:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/64496\/39477\/adobestock-goami-1.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Americanos Usam Criptomoedas: Pesquisa Revela Tend\u00eancias e Uso\" \/>\n<meta name=\"twitter:description\" content=\"Uma pesquisa revela que 16% dos americanos utilizam criptomoedas, tanto como comerciantes quanto usu\u00e1rios. Entenda as tend\u00eancias e o impacto dessa ado\u00e7\u00e3o crescente.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/64496\/39477\/adobestock-goami-1.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Americanos Usam Criptomoedas: Pesquisa Revela Tend\u00eancias e Uso","description":"Uma pesquisa revela que 16% dos americanos utilizam criptomoedas, tanto como comerciantes quanto usu\u00e1rios. Entenda as tend\u00eancias e o impacto dessa ado\u00e7\u00e3o crescente.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/br\/noticias\/16-dos-americanos-pesquisados-utilizam-criptomoedas-sendo-comerciantes-e-usuarios-think-tank\/","og_locale":"pt_BR","og_type":"article","og_title":"Americanos Usam Criptomoedas: Pesquisa Revela Tend\u00eancias e Uso","og_description":"Uma pesquisa revela que 16% dos americanos utilizam criptomoedas, tanto como comerciantes quanto usu\u00e1rios. Entenda as tend\u00eancias e o impacto dessa ado\u00e7\u00e3o crescente.","og_url":"https:\/\/cryptonews.com\/br\/noticias\/16-dos-americanos-pesquisados-utilizam-criptomoedas-sendo-comerciantes-e-usuarios-think-tank\/","og_site_name":"CryptoNews Brasil","article_published_time":"2021-11-20T14:30:00+00:00","article_modified_time":"2022-07-04T07:57:17+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/64496\/39477\/adobestock-goami-1.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Americanos Usam Criptomoedas: Pesquisa Revela Tend\u00eancias e Uso","twitter_description":"Uma pesquisa revela que 16% dos americanos utilizam criptomoedas, tanto como comerciantes quanto usu\u00e1rios. Entenda as tend\u00eancias e o impacto dessa ado\u00e7\u00e3o crescente.","twitter_image":"https:\/\/cimg.co\/news\/64496\/39477\/adobestock-goami-1.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/br\/noticias\/16-dos-americanos-pesquisados-utilizam-criptomoedas-sendo-comerciantes-e-usuarios-think-tank\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/16-dos-americanos-pesquisados-utilizam-criptomoedas-sendo-comerciantes-e-usuarios-think-tank\/"},"author":{"name":"caiomatsuiribeirokyy","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/person\/6586ec84b3e08829c939cecb8a29638e"},"headline":"16% dos Americanos Pesquisados Utilizam Criptomoedas, Sendo Comerciantes e Usu\u00e1rios &#8211; Think Tank","datePublished":"2021-11-20T14:30:00+00:00","dateModified":"2022-07-04T07:57:17+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/16-dos-americanos-pesquisados-utilizam-criptomoedas-sendo-comerciantes-e-usuarios-think-tank\/"},"wordCount":398,"publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/16-dos-americanos-pesquisados-utilizam-criptomoedas-sendo-comerciantes-e-usuarios-think-tank\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/64496\/39477\/adobestock-goami-1.jpg","articleSection":["Noticias","Not\u00edcias de Bitcoin"],"inLanguage":"pt-BR","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/br\/noticias\/16-dos-americanos-pesquisados-utilizam-criptomoedas-sendo-comerciantes-e-usuarios-think-tank\/","url":"https:\/\/cryptonews.com\/br\/noticias\/16-dos-americanos-pesquisados-utilizam-criptomoedas-sendo-comerciantes-e-usuarios-think-tank\/","name":"Americanos Usam Criptomoedas: Pesquisa Revela Tend\u00eancias e Uso","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/16-dos-americanos-pesquisados-utilizam-criptomoedas-sendo-comerciantes-e-usuarios-think-tank\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/16-dos-americanos-pesquisados-utilizam-criptomoedas-sendo-comerciantes-e-usuarios-think-tank\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/64496\/39477\/adobestock-goami-1.jpg","datePublished":"2021-11-20T14:30:00+00:00","dateModified":"2022-07-04T07:57:17+00:00","description":"Uma pesquisa revela que 16% dos americanos utilizam criptomoedas, tanto como comerciantes quanto usu\u00e1rios. Entenda as tend\u00eancias e o impacto dessa ado\u00e7\u00e3o crescente.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/16-dos-americanos-pesquisados-utilizam-criptomoedas-sendo-comerciantes-e-usuarios-think-tank\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/br\/noticias\/16-dos-americanos-pesquisados-utilizam-criptomoedas-sendo-comerciantes-e-usuarios-think-tank\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/noticias\/16-dos-americanos-pesquisados-utilizam-criptomoedas-sendo-comerciantes-e-usuarios-think-tank\/#primaryimage","url":"https:\/\/cimg.co\/news\/64496\/39477\/adobestock-goami-1.jpg","contentUrl":"https:\/\/cimg.co\/news\/64496\/39477\/adobestock-goami-1.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/br\/noticias\/16-dos-americanos-pesquisados-utilizam-criptomoedas-sendo-comerciantes-e-usuarios-think-tank\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/br\/"},{"@type":"ListItem","position":2,"name":"16% dos Americanos Pesquisados Utilizam Criptomoedas, Sendo Comerciantes e Usu\u00e1rios &#8211; Think Tank"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/br\/#website","url":"https:\/\/cryptonews.com\/br\/","name":"Cryptonews Portugal","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/br\/#organization","name":"Cryptonews Portugal","url":"https:\/\/cryptonews.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews Portugal"},"image":{"@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/64647","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/comments?post=64647"}],"version-history":[{"count":1,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/64647\/revisions"}],"predecessor-version":[{"id":125879,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/64647\/revisions\/125879"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/media?parent=64647"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/categories?post=64647"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/tags?post=64647"},{"taxonomy":"editores","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/editores?post=64647"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/sponsored_companies?post=64647"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}