{"id":62291,"date":"2021-10-16T15:00:00","date_gmt":"2021-10-16T15:00:00","guid":{"rendered":"https:\/\/pt.cryptonews.com\/?p=62291"},"modified":"2022-07-04T07:57:18","modified_gmt":"2022-07-04T07:57:18","slug":"os-usuarios-da-bakkt-poderao-gastar-bitcoin-com-o-google-pay","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/br\/noticias\/os-usuarios-da-bakkt-poderao-gastar-bitcoin-com-o-google-pay\/","title":{"rendered":"Os usu\u00e1rios da Bakkt poder\u00e3o gastar Bitcoin com o Google Pay"},"content":{"rendered":"<figure class=\"image\"><img decoding=\"async\" src=\"https:\/\/cimg.co\/news\/62072\/30705\/33dee2b561.jpg\" alt=\"\" width=\"900\" class=\"content-img\"><\/figure><p class=\"wp-block-paragraph\">O mercado de ativos digitais <strong>Bakkt <\/strong>disse que seus clientes poder\u00e3o adicionar seus cart\u00f5es de d\u00e9bito Bakkt Visa ao Google Pay para compras di\u00e1rias.<\/p><p>\u201cAtivos digitais como Bitcoin ser\u00e3o convertidos em moeda fiduci\u00e1ria para que esses pagamentos ocorram\u201d, disse a empresa.<\/p><p>Bakkt tamb\u00e9m disse que escolheu o Google Cloud como um provedor de nuvem preferencial. Dito isso, eles planejam comercializar suas solu\u00e7\u00f5es que ser\u00e3o fornecidas pelo Google Cloud para \u201cvarejistas e comerciantes l\u00edderes nos Estados Unidos\u201d.<\/p><p>A empresa planeja alavancar ainda mais as ferramentas do Google Cloud criando novas an\u00e1lises em sua plataforma, junto com intelig\u00eancia artificial (IA), aprendizado de m\u00e1quina (ML) e funcionalidade de geolocaliza\u00e7\u00e3o, a fim de \u201cextrair informa\u00e7\u00f5es de neg\u00f3cios profundas e com reconhecimento de localiza\u00e7\u00e3o\u201d. Esses insights, ent\u00e3o, fornecer\u00e3o op\u00e7\u00f5es de resgate de fidelidade expandidas para os consumidores da Bakkt, bem como padr\u00f5es de comportamento do consumidor para os parceiros da Bakkt, disseram eles.<\/p><p>Segundo o CEO da Bakkt Gavin Michael, \u201ca parceria com o Google Cloud nos permitir\u00e1 continuar a construir uma plataforma inovadora e de primeira classe que pode, sem d\u00favida, ser dimensionada para atender \u00e0s necessidades de milh\u00f5es de usu\u00e1rios\u201d.<\/p><p>Enquanto isso, no final de setembro, a plataforma de criptomoedas da<strong> Intercontinental Exchange Inc.<\/strong>, fez parceria com a <strong>Choice Hotels International <\/strong>para expandir a utilidade do programa de recompensas da empresa, Choice Privileges, por meio do Bakkt App &#8211; que foi lan\u00e7ado em mar\u00e7o.<\/p><p>Antes disso, no in\u00edcio de agosto, eles fizeram parceria com o restaurante de servi\u00e7o r\u00e1pido <strong>Quiznos <\/strong>para lan\u00e7ar seu primeiro projeto piloto de localiza\u00e7\u00e3o f\u00edsica, permitindo que os clientes da Quiznos pagassem com BTC. <\/p>","protected":false},"excerpt":{"rendered":"<p>O mercado de ativos digitais Bakkt disse que seus clientes poder\u00e3o adicionar seus cart\u00f5es de d\u00e9bito Bakkt Visa ao Google Pay para compras di\u00e1rias.\u201cAtivos digitais como Bitcoin ser\u00e3o convertidos em moeda fiduci\u00e1ria para que esses pagamentos ocorram\u201d, disse a empresa.Bakkt tamb\u00e9m disse que escolheu o Google Cloud como um provedor de nuvem preferencial. Dito isso, [&hellip;]<\/p>\n","protected":false},"author":30,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1,6],"tags":[],"editores":[884],"sponsored_companies":[],"class_list":["post-62291","post","type-post","status-publish","format-standard","hentry","category-noticias","category-bitcoin-news","editores-cryptonewscom"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Usu\u00e1rios da Bakkt Poder\u00e3o Gastar Bitcoin com o Google Pay<\/title>\n<meta name=\"description\" content=\"Usu\u00e1rios da Bakkt agora podem gastar Bitcoin com o Google Pay. Descubra como esta integra\u00e7\u00e3o expande as op\u00e7\u00f5es de pagamento e o impacto positivo para o uso de criptomoedas.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/br\/noticias\/os-usuarios-da-bakkt-poderao-gastar-bitcoin-com-o-google-pay\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Usu\u00e1rios da Bakkt Poder\u00e3o Gastar Bitcoin com o Google Pay\" \/>\n<meta property=\"og:description\" content=\"Usu\u00e1rios da Bakkt agora podem gastar Bitcoin com o Google Pay. Descubra como esta integra\u00e7\u00e3o expande as op\u00e7\u00f5es de pagamento e o impacto positivo para o uso de criptomoedas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/br\/noticias\/os-usuarios-da-bakkt-poderao-gastar-bitcoin-com-o-google-pay\/\" \/>\n<meta property=\"og:site_name\" content=\"CryptoNews Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2021-10-16T15:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-04T07:57:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/news\/62072\/30705\/33dee2b561.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Usu\u00e1rios da Bakkt Poder\u00e3o Gastar Bitcoin com o Google Pay\" \/>\n<meta name=\"twitter:description\" content=\"Usu\u00e1rios da Bakkt agora podem gastar Bitcoin com o Google Pay. Descubra como esta integra\u00e7\u00e3o expande as op\u00e7\u00f5es de pagamento e o impacto positivo para o uso de criptomoedas.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/news\/62072\/30705\/33dee2b561.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Usu\u00e1rios da Bakkt Poder\u00e3o Gastar Bitcoin com o Google Pay","description":"Usu\u00e1rios da Bakkt agora podem gastar Bitcoin com o Google Pay. Descubra como esta integra\u00e7\u00e3o expande as op\u00e7\u00f5es de pagamento e o impacto positivo para o uso de criptomoedas.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/br\/noticias\/os-usuarios-da-bakkt-poderao-gastar-bitcoin-com-o-google-pay\/","og_locale":"pt_BR","og_type":"article","og_title":"Usu\u00e1rios da Bakkt Poder\u00e3o Gastar Bitcoin com o Google Pay","og_description":"Usu\u00e1rios da Bakkt agora podem gastar Bitcoin com o Google Pay. Descubra como esta integra\u00e7\u00e3o expande as op\u00e7\u00f5es de pagamento e o impacto positivo para o uso de criptomoedas.","og_url":"https:\/\/cryptonews.com\/br\/noticias\/os-usuarios-da-bakkt-poderao-gastar-bitcoin-com-o-google-pay\/","og_site_name":"CryptoNews Brasil","article_published_time":"2021-10-16T15:00:00+00:00","article_modified_time":"2022-07-04T07:57:18+00:00","og_image":[{"url":"https:\/\/cimg.co\/news\/62072\/30705\/33dee2b561.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_title":"Usu\u00e1rios da Bakkt Poder\u00e3o Gastar Bitcoin com o Google Pay","twitter_description":"Usu\u00e1rios da Bakkt agora podem gastar Bitcoin com o Google Pay. Descubra como esta integra\u00e7\u00e3o expande as op\u00e7\u00f5es de pagamento e o impacto positivo para o uso de criptomoedas.","twitter_image":"https:\/\/cimg.co\/news\/62072\/30705\/33dee2b561.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/br\/noticias\/os-usuarios-da-bakkt-poderao-gastar-bitcoin-com-o-google-pay\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/os-usuarios-da-bakkt-poderao-gastar-bitcoin-com-o-google-pay\/"},"author":{"name":"caiomatsuiribeirokyy","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/person\/6586ec84b3e08829c939cecb8a29638e"},"headline":"Os usu\u00e1rios da Bakkt poder\u00e3o gastar Bitcoin com o Google Pay","datePublished":"2021-10-16T15:00:00+00:00","dateModified":"2022-07-04T07:57:18+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/os-usuarios-da-bakkt-poderao-gastar-bitcoin-com-o-google-pay\/"},"wordCount":310,"publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/os-usuarios-da-bakkt-poderao-gastar-bitcoin-com-o-google-pay\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/62072\/30705\/33dee2b561.jpg","articleSection":["Noticias","Not\u00edcias de Bitcoin"],"inLanguage":"pt-BR","copyrightYear":"2021","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/br\/noticias\/os-usuarios-da-bakkt-poderao-gastar-bitcoin-com-o-google-pay\/","url":"https:\/\/cryptonews.com\/br\/noticias\/os-usuarios-da-bakkt-poderao-gastar-bitcoin-com-o-google-pay\/","name":"Usu\u00e1rios da Bakkt Poder\u00e3o Gastar Bitcoin com o Google Pay","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/os-usuarios-da-bakkt-poderao-gastar-bitcoin-com-o-google-pay\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/os-usuarios-da-bakkt-poderao-gastar-bitcoin-com-o-google-pay\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/news\/62072\/30705\/33dee2b561.jpg","datePublished":"2021-10-16T15:00:00+00:00","dateModified":"2022-07-04T07:57:18+00:00","description":"Usu\u00e1rios da Bakkt agora podem gastar Bitcoin com o Google Pay. Descubra como esta integra\u00e7\u00e3o expande as op\u00e7\u00f5es de pagamento e o impacto positivo para o uso de criptomoedas.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/os-usuarios-da-bakkt-poderao-gastar-bitcoin-com-o-google-pay\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/br\/noticias\/os-usuarios-da-bakkt-poderao-gastar-bitcoin-com-o-google-pay\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/noticias\/os-usuarios-da-bakkt-poderao-gastar-bitcoin-com-o-google-pay\/#primaryimage","url":"https:\/\/cimg.co\/news\/62072\/30705\/33dee2b561.jpg","contentUrl":"https:\/\/cimg.co\/news\/62072\/30705\/33dee2b561.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/br\/noticias\/os-usuarios-da-bakkt-poderao-gastar-bitcoin-com-o-google-pay\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/br\/"},{"@type":"ListItem","position":2,"name":"Os usu\u00e1rios da Bakkt poder\u00e3o gastar Bitcoin com o Google Pay"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/br\/#website","url":"https:\/\/cryptonews.com\/br\/","name":"Cryptonews Portugal","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/br\/#organization","name":"Cryptonews Portugal","url":"https:\/\/cryptonews.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews Portugal"},"image":{"@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/62291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/users\/30"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/comments?post=62291"}],"version-history":[{"count":1,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/62291\/revisions"}],"predecessor-version":[{"id":125872,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/62291\/revisions\/125872"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/media?parent=62291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/categories?post=62291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/tags?post=62291"},{"taxonomy":"editores","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/editores?post=62291"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/sponsored_companies?post=62291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}