{"id":155972,"date":"2025-12-07T20:44:00","date_gmt":"2025-12-07T20:44:00","guid":{"rendered":"https:\/\/cryptonews.com\/br\/?p=155972"},"modified":"2025-12-08T03:26:06","modified_gmt":"2025-12-08T03:26:06","slug":"bitcoin-hoje-corte-juros-fed","status":"publish","type":"post","link":"https:\/\/cryptonews.com\/br\/noticias\/bitcoin-hoje-corte-juros-fed\/","title":{"rendered":"Bitcoin hoje: corte de juros pelo Fed impulsiona retomada do BTC"},"content":{"rendered":"<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"574\" src=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/13\/2025\/12\/08032203\/image-9-1024x574.jpg\" alt=\"\" class=\"wp-image-155975\" srcset=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/13\/2025\/12\/08032203\/image-9-1024x574.jpg 1024w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/13\/2025\/12\/08032203\/image-9-300x168.jpg 300w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/13\/2025\/12\/08032203\/image-9-768x431.jpg 768w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/13\/2025\/12\/08032203\/image-9-450x252.jpg 450w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/13\/2025\/12\/08032203\/image-9.jpg 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\"><\/figure><p class=\"wp-block-paragraph\">O Polymarket atribui 92% de probabilidade para um corte de 25 pontos-base pelo Fed na pr\u00f3xima semana. Isso muda a an\u00e1lise do pre\u00e7o do Bitcoin (BTC) de um rompimento bearish para um poss\u00edvel retorno, j\u00e1 que indicadores t\u00e9cnicos mostram impulso de breakout.<\/p><p class=\"wp-block-paragraph\">O FOMC se re\u00fane na pr\u00f3xima ter\u00e7a-feira (9\/12). Assim, o mercado aposta quase de forma un\u00e2nime em uma postura dovish do Fed.<\/p><p class=\"wp-block-paragraph\">Esse cen\u00e1rio muda a leitura do pre\u00e7o do Bitcoin de breakdown para um poss\u00edvel comeback.<\/p><h2 class=\"wp-block-heading\">Fed impulsiona Bitcoin hoje<\/h2><span class=\"replacer\"><\/span><p class=\"wp-block-paragraph\">O <a href=\"https:\/\/cryptonews.com\/br\/noticias\/trump-pressiona-powell-por-corte-maior-nos-juros\/\" target=\"_blank\" rel=\"noreferrer noopener\">chair do Federal Reserve, Jerome Powell<\/a>, deve seguir com mais um corte de um quarto de ponto esta semana. Dessa forma, ele mant\u00e9m essa dire\u00e7\u00e3o mesmo com alguns formuladores de pol\u00edtica monet\u00e1ria demonstrando preocupa\u00e7\u00e3o com a infla\u00e7\u00e3o persistente.<\/p><p class=\"wp-block-paragraph\">O Fed realizou o segundo corte consecutivo em outubro. A institui\u00e7\u00e3o reagiu \u00e0 fraqueza inesperada nos dados de emprego durante o ver\u00e3o.<\/p><div class=\"su-note\" style=\"border-color:#e0d5e5;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><div class=\"su-note-inner su-u-clearfix su-u-trim\" style=\"background-color:#faefff;border-color:#ffffff;color:#333333;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\">\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\"><strong>\ud83d\udc49Assim como o Zcash disparou e criou milion\u00e1rios, descubra a pr\u00f3xima <a href=\"https:\/\/cryptonews.com\/br\/criptomoedas\/criptomoeda-que-vai-explodir\/\" target=\"_blank\" rel=\"noreferrer noopener\">criptomoeda que pode explodir<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p><\/div><\/div><p class=\"wp-block-paragraph\">Depois disso, vozes hawkish surgiram entre as autoridades. No total, cinco membros com direito a voto sinalizaram resist\u00eancia a apoiar nova flexibiliza\u00e7\u00e3o em dezembro.<\/p><p class=\"wp-block-paragraph\">Mas, o cen\u00e1rio mudou no dia 21 de novembro. Na ocasi\u00e3o, John Williams, presidente do Fed de Nova York, afirmou que as condi\u00e7\u00f5es justificavam uma redu\u00e7\u00e3o \u2018no curto prazo\u2019.<\/p><h2 class=\"wp-block-heading\">Mercado cripto em recupera\u00e7\u00e3o<\/h2><span class=\"replacer\"><\/span><p class=\"wp-block-paragraph\">A an\u00e1lise recente do Cryptonews destaca uma <a href=\"https:\/\/cryptonews.com\/br\/noticias\/indicador-btc-ciclo-de-alta\/\" target=\"_blank\" rel=\"noreferrer noopener\">m\u00e9trica on-chain cr\u00edtica em acelera\u00e7\u00e3o<\/a>.<\/p><p class=\"wp-block-paragraph\">A \u2018liveliness\u2019 do Bitcoin sobe novamente. Esse movimento costuma aparecer em fases de bull market e sugere que o ciclo atual pode ter mais espa\u00e7o para alta.<\/p><p class=\"wp-block-paragraph\">O analista Micha\u00ebl van de Poppe apresentou um cen\u00e1rio bullish. Ele prev\u00ea volatilidade de curto prazo antes de uma alta sustentada.<\/p><p class=\"wp-block-paragraph\">Ele espera press\u00e3o vendedora pr\u00e9-FOMC hoje e na segunda-feira (08\/12). Sendo assim, esse movimento pode levar o pre\u00e7o at\u00e9 a regi\u00e3o de US$ 87 mil para buscar liquidez nos fundos.<\/p><figure class=\"wp-block-embed is-type-rich is-provider-twitter wp-block-embed-twitter\"><div class=\"wp-block-embed__wrapper\">\n<blockquote class=\"twitter-tweet\" data-width=\"550\" data-dnt=\"true\"><p lang=\"en\" dir=\"ltr\">This would be my bullish scenario.<br><br>Pre-FOMC and on Monday, correction to sweep the lows. Perhaps hitting $87K.<br><br>After that, bounce back up, swiftly, in which the uptrend is confirmed for <a href=\"https:\/\/twitter.com\/hashtag\/Bitcoin?src=hash&amp;ref_src=twsrc%5Etfw\">#Bitcoin<\/a> and it&#39;s ready to break $92K and therefore the run towards $100K in the coming 1-2\u2026 <a href=\"https:\/\/t.co\/lQezKkQM5W\">pic.twitter.com\/lQezKkQM5W<\/a><\/p>&mdash; Micha\u00ebl van de Poppe (@CryptoMichNL) <a href=\"https:\/\/twitter.com\/CryptoMichNL\/status\/1997614564469506516?ref_src=twsrc%5Etfw\">December 7, 2025<\/a><\/blockquote><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script>\n<\/div><\/figure><p class=\"wp-block-paragraph\">\u2018Depois disso, o pre\u00e7o deve subir r\u00e1pido. O uptrend do Bitcoin se confirma e ele fica pronto para romper US$ 92 mil.<\/p><p class=\"wp-block-paragraph\">Com isso, o BTC pode correr para US$ 100 mil nas pr\u00f3ximas 1\u20132 semanas. O Fed est\u00e1 reduzindo QT, cortando juros e ampliando a oferta de dinheiro para acelerar o ciclo de neg\u00f3cios\u2019, afirmou van de Poppe.<\/p><h2 class=\"wp-block-heading\">An\u00e1lise de pre\u00e7o do Bitcoin<\/h2><span class=\"replacer\"><\/span><p class=\"wp-block-paragraph\">A an\u00e1lise t\u00e9cnica mostra o Bitcoin rompendo um canal vermelho descendente de longo prazo. Ou seja, esse movimento indica que a fase mais forte da tend\u00eancia de baixa provavelmente terminou.<\/p><p class=\"wp-block-paragraph\">O pre\u00e7o opera perto da regi\u00e3o de US$ 89 mil, logo abaixo de uma zona-chave de resist\u00eancia que virou suporte, marcada em laranja.<\/p><p class=\"wp-block-paragraph\">O BTC ainda precisa fechar de forma decisiva acima dessa regi\u00e3o. Caso contr\u00e1rio, vendedores podem criar press\u00e3o de curto prazo.<\/p><figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"540\" src=\"https:\/\/cimg.co\/p\/no_image.svg\" alt=\"\" class=\"wp-image-155974 lazyload\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" data-src=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/13\/2025\/12\/08032140\/image-8-1024x540.png\" data-srcset=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/13\/2025\/12\/08032140\/image-8-1024x540.png 1024w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/13\/2025\/12\/08032140\/image-8-300x158.png 300w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/13\/2025\/12\/08032140\/image-8-768x405.png 768w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/13\/2025\/12\/08032140\/image-8-450x237.png 450w, https:\/\/cimg.co\/wp-content\/uploads\/sites\/13\/2025\/12\/08032140\/image-8.png 1536w\"><figcaption class=\"wp-element-caption\">An\u00e1lise de pre\u00e7o do Bitcoin (Fonte: TradingView)<\/figcaption><\/figure><p class=\"wp-block-paragraph\">O breakout j\u00e1 mostra for\u00e7a inicial. O BTC saltou da parte inferior do canal, perto de US$ 79 mil, e voltou para a regi\u00e3o intermedi\u00e1ria.<\/p><p class=\"wp-block-paragraph\">A pr\u00f3xima grande resist\u00eancia fica em US$ 94,6 mil. Se o Bitcoin romper esse n\u00edvel, o movimento confirma continua\u00e7\u00e3o bullish.<\/p><p class=\"wp-block-paragraph\">Se isso ocorrer, o gr\u00e1fico projeta alvos de alta em US$ 108 mil e, depois, US$ 116 mil, alinhados a zonas anteriores de liquidez.<\/p><div class=\"su-note\" style=\"border-color:#e0d5e5;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\"><div class=\"su-note-inner su-u-clearfix su-u-trim\" style=\"background-color:#faefff;border-color:#ffffff;color:#333333;border-radius:3px;-moz-border-radius:3px;-webkit-border-radius:3px;\">\n\n\n\n<p class=\"has-text-align-left wp-block-paragraph\"><strong>\ud83d\udcdaNeste guia, apresentamos as melhores oportunidades de <a href=\"https:\/\/cryptonews.com\/br\/criptomoedas\/pre-lancamento-criptomoedas\/\" target=\"_blank\" rel=\"noreferrer noopener\">pr\u00e9-lan\u00e7amento de criptomoedas<\/a>, segundo nossos especialistas.<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p><\/div><\/div>","protected":false},"excerpt":{"rendered":"<p>O Polymarket atribui 92% de probabilidade para um corte de 25 pontos-base pelo Fed na pr\u00f3xima semana. Isso muda a an\u00e1lise do pre\u00e7o do Bitcoin (BTC) de um rompimento bearish para um poss\u00edvel retorno, j\u00e1 que indicadores t\u00e9cnicos mostram impulso de breakout.O FOMC se re\u00fane na pr\u00f3xima ter\u00e7a-feira (9\/12). Assim, o mercado aposta quase de [&hellip;]<\/p>\n","protected":false},"author":610,"featured_media":155975,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[6],"tags":[103,86,95,93],"editores":[1187],"sponsored_companies":[],"class_list":["post-155972","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-bitcoin-news","tag-bitcoin","tag-btc","tag-criptomoedas","tag-mercado","editores-pedro-augusto"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Bitcoin hoje: corte de juros pelo Fed impulsiona retomada do BTC - CryptoNews Brasil<\/title>\n<meta name=\"description\" content=\"O pre\u00e7o do Bitcoin (BTC) d\u00e1 sinais de recupera\u00e7\u00e3o hoje (08\/12), ap\u00f3s impulsionamento relacionado ao corte de juros nos EUA.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/cryptonews.com\/br\/noticias\/bitcoin-hoje-corte-juros-fed\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bitcoin hoje: corte de juros pelo Fed impulsiona retomada do BTC - CryptoNews Brasil\" \/>\n<meta property=\"og:description\" content=\"O pre\u00e7o do Bitcoin (BTC) d\u00e1 sinais de recupera\u00e7\u00e3o hoje (08\/12), ap\u00f3s impulsionamento relacionado ao corte de juros nos EUA.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/cryptonews.com\/br\/noticias\/bitcoin-hoje-corte-juros-fed\/\" \/>\n<meta property=\"og:site_name\" content=\"CryptoNews Brasil\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-07T20:44:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-08T03:26:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/13\/2025\/12\/08032203\/image-9.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"673\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Bitcoin hoje: corte de juros pelo Fed impulsiona retomada do BTC - CryptoNews Brasil\" \/>\n<meta name=\"twitter:description\" content=\"O pre\u00e7o do Bitcoin (BTC) d\u00e1 sinais de recupera\u00e7\u00e3o hoje (08\/12), ap\u00f3s impulsionamento relacionado ao corte de juros nos EUA.\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/cimg.co\/wp-content\/uploads\/sites\/13\/2025\/12\/08032203\/image-9.jpg\" \/>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Bitcoin hoje: corte de juros pelo Fed impulsiona retomada do BTC - CryptoNews Brasil","description":"O pre\u00e7o do Bitcoin (BTC) d\u00e1 sinais de recupera\u00e7\u00e3o hoje (08\/12), ap\u00f3s impulsionamento relacionado ao corte de juros nos EUA.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/cryptonews.com\/br\/noticias\/bitcoin-hoje-corte-juros-fed\/","og_locale":"pt_BR","og_type":"article","og_title":"Bitcoin hoje: corte de juros pelo Fed impulsiona retomada do BTC - CryptoNews Brasil","og_description":"O pre\u00e7o do Bitcoin (BTC) d\u00e1 sinais de recupera\u00e7\u00e3o hoje (08\/12), ap\u00f3s impulsionamento relacionado ao corte de juros nos EUA.","og_url":"https:\/\/cryptonews.com\/br\/noticias\/bitcoin-hoje-corte-juros-fed\/","og_site_name":"CryptoNews Brasil","article_published_time":"2025-12-07T20:44:00+00:00","article_modified_time":"2025-12-08T03:26:06+00:00","og_image":[{"width":1200,"height":673,"url":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/13\/2025\/12\/08032203\/image-9.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_title":"Bitcoin hoje: corte de juros pelo Fed impulsiona retomada do BTC - CryptoNews Brasil","twitter_description":"O pre\u00e7o do Bitcoin (BTC) d\u00e1 sinais de recupera\u00e7\u00e3o hoje (08\/12), ap\u00f3s impulsionamento relacionado ao corte de juros nos EUA.","twitter_image":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/13\/2025\/12\/08032203\/image-9.jpg","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/cryptonews.com\/br\/noticias\/bitcoin-hoje-corte-juros-fed\/#article","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/bitcoin-hoje-corte-juros-fed\/"},"author":{"name":"pooljornalista","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/person\/d9b16ccb1579469d6c329976846138d2"},"headline":"Bitcoin hoje: corte de juros pelo Fed impulsiona retomada do BTC","datePublished":"2025-12-07T20:44:00+00:00","dateModified":"2025-12-08T03:26:06+00:00","mainEntityOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/bitcoin-hoje-corte-juros-fed\/"},"wordCount":622,"publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/bitcoin-hoje-corte-juros-fed\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/13\/2025\/12\/08032203\/image-9.jpg","keywords":["Bitcoin","Btc","Criptomoedas","Mercado"],"articleSection":["Not\u00edcias de Bitcoin"],"inLanguage":"pt-BR","copyrightYear":"2025","copyrightHolder":{"@id":"https:\/\/cryptonews.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/cryptonews.com\/br\/noticias\/bitcoin-hoje-corte-juros-fed\/","url":"https:\/\/cryptonews.com\/br\/noticias\/bitcoin-hoje-corte-juros-fed\/","name":"Bitcoin hoje: corte de juros pelo Fed impulsiona retomada do BTC - CryptoNews Brasil","isPartOf":{"@id":"https:\/\/cryptonews.com\/br\/#website"},"primaryImageOfPage":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/bitcoin-hoje-corte-juros-fed\/#primaryimage"},"image":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/bitcoin-hoje-corte-juros-fed\/#primaryimage"},"thumbnailUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/13\/2025\/12\/08032203\/image-9.jpg","datePublished":"2025-12-07T20:44:00+00:00","dateModified":"2025-12-08T03:26:06+00:00","description":"O pre\u00e7o do Bitcoin (BTC) d\u00e1 sinais de recupera\u00e7\u00e3o hoje (08\/12), ap\u00f3s impulsionamento relacionado ao corte de juros nos EUA.","breadcrumb":{"@id":"https:\/\/cryptonews.com\/br\/noticias\/bitcoin-hoje-corte-juros-fed\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/cryptonews.com\/br\/noticias\/bitcoin-hoje-corte-juros-fed\/"]}],"author":[]},{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/noticias\/bitcoin-hoje-corte-juros-fed\/#primaryimage","url":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/13\/2025\/12\/08032203\/image-9.jpg","contentUrl":"https:\/\/cimg.co\/wp-content\/uploads\/sites\/13\/2025\/12\/08032203\/image-9.jpg","width":1200,"height":673,"caption":"Ativo pode voltar a subir"},{"@type":"BreadcrumbList","@id":"https:\/\/cryptonews.com\/br\/noticias\/bitcoin-hoje-corte-juros-fed\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/cryptonews.com\/br\/"},{"@type":"ListItem","position":2,"name":"Bitcoin hoje: corte de juros pelo Fed impulsiona retomada do BTC"}]},{"@type":"WebSite","@id":"https:\/\/cryptonews.com\/br\/#website","url":"https:\/\/cryptonews.com\/br\/","name":"Cryptonews Portugal","description":"","publisher":{"@id":"https:\/\/cryptonews.com\/br\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/cryptonews.com\/br\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/cryptonews.com\/br\/#organization","name":"Cryptonews Portugal","url":"https:\/\/cryptonews.com\/br\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/","url":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","contentUrl":"https:\/\/cryptonews.com\/wp-content\/uploads\/sites\/13\/2023\/09\/4.jpg","width":1669,"height":874,"caption":"Cryptonews Portugal"},"image":{"@id":"https:\/\/cryptonews.com\/br\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/155972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/users\/610"}],"replies":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/comments?post=155972"}],"version-history":[{"count":3,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/155972\/revisions"}],"predecessor-version":[{"id":155981,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/posts\/155972\/revisions\/155981"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/media\/155975"}],"wp:attachment":[{"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/media?parent=155972"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/categories?post=155972"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/tags?post=155972"},{"taxonomy":"editores","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/editores?post=155972"},{"taxonomy":"sponsored_companies","embeddable":true,"href":"https:\/\/cryptonews.com\/br\/wp-json\/wp\/v2\/sponsored_companies?post=155972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}